{"id":977,"date":"2014-09-03T16:08:14","date_gmt":"2014-09-03T16:08:14","guid":{"rendered":"http:\/\/www.emco.mil.cl\/?p=977"},"modified":"2021-09-29T11:55:44","modified_gmt":"2021-09-29T14:55:44","slug":"comandante-operacional-de-las-ff-aa-argentinas-sostiene-encuentro-con-ministro-de-defensa-nacional-y-jefe-del-estado-mayor-conjunto","status":"publish","type":"post","link":"https:\/\/www.emco.mil.cl\/index.php\/2014\/09\/03\/comandante-operacional-de-las-ff-aa-argentinas-sostiene-encuentro-con-ministro-de-defensa-nacional-y-jefe-del-estado-mayor-conjunto\/","title":{"rendered":"Comandante Operacional de las FF.AA. argentinas sostiene encuentro con Ministro de Defensa Nacional y Jefe del Estado Mayor Conjunto"},"content":{"rendered":"<p>En el marco de la \u201cReuni\u00f3n de Estados Mayores Conjuntos de la Fuerza de Paz Conjunta-Combinada \u201cCruz del Sur\u201d Chile-Argentina\u201d, el Comandante Operacional de las Fuerzas Armadas trasandinas, General de Divisi\u00f3n \u201cVGM\u201d Ricardo Luis Cundom, se reuni\u00f3 el d\u00eda de hoy con el Ministro de Defensa Nacional Jorge Burgos y el Jefe del Estado Mayor Conjunto, Vicealmirante Jos\u00e9 Miguel Romero.<\/p>\n<p>El General Cundom es el encargado de dirigir y coordinar las actividades operacionales que realicen las Fuerzas Armadas argentinas en tiempo de paz, proponer y desarrollar el planeamiento operacional, conducir las operaciones militares en situaci\u00f3n de crisis y conflicto y las responsabilidades del Estado Mayor Conjunto de las Fuerzas Armadas con respecto al planeamiento militar conjunto.<\/p>\n<p>Durante su permanencia en el pa\u00eds, entre otros temas, Cundom se interiorizar\u00e1 respecto del sistema de gesti\u00f3n y entrenamiento dise\u00f1ado para la toma de decisiones de las autoridades responsables del manejo de emergencias naturales.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En el marco de la \u201cReuni\u00f3n de Estados Mayores Conjuntos de la Fuerza de Paz Conjunta-Combinada \u201cCruz del Sur\u201d Chile-Argentina\u201d, el Comandante Operacional de las Fuerzas Armadas trasandinas, General de Divisi\u00f3n \u201cVGM\u201d Ricardo Luis Cundom, se reuni\u00f3 el d\u00eda de hoy con el Ministro de Defensa Nacional Jorge Burgos y el Jefe del Estado Mayor&#8230;<\/p>\n","protected":false},"author":6,"featured_media":5823,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"footnotes":""},"categories":[26,3],"tags":[],"class_list":["post-977","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-26","category-noticias"],"_links":{"self":[{"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/posts\/977","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/comments?post=977"}],"version-history":[{"count":2,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/posts\/977\/revisions"}],"predecessor-version":[{"id":7045,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/posts\/977\/revisions\/7045"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/media\/5823"}],"wp:attachment":[{"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/media?parent=977"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/categories?post=977"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/tags?post=977"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}