{"id":9590,"date":"2022-11-11T12:56:15","date_gmt":"2022-11-11T15:56:15","guid":{"rendered":"https:\/\/www.emco.mil.cl\/?p=9590"},"modified":"2022-11-16T15:25:33","modified_gmt":"2022-11-16T18:25:33","slug":"ceremonia-de-clausura-del-ejercicio-conjunto-combinado-solidaridad-2022","status":"publish","type":"post","link":"https:\/\/www.emco.mil.cl\/index.php\/2022\/11\/11\/ceremonia-de-clausura-del-ejercicio-conjunto-combinado-solidaridad-2022\/","title":{"rendered":"Ceremonia de clausura del Ejercicio conjunto-combinado Solidaridad 2022"},"content":{"rendered":"\n<p>Este jueves 10 de noviembre se efectu\u00f3 en el audit\u00f3rium de la Universidad de Mendoza la ceremonia de clausura del Ejercicio Conjunto Combinado Solidaridad 2022, actividad que fue presidida por la embajadora de Chile en Argentina B\u00e1rbara Figueroa.<\/p>\n\n\n\n<p>De acuerdo al programa de la actividad, inici\u00f3 su presentaci\u00f3n el Teniente Coronel, Pablo Molina perteneciente a la Direcci\u00f3n del Ejercicio que efectu\u00f3 una exposici\u00f3n acerca de los aspectos positivos y las \u00e1reas a mejorar de este evento, donde resalt\u00f3 que este tipo de actividades van en beneficio de la comunidad, por ello, es relevante prepararse y entrenar en conjunto con las Fuerzas Armadas de Chile.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img fetchpriority=\"high\" decoding=\"async\" width=\"878\" height=\"300\" src=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/11\/clausura-interna1.jpg\" alt=\"\" class=\"wp-image-9591\" srcset=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/11\/clausura-interna1.jpg 878w, https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/11\/clausura-interna1-300x103.jpg 300w, https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/11\/clausura-interna1-768x262.jpg 768w, https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/11\/clausura-interna1-350x120.jpg 350w\" sizes=\"(max-width: 878px) 100vw, 878px\" \/><\/figure>\n<\/div>\n\n\n<p>Luego se efectu\u00f3 la entrega de certificados al personal de las Fuerzas Armadas de Chile que desarroll\u00f3 distintas tareas en el marco del Ejercicio Solidaridad 2022, recibiendo un reconocimiento el Comandante de la Componente A\u00e9rea, Coronel de Aviaci\u00f3n (A) Carlo Rosas.<\/p>\n\n\n\n<p>Para finalizar, el Director de Educaci\u00f3n y Doctrina y Entrenamiento Conjunto de la Delegaci\u00f3n de Chile, Comodoro Rodrigo Pe\u00f1aranda se\u00f1al\u00f3 que: \u201cLos desaf\u00edos que nos impone la naturaleza son m\u00faltiples y diversos, de alguna u otra forma ser similares nos impone esta necesidad de trabajar afortunadamente con mucha confianza para poder sobrellevarlo y poder atender a la ciudadan\u00eda que finalmente son a quienes nos debemos, en ese marco, y ya casi 25 a\u00f1os venimos trabajando en conjunto para poder establecer este Ejercicio Solidaridad que le da un marco a la Protecci\u00f3n Civil a la asistencia humanitaria y nos permite trabajar en forma conjunta con Fuerzas Armadas y combinada usando esas capacidades, pero tambi\u00e9n en forma interagencial con todas las agencias del Estado que est\u00e1n aqu\u00ed presentes, lo cual es una parte muy relevante. Esto nos hace hablar de una sociedad organizada ante cat\u00e1strofes que pudiesen ocurrir\u201d.<\/p>\n\n\n\n<p>Posteriormente, el Comandante de la VIII Brigada de Monta\u00f1a, Coronel Mayor Ricardo Horacio Doz concluy\u00f3: \u201cQuiero resaltar la importancia que reviste particularmente en esta regi\u00f3n las operaciones de protecci\u00f3n civil, resulta clara y evidente que el Estado est\u00e9 preparado para emplear una combinaci\u00f3n de diversos organismos en la soluci\u00f3n de las crisis y los trabajos consecuentes que producen ante la ocurrencia de un desastre natural, para lograr el \u00e9xito se convierte en imperativo que se perfeccionen la integraci\u00f3n y la cooperaci\u00f3n entre agencias, a nivel provincial y nacional, y en algunos casos como este que ejercitamos de acciones integradas con pa\u00edses hermanos. Quiero agradecer al Ej\u00e9rcito, Armada y Fuerza A\u00e9rea de la hermana Rep\u00fablica de Chile compartimos estos d\u00edas de trabajo e intercambiamos conocimientos y experiencias por lo que hemos dado un paso m\u00e1s en el proceso irreversible de integraci\u00f3n y profundizaci\u00f3n de los lazos de hermandad y camarader\u00eda que nos unen\u201d.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"878\" height=\"300\" src=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/11\/clausura-interna2.jpg\" alt=\"\" class=\"wp-image-9593\" srcset=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/11\/clausura-interna2.jpg 878w, https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/11\/clausura-interna2-300x103.jpg 300w, https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/11\/clausura-interna2-768x262.jpg 768w, https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/11\/clausura-interna2-350x120.jpg 350w\" sizes=\"(max-width: 878px) 100vw, 878px\" \/><\/figure>\n\n\n\n<p>A concluir la actividad, la embajadora de Chile en Argentina B\u00e1rbara Figueroa se\u00f1al\u00f3 \u201ces un gran orgullo para nuestro pa\u00eds todo el reconocimiento que existe respecto a nuestras Fuerza Armadas, era importante poder acompa\u00f1arlos en esta etapa de evaluaci\u00f3n, es importante poder conocer todos aquellos aspectos que se consideran reforzar y aquellos que son reconocidos en este \u00e1mbito y que fueron evaluados positivamente, este ejercicio ha sido un aprendizaje para nosotros\u201d.<\/p>\n\n\n\n<p>Durante la realizaci\u00f3n de este ejercicio la Fuerza A\u00e9rea de Chile particip\u00f3 de dos actividades de apoyo a la comunidad con la tripulaci\u00f3n de un helic\u00f3ptero MH-60M Black Hawk que traslad\u00f3 y efectu\u00f3 el ingreso de buzos t\u00e1cticos de la Armada de Chile a un dique para efectuar la b\u00fasqueda y rescate de personas en zona lacustre, como tambi\u00e9n esta tripulaci\u00f3n junto a Comandos de Aviaci\u00f3n del Grupo de Aviaci\u00f3n N\u00b0 9 efectuaron el rescate de una persona herida en una estructura colapsada en el sector de Luj\u00e1n de Cuyo, junto a personal de sanidad, encabezado por el Comandante de Grupo (S) Rodrigo Az\u00faa, que se desempe\u00f1a en la Divisi\u00f3n de Sanidad , se\u00f1al\u00f3 que \u201cdurante este ejercicio form\u00e9 parte de un team m\u00e9dico junto a un enfermero de combate, el Cabo 1\u00b0 Cristian Ortiz de la III\u00b0 Brigada A\u00e9rea. Participamos de la componente a\u00e9rea en el ejercicio de estructuras colapsadas, donde se simul\u00f3 la evacuaci\u00f3n de un herido, todo esto junto a personal sanitario de Mendoza. En espec\u00edfico se realiz\u00f3 un triage donde se efectu\u00f3 la selecci\u00f3n de un herido que estaba con lesiones graves y que necesitaba una atenci\u00f3n terciaria en alg\u00fan hospital de esta ciudad. Se seleccion\u00f3 a un paciente que estuviera habilitado para subir a la aeronave y que no presentara una condici\u00f3n de empeoramiento en el vuelo, y que adem\u00e1s tuviera la condici\u00f3n de gravedad. Posteriormente, se efectu\u00f3 la inmovilizaci\u00f3n del herido en una camilla para ser entregado a los Comandos de Aviaci\u00f3n, quienes lo subieron en un tecle a nuestro helic\u00f3ptero\u201d.<\/p>\n\n\n\n<p class=\"has-text-align-center\"><strong>Resumen Fotogr\u00e1fico del Ejercicio Solidaridad 2022<\/strong><\/p>\n\n\n<style>.wp-block-kadence-advancedgallery.kb-gallery-wrap-id-_75ef18-61{overflow:hidden;}.kb-gallery-type-carousel.kb-gallery-id-_75ef18-61 .kt-blocks-carousel .kt-blocks-carousel-init{margin:0 -5px;}.kb-gallery-type-carousel.kb-gallery-id-_75ef18-61 .kt-blocks-carousel .kt-blocks-carousel-init .kb-slide-item{padding:4px 5px;}.kb-gallery-type-carousel.kb-gallery-id-_75ef18-61 .kt-blocks-carousel .kt-blocks-carousel-init .slick-prev{left:5px;}.kb-gallery-type-carousel.kb-gallery-id-_75ef18-61 .kt-blocks-carousel .kt-blocks-carousel-init .slick-next{right:5px;}.kb-gallery-id-_75ef18-61 .kadence-blocks-gallery-item .kb-gal-image-radius, .kb-gallery-id-_75ef18-61 .kb-slide-item .kb-gal-image-radius img{border-radius:0px 0px 0px 0px;;}.kb-gallery-wrap-id-_75ef18-61.wp-block-kadence-advancedgallery{overflow:visible;}.kb-gallery-wrap-id-_75ef18-61.wp-block-kadence-advancedgallery .kt-blocks-carousel{overflow:visible;}<\/style>\n<div class=\"wp-block-kadence-advancedgallery kb-gallery-wrap-id-_75ef18-61\"><div class=\"kb-gallery-ul kb-gallery-type-carousel kb-gallery-id-_75ef18-61 kb-gallery-caption-style-bottom-hover kb-gallery-filter-none kb-gallery-magnific-init\" data-image-filter=\"none\" data-lightbox-caption=\"true\"><div class=\"kt-blocks-carousel kt-carousel-container-dotstyle-dark\"><div class=\"kt-blocks-carousel-init kb-gallery-carousel kt-carousel-arrowstyle-whiteondark kt-carousel-dotstyle-dark\" data-columns-xxl=\"2\" data-columns-xl=\"2\" data-columns-md=\"2\" data-columns-sm=\"2\" data-columns-xs=\"1\" data-columns-ss=\"1\" data-slider-anim-speed=\"400\" data-slider-scroll=\"1\" data-slider-arrows=\"true\" data-slider-dots=\"true\" data-slider-hover-pause=\"false\" data-slider-auto=\"true\" data-slider-speed=\"7000\"><div class=\"kb-slide-item kb-gallery-carousel-item\"><div class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kb-gallery-item-has-link kadence-blocks-gallery-item-hide-caption kb-has-image-ratio-land32\"><a href=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/11\/a3.jpg\" class=\"kb-gallery-item-link\"><div class=\"kb-gal-image-radius\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic kb-gallery-image-ratio-land32\"><img decoding=\"async\" src=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/11\/a3.jpg\" width=\"900\" height=\"675\" alt=\"\" data-full-image=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/11\/a3.jpg\" data-light-image=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/11\/a3.jpg\" data-id=\"9614\" data-link=\"https:\/\/www.emco.mil.cl\/index.php\/2022\/11\/11\/ceremonia-de-clausura-del-ejercicio-conjunto-combinado-solidaridad-2022\/a3\/\" class=\"wp-image-9614 skip-lazy\" srcset=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/11\/a3.jpg 900w, https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/11\/a3-300x225.jpg 300w, https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/11\/a3-768x576.jpg 768w, https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/11\/a3-350x263.jpg 350w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><\/div><\/div><\/a><\/figure><\/div><\/div><\/div><div class=\"kb-slide-item kb-gallery-carousel-item\"><div class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kb-gallery-item-has-link kadence-blocks-gallery-item-hide-caption kb-has-image-ratio-land32\"><a href=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/11\/a5.jpg\" class=\"kb-gallery-item-link\"><div class=\"kb-gal-image-radius\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic kb-gallery-image-ratio-land32\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/11\/a5.jpg\" width=\"900\" height=\"675\" alt=\"\" data-full-image=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/11\/a5.jpg\" data-light-image=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/11\/a5.jpg\" data-id=\"9615\" data-link=\"https:\/\/www.emco.mil.cl\/index.php\/2022\/11\/11\/ceremonia-de-clausura-del-ejercicio-conjunto-combinado-solidaridad-2022\/a5\/\" class=\"wp-image-9615 skip-lazy\" srcset=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/11\/a5.jpg 900w, https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/11\/a5-300x225.jpg 300w, https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/11\/a5-768x576.jpg 768w, https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/11\/a5-350x263.jpg 350w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><\/div><\/div><\/a><\/figure><\/div><\/div><\/div><div class=\"kb-slide-item kb-gallery-carousel-item\"><div class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kb-gallery-item-has-link kadence-blocks-gallery-item-hide-caption kb-has-image-ratio-land32\"><a href=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/11\/a6.jpg\" class=\"kb-gallery-item-link\"><div class=\"kb-gal-image-radius\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic kb-gallery-image-ratio-land32\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/11\/a6.jpg\" width=\"900\" height=\"675\" alt=\"\" data-full-image=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/11\/a6.jpg\" data-light-image=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/11\/a6.jpg\" data-id=\"9616\" data-link=\"https:\/\/www.emco.mil.cl\/index.php\/2022\/11\/11\/ceremonia-de-clausura-del-ejercicio-conjunto-combinado-solidaridad-2022\/a6\/\" class=\"wp-image-9616 skip-lazy\" srcset=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/11\/a6.jpg 900w, https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/11\/a6-300x225.jpg 300w, https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/11\/a6-768x576.jpg 768w, https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/11\/a6-350x263.jpg 350w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><\/div><\/div><\/a><\/figure><\/div><\/div><\/div><div class=\"kb-slide-item kb-gallery-carousel-item\"><div class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kb-gallery-item-has-link kadence-blocks-gallery-item-hide-caption kb-has-image-ratio-land32\"><a href=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/11\/b1.jpg\" class=\"kb-gallery-item-link\"><div class=\"kb-gal-image-radius\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic kb-gallery-image-ratio-land32\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/11\/b1.jpg\" width=\"900\" height=\"675\" alt=\"\" data-full-image=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/11\/b1.jpg\" data-light-image=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/11\/b1.jpg\" data-id=\"9617\" data-link=\"https:\/\/www.emco.mil.cl\/index.php\/2022\/11\/11\/ceremonia-de-clausura-del-ejercicio-conjunto-combinado-solidaridad-2022\/b1\/\" class=\"wp-image-9617 skip-lazy\" srcset=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/11\/b1.jpg 900w, https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/11\/b1-300x225.jpg 300w, https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/11\/b1-768x576.jpg 768w, https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/11\/b1-350x263.jpg 350w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><\/div><\/div><\/a><\/figure><\/div><\/div><\/div><div class=\"kb-slide-item kb-gallery-carousel-item\"><div class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kb-gallery-item-has-link kadence-blocks-gallery-item-hide-caption kb-has-image-ratio-land32\"><a href=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/11\/b2.jpg\" class=\"kb-gallery-item-link\"><div class=\"kb-gal-image-radius\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic kb-gallery-image-ratio-land32\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/11\/b2.jpg\" width=\"900\" height=\"675\" alt=\"\" data-full-image=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/11\/b2.jpg\" data-light-image=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/11\/b2.jpg\" data-id=\"9618\" data-link=\"https:\/\/www.emco.mil.cl\/index.php\/2022\/11\/11\/ceremonia-de-clausura-del-ejercicio-conjunto-combinado-solidaridad-2022\/b2\/\" class=\"wp-image-9618 skip-lazy\" srcset=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/11\/b2.jpg 900w, https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/11\/b2-300x225.jpg 300w, https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/11\/b2-768x576.jpg 768w, https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/11\/b2-350x263.jpg 350w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><\/div><\/div><\/a><\/figure><\/div><\/div><\/div><div class=\"kb-slide-item kb-gallery-carousel-item\"><div class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kb-gallery-item-has-link kadence-blocks-gallery-item-hide-caption kb-has-image-ratio-land32\"><a href=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/11\/b3.jpg\" class=\"kb-gallery-item-link\"><div class=\"kb-gal-image-radius\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic kb-gallery-image-ratio-land32\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/11\/b3.jpg\" width=\"900\" height=\"675\" alt=\"\" data-full-image=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/11\/b3.jpg\" data-light-image=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/11\/b3.jpg\" data-id=\"9619\" data-link=\"https:\/\/www.emco.mil.cl\/index.php\/2022\/11\/11\/ceremonia-de-clausura-del-ejercicio-conjunto-combinado-solidaridad-2022\/b3\/\" class=\"wp-image-9619 skip-lazy\" srcset=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/11\/b3.jpg 900w, https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/11\/b3-300x225.jpg 300w, https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/11\/b3-768x576.jpg 768w, https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/11\/b3-350x263.jpg 350w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><\/div><\/div><\/a><\/figure><\/div><\/div><\/div><div class=\"kb-slide-item kb-gallery-carousel-item\"><div class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kb-gallery-item-has-link kadence-blocks-gallery-item-hide-caption kb-has-image-ratio-land32\"><a href=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/11\/b4.jpg\" class=\"kb-gallery-item-link\"><div class=\"kb-gal-image-radius\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic kb-gallery-image-ratio-land32\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/11\/b4.jpg\" width=\"900\" height=\"675\" alt=\"\" data-full-image=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/11\/b4.jpg\" data-light-image=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/11\/b4.jpg\" data-id=\"9620\" data-link=\"https:\/\/www.emco.mil.cl\/index.php\/2022\/11\/11\/ceremonia-de-clausura-del-ejercicio-conjunto-combinado-solidaridad-2022\/b4\/\" class=\"wp-image-9620 skip-lazy\" srcset=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/11\/b4.jpg 900w, https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/11\/b4-300x225.jpg 300w, https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/11\/b4-768x576.jpg 768w, https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/11\/b4-350x263.jpg 350w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><\/div><\/div><\/a><\/figure><\/div><\/div><\/div><div class=\"kb-slide-item kb-gallery-carousel-item\"><div class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kb-gallery-item-has-link kadence-blocks-gallery-item-hide-caption kb-has-image-ratio-land32\"><a href=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/11\/b5.jpg\" class=\"kb-gallery-item-link\"><div class=\"kb-gal-image-radius\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic kb-gallery-image-ratio-land32\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/11\/b5.jpg\" width=\"900\" height=\"675\" alt=\"\" data-full-image=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/11\/b5.jpg\" data-light-image=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/11\/b5.jpg\" data-id=\"9621\" data-link=\"https:\/\/www.emco.mil.cl\/index.php\/2022\/11\/11\/ceremonia-de-clausura-del-ejercicio-conjunto-combinado-solidaridad-2022\/b5\/\" class=\"wp-image-9621 skip-lazy\" srcset=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/11\/b5.jpg 900w, https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/11\/b5-300x225.jpg 300w, https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/11\/b5-768x576.jpg 768w, https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/11\/b5-350x263.jpg 350w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><\/div><\/div><\/a><\/figure><\/div><\/div><\/div><div class=\"kb-slide-item kb-gallery-carousel-item\"><div class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kb-gallery-item-has-link kadence-blocks-gallery-item-hide-caption kb-has-image-ratio-land32\"><a href=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/11\/b6.jpg\" class=\"kb-gallery-item-link\"><div class=\"kb-gal-image-radius\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic kb-gallery-image-ratio-land32\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/11\/b6.jpg\" width=\"900\" height=\"675\" alt=\"\" data-full-image=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/11\/b6.jpg\" data-light-image=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/11\/b6.jpg\" data-id=\"9622\" data-link=\"https:\/\/www.emco.mil.cl\/index.php\/2022\/11\/11\/ceremonia-de-clausura-del-ejercicio-conjunto-combinado-solidaridad-2022\/b6\/\" class=\"wp-image-9622 skip-lazy\" srcset=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/11\/b6.jpg 900w, https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/11\/b6-300x225.jpg 300w, https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/11\/b6-768x576.jpg 768w, https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/11\/b6-350x263.jpg 350w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><\/div><\/div><\/a><\/figure><\/div><\/div><\/div><div class=\"kb-slide-item kb-gallery-carousel-item\"><div class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kb-gallery-item-has-link kadence-blocks-gallery-item-hide-caption kb-has-image-ratio-land32\"><a href=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/11\/b7.jpg\" class=\"kb-gallery-item-link\"><div class=\"kb-gal-image-radius\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic kb-gallery-image-ratio-land32\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/11\/b7.jpg\" width=\"900\" height=\"675\" alt=\"\" data-full-image=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/11\/b7.jpg\" data-light-image=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/11\/b7.jpg\" data-id=\"9623\" data-link=\"https:\/\/www.emco.mil.cl\/index.php\/2022\/11\/11\/ceremonia-de-clausura-del-ejercicio-conjunto-combinado-solidaridad-2022\/b7\/\" class=\"wp-image-9623 skip-lazy\" srcset=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/11\/b7.jpg 900w, https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/11\/b7-300x225.jpg 300w, https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/11\/b7-768x576.jpg 768w, https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/11\/b7-350x263.jpg 350w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><\/div><\/div><\/a><\/figure><\/div><\/div><\/div><div class=\"kb-slide-item kb-gallery-carousel-item\"><div class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kb-gallery-item-has-link kadence-blocks-gallery-item-hide-caption kb-has-image-ratio-land32\"><a href=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/11\/b8.jpg\" class=\"kb-gallery-item-link\"><div class=\"kb-gal-image-radius\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic kb-gallery-image-ratio-land32\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/11\/b8.jpg\" width=\"900\" height=\"675\" alt=\"\" data-full-image=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/11\/b8.jpg\" data-light-image=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/11\/b8.jpg\" data-id=\"9624\" data-link=\"https:\/\/www.emco.mil.cl\/index.php\/2022\/11\/11\/ceremonia-de-clausura-del-ejercicio-conjunto-combinado-solidaridad-2022\/b8\/\" class=\"wp-image-9624 skip-lazy\" srcset=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/11\/b8.jpg 900w, https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/11\/b8-300x225.jpg 300w, https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/11\/b8-768x576.jpg 768w, https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/11\/b8-350x263.jpg 350w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><\/div><\/div><\/a><\/figure><\/div><\/div><\/div><div class=\"kb-slide-item kb-gallery-carousel-item\"><div class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kb-gallery-item-has-link kadence-blocks-gallery-item-hide-caption kb-has-image-ratio-land32\"><a href=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/11\/b9.jpg\" class=\"kb-gallery-item-link\"><div class=\"kb-gal-image-radius\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic kb-gallery-image-ratio-land32\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/11\/b9.jpg\" width=\"900\" height=\"675\" alt=\"\" data-full-image=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/11\/b9.jpg\" data-light-image=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/11\/b9.jpg\" data-id=\"9625\" data-link=\"https:\/\/www.emco.mil.cl\/index.php\/2022\/11\/11\/ceremonia-de-clausura-del-ejercicio-conjunto-combinado-solidaridad-2022\/b9\/\" class=\"wp-image-9625 skip-lazy\" srcset=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/11\/b9.jpg 900w, https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/11\/b9-300x225.jpg 300w, https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/11\/b9-768x576.jpg 768w, https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/11\/b9-350x263.jpg 350w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><\/div><\/div><\/a><\/figure><\/div><\/div><\/div><div class=\"kb-slide-item kb-gallery-carousel-item\"><div class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kb-gallery-item-has-link kadence-blocks-gallery-item-hide-caption kb-has-image-ratio-land32\"><a href=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/11\/b10.jpg\" class=\"kb-gallery-item-link\"><div class=\"kb-gal-image-radius\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic kb-gallery-image-ratio-land32\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/11\/b10.jpg\" width=\"900\" height=\"675\" alt=\"\" data-full-image=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/11\/b10.jpg\" data-light-image=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/11\/b10.jpg\" data-id=\"9626\" data-link=\"https:\/\/www.emco.mil.cl\/index.php\/2022\/11\/11\/ceremonia-de-clausura-del-ejercicio-conjunto-combinado-solidaridad-2022\/b10\/\" class=\"wp-image-9626 skip-lazy\" srcset=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/11\/b10.jpg 900w, https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/11\/b10-300x225.jpg 300w, https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/11\/b10-768x576.jpg 768w, https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/11\/b10-350x263.jpg 350w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><\/div><\/div><\/a><\/figure><\/div><\/div><\/div><div class=\"kb-slide-item kb-gallery-carousel-item\"><div class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kb-gallery-item-has-link kadence-blocks-gallery-item-hide-caption kb-has-image-ratio-land32\"><a href=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/11\/b11.jpg\" class=\"kb-gallery-item-link\"><div class=\"kb-gal-image-radius\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic kb-gallery-image-ratio-land32\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/11\/b11.jpg\" width=\"900\" height=\"675\" alt=\"\" data-full-image=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/11\/b11.jpg\" data-light-image=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/11\/b11.jpg\" data-id=\"9627\" data-link=\"https:\/\/www.emco.mil.cl\/index.php\/2022\/11\/11\/ceremonia-de-clausura-del-ejercicio-conjunto-combinado-solidaridad-2022\/b11\/\" class=\"wp-image-9627 skip-lazy\" srcset=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/11\/b11.jpg 900w, https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/11\/b11-300x225.jpg 300w, https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/11\/b11-768x576.jpg 768w, https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/11\/b11-350x263.jpg 350w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><\/div><\/div><\/a><\/figure><\/div><\/div><\/div><div class=\"kb-slide-item kb-gallery-carousel-item\"><div class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kb-gallery-item-has-link kadence-blocks-gallery-item-hide-caption kb-has-image-ratio-land32\"><a href=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/11\/c1.jpg\" class=\"kb-gallery-item-link\"><div class=\"kb-gal-image-radius\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic kb-gallery-image-ratio-land32\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/11\/c1.jpg\" width=\"900\" height=\"506\" alt=\"\" data-full-image=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/11\/c1.jpg\" data-light-image=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/11\/c1.jpg\" data-id=\"9628\" data-link=\"https:\/\/www.emco.mil.cl\/index.php\/2022\/11\/11\/ceremonia-de-clausura-del-ejercicio-conjunto-combinado-solidaridad-2022\/c1\/\" class=\"wp-image-9628 skip-lazy\" srcset=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/11\/c1.jpg 900w, https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/11\/c1-300x169.jpg 300w, https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/11\/c1-768x432.jpg 768w, https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/11\/c1-350x197.jpg 350w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><\/div><\/div><\/a><\/figure><\/div><\/div><\/div><div class=\"kb-slide-item kb-gallery-carousel-item\"><div class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kb-gallery-item-has-link kadence-blocks-gallery-item-hide-caption kb-has-image-ratio-land32\"><a href=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/11\/c2.jpg\" class=\"kb-gallery-item-link\"><div class=\"kb-gal-image-radius\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic kb-gallery-image-ratio-land32\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/11\/c2.jpg\" width=\"900\" height=\"596\" alt=\"\" data-full-image=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/11\/c2.jpg\" data-light-image=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/11\/c2.jpg\" data-id=\"9629\" data-link=\"https:\/\/www.emco.mil.cl\/index.php\/2022\/11\/11\/ceremonia-de-clausura-del-ejercicio-conjunto-combinado-solidaridad-2022\/c2\/\" class=\"wp-image-9629 skip-lazy\" srcset=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/11\/c2.jpg 900w, https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/11\/c2-300x199.jpg 300w, https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/11\/c2-768x509.jpg 768w, https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/11\/c2-350x232.jpg 350w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><\/div><\/div><\/a><\/figure><\/div><\/div><\/div><div class=\"kb-slide-item kb-gallery-carousel-item\"><div class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kb-gallery-item-has-link kadence-blocks-gallery-item-hide-caption kb-has-image-ratio-land32\"><a href=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/11\/c3.jpg\" class=\"kb-gallery-item-link\"><div class=\"kb-gal-image-radius\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic kb-gallery-image-ratio-land32\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/11\/c3.jpg\" width=\"900\" height=\"675\" alt=\"\" data-full-image=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/11\/c3.jpg\" data-light-image=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/11\/c3.jpg\" data-id=\"9630\" data-link=\"https:\/\/www.emco.mil.cl\/index.php\/2022\/11\/11\/ceremonia-de-clausura-del-ejercicio-conjunto-combinado-solidaridad-2022\/c3\/\" class=\"wp-image-9630 skip-lazy\" srcset=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/11\/c3.jpg 900w, https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/11\/c3-300x225.jpg 300w, https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/11\/c3-768x576.jpg 768w, https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/11\/c3-350x263.jpg 350w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><\/div><\/div><\/a><\/figure><\/div><\/div><\/div><div class=\"kb-slide-item kb-gallery-carousel-item\"><div class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kb-gallery-item-has-link kadence-blocks-gallery-item-hide-caption kb-has-image-ratio-land32\"><a href=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/11\/c5.jpg\" class=\"kb-gallery-item-link\"><div class=\"kb-gal-image-radius\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic kb-gallery-image-ratio-land32\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/11\/c5.jpg\" width=\"900\" height=\"675\" alt=\"\" data-full-image=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/11\/c5.jpg\" data-light-image=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/11\/c5.jpg\" data-id=\"9631\" data-link=\"https:\/\/www.emco.mil.cl\/index.php\/2022\/11\/11\/ceremonia-de-clausura-del-ejercicio-conjunto-combinado-solidaridad-2022\/c5\/\" class=\"wp-image-9631 skip-lazy\" srcset=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/11\/c5.jpg 900w, https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/11\/c5-300x225.jpg 300w, https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/11\/c5-768x576.jpg 768w, https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/11\/c5-350x263.jpg 350w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><\/div><\/div><\/a><\/figure><\/div><\/div><\/div><div class=\"kb-slide-item kb-gallery-carousel-item\"><div class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kb-gallery-item-has-link kadence-blocks-gallery-item-hide-caption kb-has-image-ratio-land32\"><a href=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/11\/c7.jpg\" class=\"kb-gallery-item-link\"><div class=\"kb-gal-image-radius\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic kb-gallery-image-ratio-land32\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/11\/c7.jpg\" width=\"900\" height=\"675\" alt=\"\" data-full-image=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/11\/c7.jpg\" data-light-image=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/11\/c7.jpg\" data-id=\"9632\" data-link=\"https:\/\/www.emco.mil.cl\/index.php\/2022\/11\/11\/ceremonia-de-clausura-del-ejercicio-conjunto-combinado-solidaridad-2022\/c7\/\" class=\"wp-image-9632 skip-lazy\" srcset=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/11\/c7.jpg 900w, https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/11\/c7-300x225.jpg 300w, https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/11\/c7-768x576.jpg 768w, https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/11\/c7-350x263.jpg 350w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><\/div><\/div><\/a><\/figure><\/div><\/div><\/div><div class=\"kb-slide-item kb-gallery-carousel-item\"><div class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kb-gallery-item-has-link kadence-blocks-gallery-item-hide-caption kb-has-image-ratio-land32\"><a href=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/11\/d1.jpg\" class=\"kb-gallery-item-link\"><div class=\"kb-gal-image-radius\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic kb-gallery-image-ratio-land32\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/11\/d1.jpg\" width=\"900\" height=\"675\" alt=\"\" data-full-image=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/11\/d1.jpg\" data-light-image=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/11\/d1.jpg\" data-id=\"9633\" data-link=\"https:\/\/www.emco.mil.cl\/index.php\/2022\/11\/11\/ceremonia-de-clausura-del-ejercicio-conjunto-combinado-solidaridad-2022\/d1\/\" class=\"wp-image-9633 skip-lazy\" srcset=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/11\/d1.jpg 900w, https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/11\/d1-300x225.jpg 300w, https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/11\/d1-768x576.jpg 768w, https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/11\/d1-350x263.jpg 350w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><\/div><\/div><\/a><\/figure><\/div><\/div><\/div><div class=\"kb-slide-item kb-gallery-carousel-item\"><div class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kb-gallery-item-has-link kadence-blocks-gallery-item-hide-caption kb-has-image-ratio-land32\"><a href=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/11\/d2.jpg\" class=\"kb-gallery-item-link\"><div class=\"kb-gal-image-radius\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic kb-gallery-image-ratio-land32\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/11\/d2.jpg\" width=\"900\" height=\"675\" alt=\"\" data-full-image=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/11\/d2.jpg\" data-light-image=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/11\/d2.jpg\" data-id=\"9634\" data-link=\"https:\/\/www.emco.mil.cl\/index.php\/2022\/11\/11\/ceremonia-de-clausura-del-ejercicio-conjunto-combinado-solidaridad-2022\/d2\/\" class=\"wp-image-9634 skip-lazy\" srcset=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/11\/d2.jpg 900w, https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/11\/d2-300x225.jpg 300w, https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/11\/d2-768x576.jpg 768w, https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/11\/d2-350x263.jpg 350w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><\/div><\/div><\/a><\/figure><\/div><\/div><\/div><div class=\"kb-slide-item kb-gallery-carousel-item\"><div class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kb-gallery-item-has-link kadence-blocks-gallery-item-hide-caption kb-has-image-ratio-land32\"><a href=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/11\/d4.jpg\" class=\"kb-gallery-item-link\"><div class=\"kb-gal-image-radius\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic kb-gallery-image-ratio-land32\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/11\/d4.jpg\" width=\"900\" height=\"675\" alt=\"\" data-full-image=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/11\/d4.jpg\" data-light-image=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/11\/d4.jpg\" data-id=\"9635\" data-link=\"https:\/\/www.emco.mil.cl\/index.php\/2022\/11\/11\/ceremonia-de-clausura-del-ejercicio-conjunto-combinado-solidaridad-2022\/d4\/\" class=\"wp-image-9635 skip-lazy\" srcset=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/11\/d4.jpg 900w, https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/11\/d4-300x225.jpg 300w, https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/11\/d4-768x576.jpg 768w, https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/11\/d4-350x263.jpg 350w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><\/div><\/div><\/a><\/figure><\/div><\/div><\/div><div class=\"kb-slide-item kb-gallery-carousel-item\"><div class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kb-gallery-item-has-link kadence-blocks-gallery-item-hide-caption kb-has-image-ratio-land32\"><a href=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/11\/d5.jpg\" class=\"kb-gallery-item-link\"><div class=\"kb-gal-image-radius\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic kb-gallery-image-ratio-land32\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/11\/d5.jpg\" width=\"900\" height=\"675\" alt=\"\" data-full-image=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/11\/d5.jpg\" data-light-image=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/11\/d5.jpg\" data-id=\"9636\" data-link=\"https:\/\/www.emco.mil.cl\/index.php\/2022\/11\/11\/ceremonia-de-clausura-del-ejercicio-conjunto-combinado-solidaridad-2022\/d5\/\" class=\"wp-image-9636 skip-lazy\" srcset=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/11\/d5.jpg 900w, https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/11\/d5-300x225.jpg 300w, https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/11\/d5-768x576.jpg 768w, https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/11\/d5-350x263.jpg 350w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><\/div><\/div><\/a><\/figure><\/div><\/div><\/div><div class=\"kb-slide-item kb-gallery-carousel-item\"><div class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kb-gallery-item-has-link kadence-blocks-gallery-item-hide-caption kb-has-image-ratio-land32\"><a href=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/11\/d6.jpg\" class=\"kb-gallery-item-link\"><div class=\"kb-gal-image-radius\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic kb-gallery-image-ratio-land32\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/11\/d6.jpg\" width=\"900\" height=\"675\" alt=\"\" data-full-image=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/11\/d6.jpg\" data-light-image=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/11\/d6.jpg\" data-id=\"9637\" data-link=\"https:\/\/www.emco.mil.cl\/index.php\/2022\/11\/11\/ceremonia-de-clausura-del-ejercicio-conjunto-combinado-solidaridad-2022\/d6\/\" class=\"wp-image-9637 skip-lazy\" srcset=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/11\/d6.jpg 900w, https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/11\/d6-300x225.jpg 300w, https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/11\/d6-768x576.jpg 768w, https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/11\/d6-350x263.jpg 350w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><\/div><\/div><\/a><\/figure><\/div><\/div><\/div><div class=\"kb-slide-item kb-gallery-carousel-item\"><div class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kb-gallery-item-has-link kadence-blocks-gallery-item-hide-caption kb-has-image-ratio-land32\"><a href=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/11\/d7.jpg\" class=\"kb-gallery-item-link\"><div class=\"kb-gal-image-radius\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic kb-gallery-image-ratio-land32\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/11\/d7.jpg\" width=\"900\" height=\"675\" alt=\"\" data-full-image=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/11\/d7.jpg\" data-light-image=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/11\/d7.jpg\" data-id=\"9638\" data-link=\"https:\/\/www.emco.mil.cl\/index.php\/2022\/11\/11\/ceremonia-de-clausura-del-ejercicio-conjunto-combinado-solidaridad-2022\/d7\/\" class=\"wp-image-9638 skip-lazy\" srcset=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/11\/d7.jpg 900w, https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/11\/d7-300x225.jpg 300w, https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/11\/d7-768x576.jpg 768w, https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/11\/d7-350x263.jpg 350w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><\/div><\/div><\/a><\/figure><\/div><\/div><\/div><div class=\"kb-slide-item kb-gallery-carousel-item\"><div class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kb-gallery-item-has-link kadence-blocks-gallery-item-hide-caption kb-has-image-ratio-land32\"><a href=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/11\/d8.jpg\" class=\"kb-gallery-item-link\"><div class=\"kb-gal-image-radius\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic kb-gallery-image-ratio-land32\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/11\/d8.jpg\" width=\"900\" height=\"675\" alt=\"\" data-full-image=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/11\/d8.jpg\" data-light-image=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/11\/d8.jpg\" data-id=\"9639\" data-link=\"https:\/\/www.emco.mil.cl\/index.php\/2022\/11\/11\/ceremonia-de-clausura-del-ejercicio-conjunto-combinado-solidaridad-2022\/d8\/\" class=\"wp-image-9639 skip-lazy\" srcset=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/11\/d8.jpg 900w, https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/11\/d8-300x225.jpg 300w, https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/11\/d8-768x576.jpg 768w, https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/11\/d8-350x263.jpg 350w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><\/div><\/div><\/a><\/figure><\/div><\/div><\/div><div class=\"kb-slide-item kb-gallery-carousel-item\"><div class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kb-gallery-item-has-link kadence-blocks-gallery-item-hide-caption kb-has-image-ratio-land32\"><a href=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/11\/d10.jpg\" class=\"kb-gallery-item-link\"><div class=\"kb-gal-image-radius\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic kb-gallery-image-ratio-land32\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/11\/d10.jpg\" width=\"900\" height=\"675\" alt=\"\" data-full-image=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/11\/d10.jpg\" data-light-image=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/11\/d10.jpg\" data-id=\"9640\" data-link=\"https:\/\/www.emco.mil.cl\/index.php\/2022\/11\/11\/ceremonia-de-clausura-del-ejercicio-conjunto-combinado-solidaridad-2022\/d10\/\" class=\"wp-image-9640 skip-lazy\" srcset=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/11\/d10.jpg 900w, https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/11\/d10-300x225.jpg 300w, https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/11\/d10-768x576.jpg 768w, https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/11\/d10-350x263.jpg 350w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><\/div><\/div><\/a><\/figure><\/div><\/div><\/div><\/div><\/div><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Este jueves 10 de noviembre se efectu\u00f3 en el audit\u00f3rium de la Universidad de Mendoza la ceremonia de clausura del Ejercicio Conjunto Combinado Solidaridad 2022, actividad que fue presidida por la embajadora de Chile en Argentina B\u00e1rbara Figueroa. De acuerdo al programa de la actividad, inici\u00f3 su presentaci\u00f3n el Teniente Coronel, Pablo Molina perteneciente a&#8230;<\/p>\n","protected":false},"author":5,"featured_media":9594,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"footnotes":""},"categories":[30,3],"tags":[],"class_list":["post-9590","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-30","category-noticias"],"_links":{"self":[{"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/posts\/9590","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/comments?post=9590"}],"version-history":[{"count":2,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/posts\/9590\/revisions"}],"predecessor-version":[{"id":9641,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/posts\/9590\/revisions\/9641"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/media\/9594"}],"wp:attachment":[{"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/media?parent=9590"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/categories?post=9590"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/tags?post=9590"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}