{"id":9569,"date":"2022-11-04T18:59:00","date_gmt":"2022-11-04T21:59:00","guid":{"rendered":"https:\/\/www.emco.mil.cl\/?p=9569"},"modified":"2022-11-09T11:38:50","modified_gmt":"2022-11-09T14:38:50","slug":"curso-conjunto-de-estado-mayor-visita-areas-de-responsabilidad-del-comando-conjunto-austral-en-punta-arenas","status":"publish","type":"post","link":"https:\/\/www.emco.mil.cl\/index.php\/2022\/11\/04\/curso-conjunto-de-estado-mayor-visita-areas-de-responsabilidad-del-comando-conjunto-austral-en-punta-arenas\/","title":{"rendered":"Curso Conjunto de Estado Mayor visita \u00e1reas de responsabilidad del Comando Conjunto Austral en Punta Arenas"},"content":{"rendered":"\n<p>Este 4 de noviembre, y como parte de las actividades acad\u00e9micas del Curso Conjunto de Estado Mayor, oficiales alumnos realizaron una visita profesional a la ciudad de Punta Arenas donde, luego de ser recibidos por el Comandante del Comando Conjunto Austral, General de Brigada Sergio Est\u00e9vez Valencia y por su Jefe de Estado Mayor, Capit\u00e1n de Nav\u00edo IM Luis Sarnataro Lillo a bordo del buque de Transporte AP-41 Aquiles a su recalada en el muelle Capit\u00e1n Guillermos, el Director de Instituto Ant\u00e1rtico Chileno (INACH), Doctor Marcelo Leppe, efectu\u00f3 una exposici\u00f3n informativa orientada en los proyectos ant\u00e1rticos y sus repercusiones en el \u00e1mbito nacional e internacional, para despu\u00e9s realizar una visita profesional a las instalaciones de Astilleros y Maestranzas de la Armada Magallanes, que estuvo enfocada en las capacidades que prestan estos astilleros a la industria civil-militar naval.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img fetchpriority=\"high\" decoding=\"async\" width=\"878\" height=\"308\" src=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/11\/interna1-2.jpg\" alt=\"\" class=\"wp-image-9571\" srcset=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/11\/interna1-2.jpg 878w, https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/11\/interna1-2-300x105.jpg 300w, https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/11\/interna1-2-768x269.jpg 768w, https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/11\/interna1-2-350x123.jpg 350w\" sizes=\"(max-width: 878px) 100vw, 878px\" \/><\/figure>\n<\/div>\n\n\n<p>Con posterioridad asistieron a una exposici\u00f3n y muestra est\u00e1tica de la componente terrestre en instalaciones de la IV Brigada Acorazada \u201cChorrillos\u201d, finalizando con un almuerzo de camarader\u00eda en el casino de ese lugar.<\/p>\n\n\n\n<p>De tal manera, esta actividad se enmarc\u00f3 dentro de los prop\u00f3sitos del Curso Conjunto de Estado Mayor, que es enterar a sus alumnos de las capacidades conjuntas en el \u00e1rea de responsabilidad del Comando Conjunto Austral, adem\u00e1s de informarse acerca de los proyectos que conduce el INACH en el territorio ant\u00e1rtico chileno.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img decoding=\"async\" width=\"878\" height=\"308\" src=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/11\/interna2-1.jpg\" alt=\"\" class=\"wp-image-9572\" srcset=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/11\/interna2-1.jpg 878w, https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/11\/interna2-1-300x105.jpg 300w, https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/11\/interna2-1-768x269.jpg 768w, https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/11\/interna2-1-350x123.jpg 350w\" sizes=\"(max-width: 878px) 100vw, 878px\" \/><\/figure>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Este 4 de noviembre, y como parte de las actividades acad\u00e9micas del Curso Conjunto de Estado Mayor, oficiales alumnos realizaron una visita profesional a la ciudad de Punta Arenas donde, luego de ser recibidos por el Comandante del Comando Conjunto Austral, General de Brigada Sergio Est\u00e9vez Valencia y por su Jefe de Estado Mayor, Capit\u00e1n&#8230;<\/p>\n","protected":false},"author":5,"featured_media":9573,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"footnotes":""},"categories":[30],"tags":[],"class_list":["post-9569","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-30"],"_links":{"self":[{"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/posts\/9569","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/comments?post=9569"}],"version-history":[{"count":2,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/posts\/9569\/revisions"}],"predecessor-version":[{"id":9575,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/posts\/9569\/revisions\/9575"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/media\/9573"}],"wp:attachment":[{"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/media?parent=9569"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/categories?post=9569"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/tags?post=9569"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}