{"id":9553,"date":"2022-10-07T10:17:03","date_gmt":"2022-10-07T13:17:03","guid":{"rendered":"https:\/\/www.emco.mil.cl\/?p=9553"},"modified":"2022-10-07T10:17:03","modified_gmt":"2022-10-07T13:17:03","slug":"ceremonia-de-despedida-de-dotaciones-antarticas-2022-2023","status":"publish","type":"post","link":"https:\/\/www.emco.mil.cl\/index.php\/2022\/10\/07\/ceremonia-de-despedida-de-dotaciones-antarticas-2022-2023\/","title":{"rendered":"Ceremonia de despedida de Dotaciones Ant\u00e1rticas 2022-2023"},"content":{"rendered":"\n<p>En el marco de las actividades ant\u00e1rticas que desarrolla el Estado Mayor Conjunto, este jueves 6 de octubre se efectu\u00f3 la ceremonia de despedida del personal del Ej\u00e9rcito, Armada, Fuerza A\u00e9rea y Direcci\u00f3n General de Aeron\u00e1utica Civil, que a partir de noviembre del presente a\u00f1o reemplazar\u00e1n a las actuales dotaciones de las bases ant\u00e1rticas chilenas.<\/p>\n\n\n\n<p>La ceremonia se llev\u00f3 a cabo en las instalaciones del Centro Conjunto de Operaciones de Paz (CECOPAC) y fue presidida por la Ministra de Defensa Nacional, Maya Fern\u00e1ndez Allende, quien despidi\u00f3 personalmente a cada uno de los integrantes de las nuevas dotaciones, acompa\u00f1ada por el Jefe del Estado Mayor Conjunto, Vicealmirante Jos\u00e9 Luis Fern\u00e1ndez Morales.&nbsp; En la ocasi\u00f3n tambi\u00e9n se cont\u00f3 con la presencia del Subsecretario para las Fuerzas Armadas, Galo Eldestein Silber, adem\u00e1s de representantes de las Instituciones de las Fuerzas Armadas, del Ministerio de Relaciones Exteriores (MINREL), el Instituto Ant\u00e1rtico Chileno (INACH), la Direcci\u00f3n General de Aeron\u00e1utica Civil (DGAC) y la Subsecretar\u00eda de Defensa.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img fetchpriority=\"high\" decoding=\"async\" width=\"878\" height=\"419\" src=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/10\/interna1-1.jpg\" alt=\"\" class=\"wp-image-9554\" srcset=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/10\/interna1-1.jpg 878w, https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/10\/interna1-1-300x143.jpg 300w, https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/10\/interna1-1-768x367.jpg 768w, https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/10\/interna1-1-350x167.jpg 350w\" sizes=\"(max-width: 878px) 100vw, 878px\" \/><\/figure>\n<\/div>\n\n\n<p>La actividad comenz\u00f3 a las 9:00 de la ma\u00f1ana con los honores a la Ministra de Defensa para, posteriormente dirigirse a los presentes el Coronel de Aviaci\u00f3n Marcelo Flores, quien realiz\u00f3 una alocuci\u00f3n dirigida al personal desplegado haciendo hincapi\u00e9 en las importantes tareas contra\u00eddas en esta misi\u00f3n, el sacrificio personal al dejar a sus familia y el significativo aporte que le entregar\u00e1n al pa\u00eds en materias de concientizaci\u00f3n del medio ambiente, de las ciencias y de la soberan\u00eda nacional al ser nuestros embajadores ante el mundo.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img decoding=\"async\" width=\"878\" height=\"419\" src=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/10\/interna2-1.jpg\" alt=\"\" class=\"wp-image-9555\" srcset=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/10\/interna2-1.jpg 878w, https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/10\/interna2-1-300x143.jpg 300w, https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/10\/interna2-1-768x367.jpg 768w, https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/10\/interna2-1-350x167.jpg 350w\" sizes=\"(max-width: 878px) 100vw, 878px\" \/><\/figure>\n<\/div>\n\n\n<p>Consecutivamente, el personal despedido recibi\u00f3 el saludo personal de la Ministra de Defensa para luego ingresar al auditorio de CECOPAC con el objetivo de presenciar los saludos de bienvenida de los actuales integrantes de las bases ant\u00e1rticas chilenas: O\u00b4Higgins (Ej\u00e9rcito), Prat (Armada) y Frei (Fuerza A\u00e9rea de Chile), extendidas al personal que los relevar\u00e1, para pasar seguidamente a la toma de fotograf\u00edas conjuntas de las delegaciones.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img decoding=\"async\" width=\"878\" height=\"419\" src=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/10\/interna3-1.jpg\" alt=\"\" class=\"wp-image-9556\" srcset=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/10\/interna3-1.jpg 878w, https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/10\/interna3-1-300x143.jpg 300w, https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/10\/interna3-1-768x367.jpg 768w, https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/10\/interna3-1-350x167.jpg 350w\" sizes=\"(max-width: 878px) 100vw, 878px\" \/><\/figure>\n<\/div>\n\n\n<p>A continuaci\u00f3n, la Ministra de Defensa se dirigi\u00f3 a los presentes para destacar la importancia de la misi\u00f3n que nuestras Fuerzas Armadas cumplen con la presencia permanente de su personal en el continente blanco, el cual representa al Estado de Chile ante la comunidad internacional, difundiendo y resguardando los intereses de nuestro pa\u00eds, adem\u00e1s de apoyar el desarrollo de actividades cient\u00edficas, cautelar el cuidado del medio ambiente y controlar la explotaci\u00f3n de los recursos vivos ant\u00e1rticos en un escenario de creciente actividad tur\u00edstica y comercial en esas latitudes.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En el marco de las actividades ant\u00e1rticas que desarrolla el Estado Mayor Conjunto, este jueves 6 de octubre se efectu\u00f3 la ceremonia de despedida del personal del Ej\u00e9rcito, Armada, Fuerza A\u00e9rea y Direcci\u00f3n General de Aeron\u00e1utica Civil, que a partir de noviembre del presente a\u00f1o reemplazar\u00e1n a las actuales dotaciones de las bases ant\u00e1rticas chilenas&#8230;.<\/p>\n","protected":false},"author":5,"featured_media":9557,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"footnotes":""},"categories":[30,3],"tags":[],"class_list":["post-9553","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-30","category-noticias"],"_links":{"self":[{"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/posts\/9553","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/comments?post=9553"}],"version-history":[{"count":1,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/posts\/9553\/revisions"}],"predecessor-version":[{"id":9558,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/posts\/9553\/revisions\/9558"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/media\/9557"}],"wp:attachment":[{"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/media?parent=9553"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/categories?post=9553"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/tags?post=9553"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}