{"id":9425,"date":"2022-08-26T16:45:00","date_gmt":"2022-08-26T20:45:00","guid":{"rendered":"https:\/\/www.emco.mil.cl\/?p=9425"},"modified":"2022-08-31T16:47:11","modified_gmt":"2022-08-31T20:47:11","slug":"visita-del-subsecretario-de-defensa-al-comando-conjunto-austral","status":"publish","type":"post","link":"https:\/\/www.emco.mil.cl\/index.php\/2022\/08\/26\/visita-del-subsecretario-de-defensa-al-comando-conjunto-austral\/","title":{"rendered":"Visita del Subsecretario de Defensa al Comando Conjunto Austral"},"content":{"rendered":"\n<p>En el marco de la 57\u00b0 Reuni\u00f3n del Consejo de Pol\u00edtica Ant\u00e1rtica llevada a cabo en Punta Arenas, el d\u00eda 25 de agosto el Subsecretario de Defensa, Luis Fernando Ayala Gonz\u00e1lez, hizo un espacio en su agenda para realizar una visita al Comando Conjunto Austral (CCA), lugar en donde el Jefe de Estado Mayor y Comandante del Cuartel General del CCA, Capit\u00e1n de Nav\u00edo IM Luis Sarnataro Lillo, le expuso la historia, organizaci\u00f3n, capacidades y despliegue de los medios de las componentes del Comando, adem\u00e1s de las distintas actividades operativas, de entrenamiento y ejercicios que se han efectuado desde el a\u00f1o 2020 a la fecha en el Teatro de Operaciones Austral Conjunto (TOAC).<\/p>\n\n\n\n<p>La instancia, en la que tambi\u00e9n participaron oficiales, suboficiales y personal del Comando Conjunto Austral, sirvi\u00f3 para enterar al Subsecretario de diversos aspectos de esta Fuerza dependiente del Estado Mayor Conjunto, as\u00ed como el \u00e1rea de jurisdicci\u00f3n del TOAC, el trabajo integrado del personal ac\u00e1 destinado desde las Fuerzas Armadas y de Orden y Seguridad, adem\u00e1s de entender el funcionamiento general en tiempos de normalidad y en Estado de Excepci\u00f3n en este Comando Conjunto.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img fetchpriority=\"high\" decoding=\"async\" width=\"878\" height=\"397\" src=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/08\/interna-4.jpg\" alt=\"\" class=\"wp-image-9426\" srcset=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/08\/interna-4.jpg 878w, https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/08\/interna-4-300x136.jpg 300w, https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/08\/interna-4-768x347.jpg 768w, https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/08\/interna-4-350x158.jpg 350w\" sizes=\"(max-width: 878px) 100vw, 878px\" \/><\/figure>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>En el marco de la 57\u00b0 Reuni\u00f3n del Consejo de Pol\u00edtica Ant\u00e1rtica llevada a cabo en Punta Arenas, el d\u00eda 25 de agosto el Subsecretario de Defensa, Luis Fernando Ayala Gonz\u00e1lez, hizo un espacio en su agenda para realizar una visita al Comando Conjunto Austral (CCA), lugar en donde el Jefe de Estado Mayor y&#8230;<\/p>\n","protected":false},"author":5,"featured_media":9428,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"footnotes":""},"categories":[30,3],"tags":[],"class_list":["post-9425","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-30","category-noticias"],"_links":{"self":[{"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/posts\/9425","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/comments?post=9425"}],"version-history":[{"count":1,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/posts\/9425\/revisions"}],"predecessor-version":[{"id":9427,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/posts\/9425\/revisions\/9427"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/media\/9428"}],"wp:attachment":[{"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/media?parent=9425"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/categories?post=9425"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/tags?post=9425"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}