{"id":9318,"date":"2022-07-25T11:15:00","date_gmt":"2022-07-25T15:15:00","guid":{"rendered":"https:\/\/www.emco.mil.cl\/?p=9318"},"modified":"2022-07-27T11:16:56","modified_gmt":"2022-07-27T15:16:56","slug":"estado-mayor-conjunto-y-cancilleria-realizan-curso-para-dotaciones-antarticas-2022-2023","status":"publish","type":"post","link":"https:\/\/www.emco.mil.cl\/index.php\/2022\/07\/25\/estado-mayor-conjunto-y-cancilleria-realizan-curso-para-dotaciones-antarticas-2022-2023\/","title":{"rendered":"Estado Mayor Conjunto y Canciller\u00eda realizan curso para Dotaciones Ant\u00e1rticas 2022-2023"},"content":{"rendered":"\n<p>El Estado Mayor Conjunto y la Divisi\u00f3n de Asuntos Ant\u00e1rticos de Canciller\u00eda, organizaron el curso para las Dotaciones Ant\u00e1rticas de las Fuerzas Armadas 2022-2023, el cual se desarroll\u00f3 entre el 20 y el 22 de julio en el Sal\u00f3n O\u2019Higgins del Ministerio de Relaciones Exteriores.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img fetchpriority=\"high\" decoding=\"async\" width=\"878\" height=\"410\" src=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/07\/interna2-4.jpg\" alt=\"\" class=\"wp-image-9319\" srcset=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/07\/interna2-4.jpg 878w, https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/07\/interna2-4-300x140.jpg 300w, https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/07\/interna2-4-768x359.jpg 768w, https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/07\/interna2-4-350x163.jpg 350w\" sizes=\"(max-width: 878px) 100vw, 878px\" \/><\/figure>\n<\/div>\n\n\n<p>La instancia cont\u00f3 con la presencia de instructores de las Fuerzas Armadas, la Direcci\u00f3n General de Aeron\u00e1utica Civil, el Instituto Ant\u00e1rtico Chileno, la Subsecretar\u00eda de Defensa, la Direcci\u00f3n Nacional de Fronteras y L\u00edmites y la Divisi\u00f3n de Asuntos Ant\u00e1rticos, participando en su inauguraci\u00f3n el Secretario General de Pol\u00edtica Exterior (s), Embajador Patricio Powell; el Jefe de la Divisi\u00f3n de Asuntos Ant\u00e1rticos, Embajador Francisco Bergu\u00f1o y el Jefe del Departamento Ant\u00e1rtico del Estado Mayor Conjunto, Coronel de Aviaci\u00f3n Marcelo Flores. En la oportunidad, intervino el Embajador Powell destac\u00f3 que: <em>\u201cTodas las instituciones ant\u00e1rticas trabajan para lograr objetivos comunes, enunciados en la Pol\u00edtica Ant\u00e1rtica Nacional\u201d.<\/em><\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img decoding=\"async\" width=\"878\" height=\"410\" src=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/07\/interna1-4.jpg\" alt=\"\" class=\"wp-image-9320\" srcset=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/07\/interna1-4.jpg 878w, https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/07\/interna1-4-300x140.jpg 300w, https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/07\/interna1-4-768x359.jpg 768w, https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/07\/interna1-4-350x163.jpg 350w\" sizes=\"(max-width: 878px) 100vw, 878px\" \/><\/figure>\n<\/div>\n\n\n<p>En la actividad participaron m\u00e1s de 100 efectivos del Ej\u00e9rcito, la Armada y la Fuerza A\u00e9rea, tanto de manera presencial como telem\u00e1tica. Cabe destacar que este curso, que se efect\u00faa anualmente, tiene como objetivo formar al personal que se desempe\u00f1ar\u00e1 en territorio ant\u00e1rtico en las exigencias y las obligaciones del Sistema del Tratado Ant\u00e1rtico, as\u00ed como los fundamentos de nuestra Pol\u00edtica Ant\u00e1rtica Nacional.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Estado Mayor Conjunto y la Divisi\u00f3n de Asuntos Ant\u00e1rticos de Canciller\u00eda, organizaron el curso para las Dotaciones Ant\u00e1rticas de las Fuerzas Armadas 2022-2023, el cual se desarroll\u00f3 entre el 20 y el 22 de julio en el Sal\u00f3n O\u2019Higgins del Ministerio de Relaciones Exteriores. La instancia cont\u00f3 con la presencia de instructores de las&#8230;<\/p>\n","protected":false},"author":5,"featured_media":9321,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"footnotes":""},"categories":[30,3],"tags":[],"class_list":["post-9318","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-30","category-noticias"],"_links":{"self":[{"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/posts\/9318","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/comments?post=9318"}],"version-history":[{"count":1,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/posts\/9318\/revisions"}],"predecessor-version":[{"id":9322,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/posts\/9318\/revisions\/9322"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/media\/9321"}],"wp:attachment":[{"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/media?parent=9318"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/categories?post=9318"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/tags?post=9318"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}