{"id":8948,"date":"2022-06-01T10:08:03","date_gmt":"2022-06-01T14:08:03","guid":{"rendered":"https:\/\/www.emco.mil.cl\/?p=8948"},"modified":"2022-06-02T14:25:16","modified_gmt":"2022-06-02T18:25:16","slug":"clase-magistral-2022-de-la-ministra-de-defensa-nacional-en-la-escuela-militar","status":"publish","type":"post","link":"https:\/\/www.emco.mil.cl\/index.php\/2022\/06\/01\/clase-magistral-2022-de-la-ministra-de-defensa-nacional-en-la-escuela-militar\/","title":{"rendered":"Clase Magistral 2022 de la Ministra de Defensa Nacional en la Escuela Militar"},"content":{"rendered":"\n<p>La ma\u00f1ana de este 31 de mayo se realiz\u00f3, en el Aula Magna de la Escuela Militar, la Clase Magistral de la Ministra de Defensa Nacional 2022.<\/p>\n\n\n\n<p>La actividad, cont\u00f3 con la presencia de la Ministra de Defensa Nacional, Maya Fern\u00e1ndez Allende, los Comandantes en Jefe del Ej\u00e9rcito, Armada y Fuerza A\u00e9rea de Chile, el Jefe del Estado Mayor Conjunto, General de Divisi\u00f3n Guillermo R. Paiva Hern\u00e1ndez, autoridades ministeriales, autoridades y delegaciones de las Fuerzas Armadas, representantes de orden y seguridad nacional, e invitados especiales.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img fetchpriority=\"high\" decoding=\"async\" width=\"878\" height=\"421\" src=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/06\/interna1.jpg\" alt=\"\" class=\"wp-image-8949\" srcset=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/06\/interna1.jpg 878w, https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/06\/interna1-300x144.jpg 300w, https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/06\/interna1-768x368.jpg 768w, https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/06\/interna1-350x168.jpg 350w\" sizes=\"(max-width: 878px) 100vw, 878px\" \/><\/figure>\n<\/div>\n\n\n<p>El Ministra de Defensa comenz\u00f3 la Clase Magistral: \u201cDesaf\u00edos presentes y futuros de la Defensa Nacional\u201d, agradeciendo el trabajo de los miembros de las Fuerzas Armadas que se mantuvieron desplegados en apoyo a la ciudadan\u00eda durante los momentos m\u00e1s duros de la pandemia del coronavirus y a quienes han cumplido funciones durante el Estado de Excepci\u00f3n Constitucional en las provincias de Arauco y Biob\u00edo y en la Regi\u00f3n de la Araucan\u00eda, para proseguir con una reflexi\u00f3n acerca del desaf\u00edo que asumi\u00f3 el 11 de marzo reci\u00e9n pasado en la conducci\u00f3n de las Fuerzas Armadas: \u201cno solo es importante en lo personal, porque desde el Gobierno, asumimos la conducci\u00f3n del Ministerio de Defensa para aportar a un nuevo ciclo en las relaciones c\u00edvico-militares de nuestro pa\u00eds, caracterizado por la consolidaci\u00f3n y proyecci\u00f3n de la conducci\u00f3n civil de la Defensa. Pues, transcurridos ya 12 a\u00f1os desde la reforma al ministerio, es tiempo de hacer un balance y proyectar el futuro del conjunto de nuestra institucionalidad\u201d, coment\u00f3.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img decoding=\"async\" width=\"878\" height=\"420\" src=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/06\/interna2.jpg\" alt=\"\" class=\"wp-image-8950\" srcset=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/06\/interna2.jpg 878w, https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/06\/interna2-300x144.jpg 300w, https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/06\/interna2-768x367.jpg 768w, https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/06\/interna2-350x167.jpg 350w\" sizes=\"(max-width: 878px) 100vw, 878px\" \/><\/figure>\n<\/div>\n\n\n<p>Durante su exposici\u00f3n, la Ministra Fern\u00e1ndez destac\u00f3 el respaldo del Gobierno en el fortalecimiento de la industria militar nacional, contribuyendo al desarrollo cient\u00edfico y tecnol\u00f3gico del pa\u00eds y el trabajo en conjunto con el Ministerio de Ciencia, con el prop\u00f3sito de desarrollar el Sistema Nacional Satelital, para terminar su presentaci\u00f3n manifestando a los presentes: \u201ca ustedes, savia nueva y renovadora, Chile les agradece. La Patria cuenta con hombres y mujeres de uniforme que est\u00e1n formados y preparados para hacer frente a los desaf\u00edos futuros, cuentan ustedes con un Ministerio de Defensa consciente del momento hist\u00f3rico que vivimos\u201d.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img decoding=\"async\" width=\"878\" height=\"339\" src=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/06\/interna3.jpg\" alt=\"\" class=\"wp-image-8951\" srcset=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/06\/interna3.jpg 878w, https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/06\/interna3-300x116.jpg 300w, https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/06\/interna3-768x297.jpg 768w, https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/06\/interna3-350x135.jpg 350w\" sizes=\"(max-width: 878px) 100vw, 878px\" \/><\/figure>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>La ma\u00f1ana de este 31 de mayo se realiz\u00f3, en el Aula Magna de la Escuela Militar, la Clase Magistral de la Ministra de Defensa Nacional 2022. La actividad, cont\u00f3 con la presencia de la Ministra de Defensa Nacional, Maya Fern\u00e1ndez Allende, los Comandantes en Jefe del Ej\u00e9rcito, Armada y Fuerza A\u00e9rea de Chile, el&#8230;<\/p>\n","protected":false},"author":5,"featured_media":8952,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"footnotes":""},"categories":[30,3],"tags":[],"class_list":["post-8948","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-30","category-noticias"],"_links":{"self":[{"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/posts\/8948","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/comments?post=8948"}],"version-history":[{"count":4,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/posts\/8948\/revisions"}],"predecessor-version":[{"id":8981,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/posts\/8948\/revisions\/8981"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/media\/8952"}],"wp:attachment":[{"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/media?parent=8948"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/categories?post=8948"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/tags?post=8948"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}