{"id":8814,"date":"2022-03-21T15:21:00","date_gmt":"2022-03-21T18:21:00","guid":{"rendered":"https:\/\/www.emco.mil.cl\/?p=8814"},"modified":"2022-05-25T11:04:17","modified_gmt":"2022-05-25T15:04:17","slug":"aniversario-de-la-fuerza-aerea-de-chile-en-el-comando-conjunto-norte","status":"publish","type":"post","link":"https:\/\/www.emco.mil.cl\/index.php\/2022\/03\/21\/aniversario-de-la-fuerza-aerea-de-chile-en-el-comando-conjunto-norte\/","title":{"rendered":"Aniversario de la Fuerza A\u00e9rea de Chile en el Comando Conjunto Norte"},"content":{"rendered":"\n<p>El viernes 18 de marzo a las 08:30 horas, en dependencias del Comando Conjunto Norte, se efectu\u00f3 la ceremonia en conmemoraci\u00f3n del 92\u00b0 Aniversario de la Fuerza A\u00e9rea de Chile.<\/p>\n\n\n\n<p>La ceremonia comenz\u00f3 con los honores de ordenanza por parte del Jefe de Estado Mayor, Coronel Carlos Cammas Wittich, al Comandante del Comando Norte, Vicealmirante Jos\u00e9 Luis Morales Fern\u00e1ndez, continuando con un discurso alusivo a la conmemoraci\u00f3n, realizado por el oficial m\u00e1s antiguo de la instituci\u00f3n, Comandante de Grupo Patricio Illanes Ruiz, quien destac\u00f3: <em>\u201cestamos conscientes de que somos un real aporte al desarrollo de nuestra patria, no s\u00f3lo por la contribuci\u00f3n al mantenimiento de la paz, sino tambi\u00e9n porque somos una fuerza a\u00e9rea polivalente y dotada de personal altamente capacitado, lo que nos permite tambi\u00e9n enfrentar requerimientos distintos a los de la defensa, en beneficio directo de nuestros compatriotas y del estado, a quienes nos debemos como instituci\u00f3n\u201d.<\/em><\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img fetchpriority=\"high\" decoding=\"async\" width=\"878\" height=\"467\" src=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/03\/interna-1.jpg\" alt=\"\" class=\"wp-image-8815\" srcset=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/03\/interna-1.jpg 878w, https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/03\/interna-1-300x160.jpg 300w, https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/03\/interna-1-768x408.jpg 768w, https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/03\/interna-1-350x186.jpg 350w\" sizes=\"(max-width: 878px) 100vw, 878px\" \/><\/figure>\n<\/div>\n\n\n<p>Posterior al discurso, el Vicealmirante Fern\u00e1ndez, acompa\u00f1ado por el Comandante Illanes, hizo entrega de la condecoraci\u00f3n \u201cEstrella Militar\u201d por 10 a\u00f1os de servicio al Teniente (DA) de la Fuerza A\u00e9rea Chile, Juan Pablo Santib\u00e1\u00f1ez Mujica, perteneciente al Departamento de Inteligencia del Comando.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"878\" height=\"467\" src=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/03\/interna-2.jpg\" alt=\"\" class=\"wp-image-8816\" srcset=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/03\/interna-2.jpg 878w, https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/03\/interna-2-300x160.jpg 300w, https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/03\/interna-2-768x408.jpg 768w, https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/03\/interna-2-350x186.jpg 350w\" sizes=\"(max-width: 878px) 100vw, 878px\" \/><\/figure>\n\n\n\n<p>La ceremonia finaliz\u00f3 con las palabras del Comandante del Comando Conjunto Norte, qui\u00e9n reflexion\u00f3 sobre el aniversario de la instituci\u00f3n, su contribuci\u00f3n al estado de Chile y, de manera muy especial, felicit\u00f3 al personal perteneciente a la Fuerza A\u00e9rea y aquellos que recibieron medallas por a\u00f1os de servicio.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El viernes 18 de marzo a las 08:30 horas, en dependencias del Comando Conjunto Norte, se efectu\u00f3 la ceremonia en conmemoraci\u00f3n del 92\u00b0 Aniversario de la Fuerza A\u00e9rea de Chile. La ceremonia comenz\u00f3 con los honores de ordenanza por parte del Jefe de Estado Mayor, Coronel Carlos Cammas Wittich, al Comandante del Comando Norte, Vicealmirante&#8230;<\/p>\n","protected":false},"author":5,"featured_media":8817,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"footnotes":""},"categories":[30,3],"tags":[],"class_list":["post-8814","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-30","category-noticias"],"_links":{"self":[{"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/posts\/8814","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/comments?post=8814"}],"version-history":[{"count":3,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/posts\/8814\/revisions"}],"predecessor-version":[{"id":8906,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/posts\/8814\/revisions\/8906"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/media\/8817"}],"wp:attachment":[{"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/media?parent=8814"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/categories?post=8814"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/tags?post=8814"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}