{"id":8426,"date":"2021-12-01T16:02:00","date_gmt":"2021-12-01T19:02:00","guid":{"rendered":"https:\/\/www.emco.mil.cl\/?p=8426"},"modified":"2021-12-06T16:11:52","modified_gmt":"2021-12-06T19:11:52","slug":"ceremonia-del-decimo-octavo-aniversario-del-comando-conjunto-norte","status":"publish","type":"post","link":"https:\/\/www.emco.mil.cl\/index.php\/2021\/12\/01\/ceremonia-del-decimo-octavo-aniversario-del-comando-conjunto-norte\/","title":{"rendered":"Ceremonia del d\u00e9cimo octavo Aniversario del Comando Conjunto Norte"},"content":{"rendered":"\n<p>A las 11:30 horas del d\u00eda martes 30 de noviembre, se llev\u00f3 a cabo la ceremonia en conmemoraci\u00f3n del d\u00e9cimo octavo aniversario del Comando Conjunto Norte, que fue presidida por el Delegado Presidencial Regional (S), Sr. Natan Olivos N\u00fa\u00f1ez y que cont\u00f3 con la participaci\u00f3n de autoridades civiles y militares de la Regi\u00f3n de Tarapac\u00e1.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img fetchpriority=\"high\" decoding=\"async\" width=\"878\" height=\"445\" src=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2021\/12\/interna1-web-int.jpg\" alt=\"\" class=\"wp-image-8428\" srcset=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2021\/12\/interna1-web-int.jpg 878w, https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2021\/12\/interna1-web-int-300x152.jpg 300w, https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2021\/12\/interna1-web-int-768x389.jpg 768w, https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2021\/12\/interna1-web-int-350x177.jpg 350w\" sizes=\"(max-width: 878px) 100vw, 878px\" \/><\/figure>\n\n\n\n<p>El Jefe de Estado Mayor, Coronel de Aviaci\u00f3n (A) Oscar Zambrano, efectu\u00f3 un discurso haciendo alusi\u00f3n a la historia de c\u00f3mo fue evolucionando hasta lo que hoy en d\u00eda conocemos como Comando Conjunto Norte y agradeciendo todo el profesionalismo y dedicaci\u00f3n de las personas que conforman las filas de esta unidad, expresando: <em>\u201c<\/em>El trabajo desarrollado, muchas veces en condiciones dif\u00edciles, se ve sustentado en el compromiso, entrega y la dedicaci\u00f3n de los hombres y mujeres que conforman esta unidad. Gracias al esfuerzo de todos los integrantes de este Comando, desde su Comandante hasta el m\u00e1s joven, para as\u00ed cumplir todas y cada una de las tareas en forma eficiente y oportuna.\u201d<\/p>\n\n\n\n<p>Posterior al discurso, se hizo entrega de los diplomas para el personal que conforma el Cuadro de Honor del CCN, en reconocimiento a su preparaci\u00f3n personal y cualidades personales:<\/p>\n\n\n\n<p>Mejor profesional administrativo: SOF. Edgardo Grand\u00f3n Cancino (Ej\u00e9rcito)<\/p>\n\n\n\n<p>Mejor profesional operativo: SG1 Cristi\u00e1n Carrillo Seguel (Ej\u00e9rcito)<\/p>\n\n\n\n<p>Mejor compa\u00f1ero: S1 Miguel Calder\u00f3n Jaque (Armada)<\/p>\n\n\n\n<p>Mejor deportista: CB2\u00a0Nicole Aranda Elgueta (Ej\u00e9rcito)<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"855\" height=\"448\" src=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2021\/12\/interna2-web-1.jpg\" alt=\"\" class=\"wp-image-8431\" srcset=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2021\/12\/interna2-web-1.jpg 855w, https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2021\/12\/interna2-web-1-300x157.jpg 300w, https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2021\/12\/interna2-web-1-768x402.jpg 768w, https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2021\/12\/interna2-web-1-350x183.jpg 350w\" sizes=\"(max-width: 855px) 100vw, 855px\" \/><\/figure>\n\n\n\n<p>Posteriormente, el Comandante del Comando Conjunto Norte, Vicealmirante Jos\u00e9 Luis Fern\u00e1ndez impuso las medallas \u201cServicio del Ministerio de Defensa Nacional\u201d, \u201cEstado Mayor Conjunto\u201d, las Condecoraciones \u201cAl M\u00e9rito Militar de las Fuerzas Armadas\u201d por 10 y 20 a\u00f1os de servicio y finalmente, la Condecoraci\u00f3n \u201cAl Gran M\u00e9rito Ej\u00e9rcito de Chile\u201d por 34 a\u00f1os de servicio al Suboficial Mayor Claudio Benavides Norambuena.<\/p>\n\n\n<style>.kb-gallery-type-fluidcarousel.kb-gallery-id-_f469d8-d2 .kt-blocks-carousel .kt-blocks-carousel-init .kb-slide-item{padding:4px 5px;}.kb-gallery-type-fluidcarousel.kb-gallery-id-_f469d8-d2 .kt-blocks-carousel .kt-blocks-carousel-init.kb-carousel-mode-align-left .kb-slide-item{padding:4px 10px 4px 0;}.kb-gallery-id-_f469d8-d2.kb-gallery-ul.kb-gallery-type-fluidcarousel .kt-blocks-carousel figure .kb-gal-image-radius, .kb-gallery-id-_f469d8-d2.kb-gallery-ul.kb-gallery-type-fluidcarousel .kt-blocks-carousel figure .kb-gal-image-radius img{height:300px;}.kb-gallery-id-_f469d8-d2 .kadence-blocks-gallery-item .kb-gal-image-radius, .kb-gallery-id-_f469d8-d2 .kb-slide-item .kb-gal-image-radius img{border-radius:0px 0px 0px 0px;;}.kb-gallery-wrap-id-_f469d8-d2.wp-block-kadence-advancedgallery{overflow:visible;}.kb-gallery-wrap-id-_f469d8-d2.wp-block-kadence-advancedgallery .kt-blocks-carousel{overflow:visible;max-width:100%;}<\/style>\n<div class=\"wp-block-kadence-advancedgallery kb-gallery-wrap-id-_f469d8-d2\"><div class=\"kb-gallery-ul kb-gallery-type-fluidcarousel kb-gallery-id-_f469d8-d2 kb-gallery-caption-style-bottom-hover kb-gallery-filter-none\" data-image-filter=\"none\" data-lightbox-caption=\"true\"><div class=\"kt-blocks-carousel kt-carousel-container-dotstyle-dark\"><div class=\"kt-blocks-carousel-init kb-blocks-fluid-carousel kt-carousel-arrowstyle-whiteondark kt-carousel-dotstyle-dark\" data-slider-anim-speed=\"400\" data-slider-type=\"fluidcarousel\" data-slider-scroll=\"1\" data-slider-arrows=\"true\" data-slider-dots=\"true\" data-slider-hover-pause=\"false\" data-slider-auto=\"false\" data-slider-speed=\"7000\"><div class=\"kb-slide-item kb-gallery-carousel-item\"><div class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kadence-blocks-gallery-item-hide-caption\"><div class=\"kb-gal-image-radius\"><div class=\"kb-gallery-image-contain\"><img decoding=\"async\" src=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2021\/12\/interna3-web.jpg\" width=\"878\" height=\"585\" alt=\"\" data-full-image=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2021\/12\/interna3-web.jpg\" data-light-image=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2021\/12\/interna3-web.jpg\" data-id=\"8432\" data-link=\"https:\/\/www.emco.mil.cl\/?attachment_id=8432\" class=\"wp-image-8432 skip-lazy\" srcset=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2021\/12\/interna3-web.jpg 878w, https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2021\/12\/interna3-web-300x200.jpg 300w, https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2021\/12\/interna3-web-768x512.jpg 768w, https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2021\/12\/interna3-web-350x233.jpg 350w\" sizes=\"(max-width: 878px) 100vw, 878px\" \/><\/div><\/div><\/figure><\/div><\/div><\/div><div class=\"kb-slide-item kb-gallery-carousel-item\"><div class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kadence-blocks-gallery-item-hide-caption\"><div class=\"kb-gal-image-radius\"><div class=\"kb-gallery-image-contain\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2021\/12\/interna4-web.jpg\" width=\"878\" height=\"585\" alt=\"\" data-full-image=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2021\/12\/interna4-web.jpg\" data-light-image=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2021\/12\/interna4-web.jpg\" data-id=\"8433\" data-link=\"https:\/\/www.emco.mil.cl\/?attachment_id=8433\" class=\"wp-image-8433 skip-lazy\" srcset=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2021\/12\/interna4-web.jpg 878w, https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2021\/12\/interna4-web-300x200.jpg 300w, https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2021\/12\/interna4-web-768x512.jpg 768w, https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2021\/12\/interna4-web-350x233.jpg 350w\" sizes=\"(max-width: 878px) 100vw, 878px\" \/><\/div><\/div><\/figure><\/div><\/div><\/div><div class=\"kb-slide-item kb-gallery-carousel-item\"><div class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kadence-blocks-gallery-item-hide-caption\"><div class=\"kb-gal-image-radius\"><div class=\"kb-gallery-image-contain\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2021\/12\/interna5-web.jpg\" width=\"878\" height=\"585\" alt=\"\" data-full-image=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2021\/12\/interna5-web.jpg\" data-light-image=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2021\/12\/interna5-web.jpg\" data-id=\"8434\" data-link=\"https:\/\/www.emco.mil.cl\/?attachment_id=8434\" class=\"wp-image-8434 skip-lazy\" srcset=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2021\/12\/interna5-web.jpg 878w, https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2021\/12\/interna5-web-300x200.jpg 300w, https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2021\/12\/interna5-web-768x512.jpg 768w, https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2021\/12\/interna5-web-350x233.jpg 350w\" sizes=\"(max-width: 878px) 100vw, 878px\" \/><\/div><\/div><\/figure><\/div><\/div><\/div><div class=\"kb-slide-item kb-gallery-carousel-item\"><div class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kadence-blocks-gallery-item-hide-caption\"><div class=\"kb-gal-image-radius\"><div class=\"kb-gallery-image-contain\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2021\/12\/interna6-web.jpg\" width=\"878\" height=\"585\" alt=\"\" data-full-image=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2021\/12\/interna6-web.jpg\" data-light-image=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2021\/12\/interna6-web.jpg\" data-id=\"8435\" data-link=\"https:\/\/www.emco.mil.cl\/?attachment_id=8435\" class=\"wp-image-8435 skip-lazy\" srcset=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2021\/12\/interna6-web.jpg 878w, https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2021\/12\/interna6-web-300x200.jpg 300w, https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2021\/12\/interna6-web-768x512.jpg 768w, https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2021\/12\/interna6-web-350x233.jpg 350w\" sizes=\"(max-width: 878px) 100vw, 878px\" \/><\/div><\/div><\/figure><\/div><\/div><\/div><\/div><\/div><\/div><\/div>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A las 11:30 horas del d\u00eda martes 30 de noviembre, se llev\u00f3 a cabo la ceremonia en conmemoraci\u00f3n del d\u00e9cimo octavo aniversario del Comando Conjunto Norte, que fue presidida por el Delegado Presidencial Regional (S), Sr. Natan Olivos N\u00fa\u00f1ez y que cont\u00f3 con la participaci\u00f3n de autoridades civiles y militares de la Regi\u00f3n de Tarapac\u00e1&#8230;.<\/p>\n","protected":false},"author":5,"featured_media":8436,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"footnotes":""},"categories":[12,3],"tags":[],"class_list":["post-8426","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-12","category-noticias"],"_links":{"self":[{"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/posts\/8426","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/comments?post=8426"}],"version-history":[{"count":2,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/posts\/8426\/revisions"}],"predecessor-version":[{"id":8438,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/posts\/8426\/revisions\/8438"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/media\/8436"}],"wp:attachment":[{"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/media?parent=8426"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/categories?post=8426"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/tags?post=8426"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}