{"id":8113,"date":"2021-10-28T16:39:09","date_gmt":"2021-10-28T19:39:09","guid":{"rendered":"https:\/\/www2.emco.mil.cl\/?p=8113"},"modified":"2021-10-28T16:39:09","modified_gmt":"2021-10-28T19:39:09","slug":"comando-conjunto-norte-realiza-seminario-de-planificacion-de-operaciones-conjuntas","status":"publish","type":"post","link":"https:\/\/www.emco.mil.cl\/index.php\/2021\/10\/28\/comando-conjunto-norte-realiza-seminario-de-planificacion-de-operaciones-conjuntas\/","title":{"rendered":"Comando Conjunto Norte realiza Seminario de Planificaci\u00f3n de Operaciones Conjuntas"},"content":{"rendered":"\n<p>El Comando Conjunto Norte, en el marco de su planificaci\u00f3n anual, efectu\u00f3 el 27 de octubre el \u201cSeminario de Planificaci\u00f3n de Operaciones Conjuntas\u201d, cuyo desarrollo fue por v\u00eda telem\u00e1tica, contando con la participaci\u00f3n de miembros del Estado Mayor Conjunto, Ej\u00e9rcito, Armada, Fuerza A\u00e9rea, la Academia Nacional de Estudios Pol\u00edticos Estrat\u00e9gicos, Carabineros, Polic\u00eda de Investigaciones y Unidad Coordinadora Estrat\u00e9gica Norte.<\/p>\n\n\n\n<p>La jornada, que comenz\u00f3 con las palabras de bienvenida del Comandante del Comando Conjunto Norte, Vicealmirante Sr. Jos\u00e9 Luis Fern\u00e1ndez Morales, refiri\u00e9ndose a la importancia de la Planificaci\u00f3n de Operaciones Conjuntas, cont\u00f3 con la intervenci\u00f3n de cuatro expositores: el profesor Sr. Fernando Wilson Lazo, quien expuso el tema \u201cOperaci\u00f3n Overlord, ejemplo de una compleja planificaci\u00f3n\u201d, seguidamente el &nbsp;General de Divisi\u00f3n John Griffiths Spielman, con \u201cExperiencias del dise\u00f1o operacional en la ofensiva israel\u00ed al L\u00edbano 2006\u201d, el Subprefecto Juan Figueroa Vilches con \u201cPlanificaci\u00f3n de Operaciones contra el Crimen Organizado Transnacional, complejidades y ventajas\u201d para finalizar con el Teniente Coronel Enrique Rebolar Soler,&nbsp; desde el King\u2019s College de Londres, quien &nbsp;expuso el tema \u201cPlanificaci\u00f3n de operaciones Aero Transportadas, potencialidades y vigencia\u201d.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-full\"><img fetchpriority=\"high\" decoding=\"async\" width=\"878\" height=\"130\" src=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2021\/10\/interna.jpg\" alt=\"\" class=\"wp-image-8114\" srcset=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2021\/10\/interna.jpg 878w, https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2021\/10\/interna-300x44.jpg 300w, https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2021\/10\/interna-768x114.jpg 768w, https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2021\/10\/interna-350x52.jpg 350w\" sizes=\"(max-width: 878px) 100vw, 878px\" \/><\/figure><\/div>\n\n\n\n<p>El objetivo de este seminario fue analizar las complejidades y ventajas de la planificaci\u00f3n conjunta en el nivel operacional, para crisis o empleo del potencial b\u00e9lico, as\u00ed como tambi\u00e9n, en la lucha contra el crimen organizado en operaciones interagenciales, para lograr, por medio de este trabajo colaborativo y coordinado de los \u00f3rganos de maniobra del nivel operacional, una adecuada respuesta y por consiguiente el control eficiente en beneficio propio.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Comando Conjunto Norte, en el marco de su planificaci\u00f3n anual, efectu\u00f3 el 27 de octubre el \u201cSeminario de Planificaci\u00f3n de Operaciones Conjuntas\u201d, cuyo desarrollo fue por v\u00eda telem\u00e1tica, contando con la participaci\u00f3n de miembros del Estado Mayor Conjunto, Ej\u00e9rcito, Armada, Fuerza A\u00e9rea, la Academia Nacional de Estudios Pol\u00edticos Estrat\u00e9gicos, Carabineros, Polic\u00eda de Investigaciones y&#8230;<\/p>\n","protected":false},"author":5,"featured_media":8115,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"footnotes":""},"categories":[12,3],"tags":[],"class_list":["post-8113","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-12","category-noticias"],"_links":{"self":[{"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/posts\/8113","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/comments?post=8113"}],"version-history":[{"count":1,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/posts\/8113\/revisions"}],"predecessor-version":[{"id":8116,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/posts\/8113\/revisions\/8116"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/media\/8115"}],"wp:attachment":[{"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/media?parent=8113"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/categories?post=8113"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/tags?post=8113"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}