{"id":7103,"date":"2013-08-30T22:29:49","date_gmt":"2013-08-30T22:29:49","guid":{"rendered":"http:\/\/www.emc.mil.cl\/nemc\/?p=73"},"modified":"2021-09-29T14:19:10","modified_gmt":"2021-09-29T17:19:10","slug":"jemco-expone-ante-curso-de-aspirantes-a-oficial-de-reserva-caor","status":"publish","type":"post","link":"https:\/\/www.emco.mil.cl\/index.php\/2013\/08\/30\/jemco-expone-ante-curso-de-aspirantes-a-oficial-de-reserva-caor\/","title":{"rendered":"JEMCO expone ante Curso de Aspirantes a Oficial de Reserva (CAOR)"},"content":{"rendered":"<p><img decoding=\"async\" class=\"aligncenter\" src=\"https:\/\/www.emco.mil.cl\/\/wp-content\/uploads\/30-agosto-2013-JEMCO-expone-ante-Curso-de-Aspirantes-a-Oficial-de-Reserva-CAOR.jpg\"><br \/>\nEste 30 de agosto se desarroll\u00f3 en dependencias del Centro Conjunto para Operaciones de Paz (CECOPAC), una visita profesional de conocimiento para el Curso de Aspirantes a Oficial de Reserva (CAOR) 2013, presidida por el Jefe del Estado Mayor Conjunto (JEMCO), General de Divisi\u00f3n Hern\u00e1n Mardones R\u00edos.<br \/>\nLa actividad cont\u00f3 adem\u00e1s, con la presencia del Director de la Direcci\u00f3n de Operaciones Internacionales del EMCO, General de Brigada, Oscar Mezzano Escanilla, con el Director del CECOPAC, Coronel de Aviaci\u00f3n (DA) H\u00e9ctor Puebla Aguirre y con un total de 20 Aspirantes a Oficial de Reserva.<br \/>\nEl encuentro tuvo el objetivo de dar a conocer la misi\u00f3n, organizaci\u00f3n y funcionamiento del Estado Mayor Conjunto.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Este 30 de agosto se desarroll\u00f3 en dependencias del Centro Conjunto para Operaciones de Paz (CECOPAC), una visita profesional de conocimiento para el Curso de Aspirantes a Oficial de Reserva (CAOR) 2013, presidida por el Jefe del Estado Mayor Conjunto (JEMCO), General de Divisi\u00f3n Hern\u00e1n Mardones R\u00edos. La actividad cont\u00f3 adem\u00e1s, con la presencia del&#8230;<\/p>\n","protected":false},"author":5,"featured_media":5823,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"footnotes":""},"categories":[28,3],"tags":[],"class_list":["post-7103","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-28","category-noticias"],"_links":{"self":[{"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/posts\/7103","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/comments?post=7103"}],"version-history":[{"count":3,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/posts\/7103\/revisions"}],"predecessor-version":[{"id":7172,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/posts\/7103\/revisions\/7172"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/media\/5823"}],"wp:attachment":[{"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/media?parent=7103"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/categories?post=7103"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/tags?post=7103"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}