{"id":6915,"date":"2014-11-14T20:33:26","date_gmt":"2014-11-14T20:33:26","guid":{"rendered":"http:\/\/www.emco.mil.cl\/?p=1111"},"modified":"2021-09-29T11:35:02","modified_gmt":"2021-09-29T14:35:02","slug":"ff-aa-apoyan-emergencia-en-red-de-transporte-de-santiago","status":"publish","type":"post","link":"https:\/\/www.emco.mil.cl\/index.php\/2014\/11\/14\/ff-aa-apoyan-emergencia-en-red-de-transporte-de-santiago\/","title":{"rendered":"FF.AA. apoyan emergencia en red de transporte de Santiago"},"content":{"rendered":"<p>A trav\u00e9s del Estado Mayor Conjunto, el Ministerio de Defensa puso a disposici\u00f3n de las autoridades del Ministerio del Interior y el Ministerio de Transportes, &nbsp;que coordinan la emergencia suscitada en la red de transporte p\u00fablico de Santiago, buses de las tres instituciones de las Fuerzas Armadas para apoyar los recorridos de superficie a lo largo de la red del Metro a partir de las 15:00 hrs.<\/p>\n<p>Los veh\u00edculos, que normalmente se utilizan para el traslado de personal militar entre las distintas unidades, tienen capacidad para m\u00e1s de 40 pasajeros sentados.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A trav\u00e9s del Estado Mayor Conjunto, el Ministerio de Defensa puso a disposici\u00f3n de las autoridades del Ministerio del Interior y el Ministerio de Transportes, &nbsp;que coordinan la emergencia suscitada en la red de transporte p\u00fablico de Santiago, buses de las tres instituciones de las Fuerzas Armadas para apoyar los recorridos de superficie a lo&#8230;<\/p>\n","protected":false},"author":6,"featured_media":5823,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"footnotes":""},"categories":[26,3],"tags":[],"class_list":["post-6915","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-26","category-noticias"],"_links":{"self":[{"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/posts\/6915","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/comments?post=6915"}],"version-history":[{"count":2,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/posts\/6915\/revisions"}],"predecessor-version":[{"id":7012,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/posts\/6915\/revisions\/7012"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/media\/5823"}],"wp:attachment":[{"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/media?parent=6915"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/categories?post=6915"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/tags?post=6915"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}