{"id":6900,"date":"2014-09-19T18:30:58","date_gmt":"2014-09-19T18:30:58","guid":{"rendered":"http:\/\/www.emco.mil.cl\/?p=998"},"modified":"2021-09-29T11:54:55","modified_gmt":"2021-09-29T14:54:55","slug":"jefe-del-estado-mayor-conjunto-participa-en-la-gran-parada-militar","status":"publish","type":"post","link":"https:\/\/www.emco.mil.cl\/index.php\/2014\/09\/19\/jefe-del-estado-mayor-conjunto-participa-en-la-gran-parada-militar\/","title":{"rendered":"Jefe del Estado Mayor Conjunto participa en la Gran Parada Militar"},"content":{"rendered":"<p>Vicealmirante Jos\u00e9 Miguel Romero, Jefe del Estado Mayor Conjunto participa en la \u201cGran Parada Militar\u201d en conmemoraci\u00f3n de las Glorias del Ej\u00e9rcito, tradici\u00f3n republicana de nuestro pa\u00eds.<\/p>\n<p>El Jefe del Estado Mayor Conjunto es quien por disposici\u00f3n presidencial, asume el mando y conducci\u00f3n estrat\u00e9gica de los medios de defensa durante estados de excepci\u00f3n constitucional y en particular, en casos de guerra externa o crisis internacional que afecte la seguridad exterior de la Rep\u00fablica. Asimismo, el Estado Mayor Conjunto act\u00faa como organismo de trabajo y asesor\u00eda permanente del Ministerio de Defensa Nacional en materias que tengan relaci\u00f3n con la preparaci\u00f3n y empleo conjunto de las Fuerzas Armadas.&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Vicealmirante Jos\u00e9 Miguel Romero, Jefe del Estado Mayor Conjunto participa en la \u201cGran Parada Militar\u201d en conmemoraci\u00f3n de las Glorias del Ej\u00e9rcito, tradici\u00f3n republicana de nuestro pa\u00eds. El Jefe del Estado Mayor Conjunto es quien por disposici\u00f3n presidencial, asume el mando y conducci\u00f3n estrat\u00e9gica de los medios de defensa durante estados de excepci\u00f3n constitucional y&#8230;<\/p>\n","protected":false},"author":6,"featured_media":5823,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"footnotes":""},"categories":[26,3],"tags":[],"class_list":["post-6900","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-26","category-noticias"],"_links":{"self":[{"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/posts\/6900","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/comments?post=6900"}],"version-history":[{"count":2,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/posts\/6900\/revisions"}],"predecessor-version":[{"id":7043,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/posts\/6900\/revisions\/7043"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/media\/5823"}],"wp:attachment":[{"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/media?parent=6900"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/categories?post=6900"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/tags?post=6900"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}