{"id":6886,"date":"2014-06-19T15:04:49","date_gmt":"2014-06-19T15:04:49","guid":{"rendered":"http:\/\/www.emco.mil.cl\/?p=857"},"modified":"2021-09-29T12:16:00","modified_gmt":"2021-09-29T15:16:00","slug":"comando-conjunto-austral-realizo-seminario-de-emergencias-y-catastrofes","status":"publish","type":"post","link":"https:\/\/www.emco.mil.cl\/index.php\/2014\/06\/19\/comando-conjunto-austral-realizo-seminario-de-emergencias-y-catastrofes\/","title":{"rendered":"Comando Conjunto Austral realiz\u00f3 seminario de Emergencias y Cat\u00e1strofes"},"content":{"rendered":"<p>Con el fin de estar entrenados ante una posible cat\u00e1strofe en la Regi\u00f3n de Magallanes, el Comando Conjunto Austral realiz\u00f3 el seminario \u201cCapacidades y Planes para enfrentar una Emergencia\u201d.<\/p>\n<p>El tema central estuvo enfocado en obtener informaci\u00f3n actualizada sobre aquellas lecciones aprendidas de las \u00faltimas cat\u00e1strofes y\/o emergencias a nivel nacional y regional, y las capacidades de respuesta con las que cuentan las diferentes instituciones gubernamentales, civiles y de las Fuerzas Armadas de la regi\u00f3n de Magallanes y Ant\u00e1rtica Chilena.<\/p>\n<p>Asimismo, sobre el Centro de Operaciones de Defensa, unidad coordinadora para las actividades de emergencia, exposici\u00f3n que estuvo a cargo del Subjefe del Estado Mayor Conjunto, General de Divisi\u00f3n Ricardo Mart\u00ednez Menanteau; y la experiencia obtenida en el terremoto de este a\u00f1o en la zona norte, exposici\u00f3n que estuvo a cargo del Comando Conjunto Norte.<\/p>\n<p>La actividad, cont\u00f3 con la participaci\u00f3n del Intendente de la regi\u00f3n de Magallanes y Ant\u00e1rtica Chilena, Jorge Flies A\u00f1on, representantes der las Fuerzas Armadas, el Jefe de la XII Zona de Carabineros, directores provinciales de emergencia y encargados de emergencia de las municipalidades, representantes del gobierno regional y de la Universidad de Magallanes, adem\u00e1s de organismos de emergencia civiles.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Con el fin de estar entrenados ante una posible cat\u00e1strofe en la Regi\u00f3n de Magallanes, el Comando Conjunto Austral realiz\u00f3 el seminario \u201cCapacidades y Planes para enfrentar una Emergencia\u201d. El tema central estuvo enfocado en obtener informaci\u00f3n actualizada sobre aquellas lecciones aprendidas de las \u00faltimas cat\u00e1strofes y\/o emergencias a nivel nacional y regional, y las&#8230;<\/p>\n","protected":false},"author":6,"featured_media":5823,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"footnotes":""},"categories":[26,3],"tags":[],"class_list":["post-6886","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-26","category-noticias"],"_links":{"self":[{"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/posts\/6886","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/comments?post=6886"}],"version-history":[{"count":2,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/posts\/6886\/revisions"}],"predecessor-version":[{"id":7065,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/posts\/6886\/revisions\/7065"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/media\/5823"}],"wp:attachment":[{"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/media?parent=6886"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/categories?post=6886"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/tags?post=6886"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}