{"id":6641,"date":"2015-09-04T16:04:17","date_gmt":"2015-09-04T16:04:17","guid":{"rendered":"http:\/\/www.emco.mil.cl\/?p=1614"},"modified":"2021-09-29T10:34:13","modified_gmt":"2021-09-29T13:34:13","slug":"fuerza-chilena-participa-de-ceremonia-por-fallecimiento-del-force-commander-de-la-minustah-en-haiti","status":"publish","type":"post","link":"https:\/\/www.emco.mil.cl\/index.php\/2015\/09\/04\/fuerza-chilena-participa-de-ceremonia-por-fallecimiento-del-force-commander-de-la-minustah-en-haiti\/","title":{"rendered":"Fuerza chilena participa de ceremonia por fallecimiento del Force Commander de la Minustah en Hait\u00ed"},"content":{"rendered":"<p>Delegaciones de todas las unidades militares presentes en Hait\u00ed, incluida la chilena, estuvieron presentes en la ceremonia de despedida del General Jose Luiz Jaborany Jr. (1958-2015), quien fuera Force Commander de las Naciones Unidas en ese pa\u00eds caribe\u00f1o desde marzo de 2014 hasta su deceso, el 30 de agosto reci\u00e9n pasado.<\/p>\n<p>El homenaje se inici\u00f3 con la llegada de los restos General Jaborandy (Q.E.P.D.) y su familia, encabezada por su esposa, Lilian Maria Henriques Jaborandy, en un avi\u00f3n H\u00e9rcules de la Fuerza A\u00e9rea brasile\u00f1a, siendo trasladado sobre hombros de oficiales de su staff, entre los que iba el Teniente Coronel Alejandro Zuleta, Oficial Log\u00edstico chileno de la MINUSTAH, hasta un hangar donde formaban efectivos del Ej\u00e9rcito y la Armada integrantes del Batall\u00f3n Chile, y del Grupo de Helic\u00f3pteros de la Fuerza A\u00e9rea de Chile, encabezados por sus respectivos comandantes.<\/p>\n<p>En el marco de la ceremonia, el Embajador de nuestro pa\u00eds Ra\u00fal Fern\u00e1ndez, entreg\u00f3 las condolencias y el p\u00e9same a nombre del Gobierno, seguido por el C\u00f3nsul de Chile en Hait\u00ed V\u00edctor Hugo Mu\u00f1oz y el Agregado de Defensa, Coronel Enrique B\u00f6decker.<\/p>\n<p>Asimismo, durante la jornada el Deputy Force Commander, el General de Brigada Jorge Pe\u00f1a, expres\u00f3 los sentimientos de toda la familia militar. Con emotivas palabras calific\u00f3 al General Jaborandy J\u00fanior como un <i>\u00abhombre feliz\u00bb<\/i> y <i>\u00abrealizado\u00bb<\/i>, que <i>\u00abtrascendi\u00f3, porque logr\u00f3 consolidar una exitosa profesi\u00f3n militar\u00bb<\/i>, <i>\u00abporque form\u00f3 una hermosa familia<\/i> (&#8230;), <i>y porque irradi\u00f3 su carisma en las personas con las que trabajaba, se relacionaba y compart\u00eda una gran calidez humana\u00bb<\/i>. Otra de las caracter\u00edsticas que destac\u00f3 fue su gran sensibilidad a lo que ocurr\u00eda con las personas, y en forma particular, con la tropa. Adem\u00e1s, porque era decidido, arriesgado y con car\u00e1cter cuando se requer\u00eda, y porque <i>\u00ablograba crear un muy grato ambiente de trabajo. Porque manten\u00eda a su grupo unido\u00bb<\/i>. Finalmente, pidi\u00f3 como tributo <i>\u00abmantener su m\u00edstica, su deseo de unidad, de familia, de nuestra responsabilidad con nuestra tarea de paz, y continuar con esta misi\u00f3n con el mayor profesionalismo posible, mientas la comunidad internacional as\u00ed lo decida. (&#8230;) Creo que la llama y los ideales de un gran l\u00edder nunca debemos dejar que se apaguen, <\/i>se\u00f1al\u00f3.<\/p>\n<p>A continuaci\u00f3n hablaron a los presentes un representante del gobierno de Brasil, el ministro de Asuntos Exteriores y Defensa de Hait\u00ed, Lener Renaud, y la Representante Especial del Secretario General de las Naciones Unidas, Sandra Honor\u00e9. Esta \u00faltima anunci\u00f3 que la m\u00e1xima autoridad de la ONU, Ban Ki-moon decidi\u00f3 conceder al General Jaborandy Jr., en forma p\u00f3stuma, la Medalla de las Naciones Unidas por el Mantenimiento de la Paz. <i>\u00abNunca una condecoraci\u00f3n fue m\u00e1s merecida\u00bb, <\/i>afirm\u00f3 Honor\u00e9. Dicho reconocimiento fue entregado a la viuda del Force Commander, el Presidente de Haiti, Michel Martelly.<\/p>\n<p>Cabe se\u00f1alar que mientras se designe al reemplazante del fallecido Force Commander, se desempe\u00f1ar\u00e1 en el cargo, en forma interina, el General Jorge Pe\u00f1a, teniendo la responsabilidad de dirigir a los casi dos mil 400 cascos azules desplegados en este pa\u00eds.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Delegaciones de todas las unidades militares presentes en Hait\u00ed, incluida la chilena, estuvieron presentes en la ceremonia de despedida del General Jose Luiz Jaborany Jr. (1958-2015), quien fuera Force Commander de las Naciones Unidas en ese pa\u00eds caribe\u00f1o desde marzo de 2014 hasta su deceso, el 30 de agosto reci\u00e9n pasado. El homenaje se inici\u00f3&#8230;<\/p>\n","protected":false},"author":6,"featured_media":5823,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"footnotes":""},"categories":[24,3],"tags":[],"class_list":["post-6641","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-24","category-noticias"],"_links":{"self":[{"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/posts\/6641","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/comments?post=6641"}],"version-history":[{"count":2,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/posts\/6641\/revisions"}],"predecessor-version":[{"id":6798,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/posts\/6641\/revisions\/6798"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/media\/5823"}],"wp:attachment":[{"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/media?parent=6641"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/categories?post=6641"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/tags?post=6641"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}