{"id":6638,"date":"2015-08-29T01:57:31","date_gmt":"2015-08-29T01:57:31","guid":{"rendered":"http:\/\/www.emco.mil.cl\/?p=1601"},"modified":"2021-09-29T10:37:37","modified_gmt":"2021-09-29T13:37:37","slug":"secretario-general-de-unasur-realiza-visita-al-centro-conjunto-para-operaciones-de-paz","status":"publish","type":"post","link":"https:\/\/www.emco.mil.cl\/index.php\/2015\/08\/29\/secretario-general-de-unasur-realiza-visita-al-centro-conjunto-para-operaciones-de-paz\/","title":{"rendered":"Secretario General de UNASUR realiza visita al Centro Conjunto para Operaciones de Paz"},"content":{"rendered":"<p>En el marco de una gira de trabajo por Argentina, Chile y Uruguay, el Secretario General de la Uni\u00f3n de Naciones Suramericanas, UNASUR, y ex presidente colombiano, Ernesto Samper Pizano, efectu\u00f3 una visita al Centro Conjunto para Operaciones de Paz, CECOPAC.<\/p>\n<p>Tras ser recibido por el director del organismo, Teniente Coronel Paulo Mu\u00f1oz, la autoridad particip\u00f3 de una exposici\u00f3n donde se le dio a conocer respecto de la participaci\u00f3n de Chile en misiones de Paz, como tambi\u00e9n respecto al papel del CECOPAC en materia de preparaci\u00f3n de los efectivos destinados a estas operaciones.<\/p>\n<p>UNASUR es un organismo internacional, conformado por los doce pa\u00edses de la regi\u00f3n suramericana: Argentina, Bolivia, Brasil, Colombia, Chile, Ecuador, Guyana, Paraguay, Per\u00fa, Suriname, Uruguay y Venezuela, que tiene como objetivo construir un espacio de integraci\u00f3n en lo cultural, econ\u00f3mico, social y pol\u00edtico, respetando la realidad de cada naci\u00f3n, de manera de eliminar la desigualdad socio econ\u00f3mica, alcanzar la inclusi\u00f3n social, aumentar la participaci\u00f3n ciudadana, fortalecer la democracia y reducir las asimetr\u00edas existentes.&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En el marco de una gira de trabajo por Argentina, Chile y Uruguay, el Secretario General de la Uni\u00f3n de Naciones Suramericanas, UNASUR, y ex presidente colombiano, Ernesto Samper Pizano, efectu\u00f3 una visita al Centro Conjunto para Operaciones de Paz, CECOPAC. Tras ser recibido por el director del organismo, Teniente Coronel Paulo Mu\u00f1oz, la autoridad&#8230;<\/p>\n","protected":false},"author":6,"featured_media":5823,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"footnotes":""},"categories":[24,3],"tags":[],"class_list":["post-6638","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-24","category-noticias"],"_links":{"self":[{"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/posts\/6638","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/comments?post=6638"}],"version-history":[{"count":2,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/posts\/6638\/revisions"}],"predecessor-version":[{"id":6801,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/posts\/6638\/revisions\/6801"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/media\/5823"}],"wp:attachment":[{"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/media?parent=6638"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/categories?post=6638"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/tags?post=6638"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}