{"id":6600,"date":"2015-04-01T04:57:07","date_gmt":"2015-04-01T04:57:07","guid":{"rendered":"http:\/\/www.emco.mil.cl\/?p=1348"},"modified":"2021-09-29T11:10:38","modified_gmt":"2021-09-29T14:10:38","slug":"estado-mayor-conjunto-y-subsecretaria-de-defensa-mano-a-mano-en-la-entrega-de-ayuda","status":"publish","type":"post","link":"https:\/\/www.emco.mil.cl\/index.php\/2015\/04\/01\/estado-mayor-conjunto-y-subsecretaria-de-defensa-mano-a-mano-en-la-entrega-de-ayuda\/","title":{"rendered":"Estado Mayor Conjunto y Subsecretar\u00eda de Defensa: mano a mano en la entrega de ayuda"},"content":{"rendered":"<p>Durante la tarde, helic\u00f3pteros Cougar del Ej\u00e9rcito fueron los encargados de facilitar la llegada de ayuda humanitaria desde Copiap\u00f3 a San F\u00e9lix, comuna de Alto del Carmen, permitiendo as\u00ed retomar la conexi\u00f3n con el sector. Ayuda que fue directamente entregada por el Subsecretario de Defensa Marcos Robledo, quien acudi\u00f3 a la localidad acompa\u00f1ado por el Subjefe del Estado Mayor Conjunto, General Ricardo Mart\u00ednez Menanteau, autoridades que no dudaron sumarse a quienes deb\u00edan realizar la descarga de ayuda.&nbsp;<\/p>\n<p>138 efectivos del Regimiento de Infanter\u00eda de Coquimbo y del Cuerpo de Ingenieros del Ej\u00e9rcito est\u00e1n desplegados en la comuna de Alto del Carmen, fuerza que ser\u00e1 reforzada con 98 efectivos m\u00e1s provenientes del Regimiento Chacabuco.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Durante la tarde, helic\u00f3pteros Cougar del Ej\u00e9rcito fueron los encargados de facilitar la llegada de ayuda humanitaria desde Copiap\u00f3 a San F\u00e9lix, comuna de Alto del Carmen, permitiendo as\u00ed retomar la conexi\u00f3n con el sector. Ayuda que fue directamente entregada por el Subsecretario de Defensa Marcos Robledo, quien acudi\u00f3 a la localidad acompa\u00f1ado por el&#8230;<\/p>\n","protected":false},"author":6,"featured_media":5823,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"footnotes":""},"categories":[24,3],"tags":[],"class_list":["post-6600","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-24","category-noticias"],"_links":{"self":[{"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/posts\/6600","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/comments?post=6600"}],"version-history":[{"count":2,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/posts\/6600\/revisions"}],"predecessor-version":[{"id":6848,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/posts\/6600\/revisions\/6848"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/media\/5823"}],"wp:attachment":[{"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/media?parent=6600"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/categories?post=6600"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/tags?post=6600"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}