{"id":649,"date":"2014-02-24T17:33:35","date_gmt":"2014-02-24T17:33:35","guid":{"rendered":"http:\/\/www.emco.mil.cl\/?p=649"},"modified":"2021-09-29T12:26:27","modified_gmt":"2021-09-29T15:26:27","slug":"vicealmirante-romero-participa-en-conmemoracion-del-dia-del-brigadista-forestal","status":"publish","type":"post","link":"https:\/\/www.emco.mil.cl\/index.php\/2014\/02\/24\/vicealmirante-romero-participa-en-conmemoracion-del-dia-del-brigadista-forestal\/","title":{"rendered":"JEMCO participa en conmemoraci\u00f3n del D\u00eda del Brigadista Forestal"},"content":{"rendered":"<p>Con el fin de destacar su labor, luego que el Gobierno declarara el \u201cD\u00eda Nacional del Brigadista Forestal\u201d, y de realizar un reconocimiento a&nbsp; las &nbsp;instituciones que participan&nbsp; en la prevenci\u00f3n y combate de incendios forestales, entre ellas las Fuerzas Armadas de nuestro pa\u00eds,&nbsp; la Corporaci\u00f3n Nacional Forestal, CONAF realiz\u00f3 esta ma\u00f1ana una ceremonia en el Centro de Educaci\u00f3n Ambiental Bosque Santiago del Parque Metropolitano, en la comuna de Huechuraba.<\/p>\n<p>La actividad cont\u00f3 con la participaci\u00f3n del Jefe del Estado Mayor Conjunto (JEMCO), Vicealmirante Jos\u00e9 Miguel Romero, quien estuvo junto al Ministro de Agricultura Luis Mayol Bouchon y el Intendente Metropolitano Juan Antonio Peribonio, adem\u00e1s de representantes de las Fuerzas Armadas, Carabineros, la PDI y Bomberos, entre otros.<\/p>\n<p>La fecha de conmemoraci\u00f3n fue elegida como una forma de recordar a los \u00faltimos ca\u00eddos en esta actividad, los 12 brigadistas forestales fallecidos al precipitarse un helic\u00f3ptero cuando combat\u00edan un incendio forestal en Chanco, cercano a Cauquenes, en la Regi\u00f3n del Maule, el a\u00f1o 2009.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Con el fin de destacar su labor, luego que el Gobierno declarara el \u201cD\u00eda Nacional del Brigadista Forestal\u201d, y de realizar un reconocimiento a&nbsp; las &nbsp;instituciones que participan&nbsp; en la prevenci\u00f3n y combate de incendios forestales, entre ellas las Fuerzas Armadas de nuestro pa\u00eds,&nbsp; la Corporaci\u00f3n Nacional Forestal, CONAF realiz\u00f3 esta ma\u00f1ana una ceremonia en&#8230;<\/p>\n","protected":false},"author":6,"featured_media":5823,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"footnotes":""},"categories":[26,3],"tags":[],"class_list":["post-649","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-26","category-noticias"],"_links":{"self":[{"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/posts\/649","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/comments?post=649"}],"version-history":[{"count":2,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/posts\/649\/revisions"}],"predecessor-version":[{"id":7092,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/posts\/649\/revisions\/7092"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/media\/5823"}],"wp:attachment":[{"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/media?parent=649"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/categories?post=649"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/tags?post=649"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}