{"id":5998,"date":"2018-08-27T17:42:50","date_gmt":"2018-08-27T17:42:50","guid":{"rendered":"http:\/\/www.emco.mil.cl\/?p=3838"},"modified":"2021-09-28T16:26:08","modified_gmt":"2021-09-28T19:26:08","slug":"autoridades-de-defensa-inspeccionan-el-ejercicio-estrella-austral-2018","status":"publish","type":"post","link":"https:\/\/www.emco.mil.cl\/index.php\/2018\/08\/27\/autoridades-de-defensa-inspeccionan-el-ejercicio-estrella-austral-2018\/","title":{"rendered":"Autoridades de Defensa inspeccionan el Ejercicio Estrella Austral 2018"},"content":{"rendered":"<p>Hasta la 3ra Brigada Acorazada \u201cLa Concepci\u00f3n\u201d, en la regi\u00f3n de Antofagasta, viaj\u00f3 el Ministro de Defensa Nacional, Alberto Espina Otero, junto al Jefe del Estado Mayor Conjunto, General de Aviaci\u00f3n Arturo Merino N\u00fa\u00f1ez y los Comandantes en Jefe del Ej\u00e9rcito, Armada y Fuerza A\u00e9rea, para efectuar una revista operacional del Ejercicio Conjunto Combinado \u201cEstrella Austral\u201d 2018, dirigido por el Estado Mayor Conjunto.<\/p>\n<p><a href=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/Autoridades.jpg\"><img fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter size-full wp-image-3839\" src=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/Autoridades.jpg\" alt=\"Autoridades\" width=\"620\" height=\"413\"><\/a><\/p>\n<p>El ministro presenci\u00f3 un <em>briefing <\/em>sobre el ejercicio, en donde tanto el Jefe del Estado Mayor Conjunto, General Merino, como el General de Brigada Pablo M\u00fcller Barber\u00eda, explicaron el despliegue de la Fuerza de Tarea de Operaciones Especiales Conjunta Combinada en Calama y Antofagasta.<\/p>\n<p>A continuaci\u00f3n, las autoridades fueron trasladadas para observar la acci\u00f3n directa de una unidad de Fuerzas Especiales del Ej\u00e9rcito en la eliminaci\u00f3n de objetivo de alto valor con helic\u00f3pteros y veh\u00edculos terrestres y otra unidad de Fuerzas Especiales de la Fuerza A\u00e9rea, en un guiado terminal de blindados con empleo de aviones de combate, donde tambi\u00e9n participaron Fuerzas Especiales integradas del Ej\u00e9rcito y Fuerza A\u00e9rea de EE.UU. Para luego, dirigirse al Puerto de Mejillones, donde presenciaron el despliegue de una unidad de Fuerzas Especiales de la Armada en el abordaje de un buque de superficie con empleo de helic\u00f3pteros, lanchas y Buque Patrullaje mar\u00edtimo, con fuerzas integradas navales de Estados Unidos.<\/p>\n<p><a href=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/ejercicio-1.jpg\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-3842\" src=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/ejercicio-1.jpg\" alt=\"ejercicio 1\" width=\"620\" height=\"413\"><\/a><\/p>\n<p><a href=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/ejercicio-2.jpg\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-3843\" src=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/ejercicio-2.jpg\" alt=\"ejercicio 2\" width=\"620\" height=\"413\"><\/a><\/p>\n<p><strong><em>\u201cEste es uno de los ejercicios m\u00e1s importantes de la regi\u00f3n, es un ejercicio de Fuerzas Especiales, en donde participa el Ej\u00e9rcito, Armada y Fuerza A\u00e9rea de Chile, adem\u00e1s de Fuerzas Especiales de los Estados Unidos. Es una tremenda experiencia el poder compartir con otros pa\u00edses, es uno de los objetivos que persigue este ejercicio, aprender c\u00f3mo lo est\u00e1n haciendo otras Fuerzas Especiales en el mundo y que Estados Unidos est\u00e9 a la par operando con nosotros en terreno t\u00e1ctico, operacional y estrat\u00e9gico, es un orgullo para las Fuerzas Especiales de este pa\u00eds<\/em><\/strong>\u201d, coment\u00f3 el General Merino.<\/p>\n<p><a href=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/Autoridades-1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-3840\" src=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/Autoridades-1.jpg\" alt=\"Autoridades 1\" width=\"620\" height=\"413\"><\/a><\/p>\n<p>Este ejercicio, comenz\u00f3 a partir del a\u00f1o 2007, a trav\u00e9s de un acuerdo bilateral entre las Fuerzas Especiales de EE.UU. y Chile, y est\u00e1 basado en un entrenamiento de Fuerzas de Operaciones Especiales, en el marco de una situaci\u00f3n ficticia de imposici\u00f3n de la paz, que permite que nuestras Fuerzas ejecuten operaciones que incrementen la interoperabilidad conjunta y combinada, tales como acci\u00f3n directa, operaciones de rescate, de informaci\u00f3n y asistencia militar, entre otros.<\/p>\n<p><a href=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/Autoridades-2.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-3841\" src=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/Autoridades-2.jpg\" alt=\"Autoridades 2\" width=\"620\" height=\"413\"><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hasta la 3ra Brigada Acorazada \u201cLa Concepci\u00f3n\u201d, en la regi\u00f3n de Antofagasta, viaj\u00f3 el Ministro de Defensa Nacional, Alberto Espina Otero, junto al Jefe del Estado Mayor Conjunto, General de Aviaci\u00f3n Arturo Merino N\u00fa\u00f1ez y los Comandantes en Jefe del Ej\u00e9rcito, Armada y Fuerza A\u00e9rea, para efectuar una revista operacional del Ejercicio Conjunto Combinado \u201cEstrella&#8230;<\/p>\n","protected":false},"author":4,"featured_media":5823,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"footnotes":""},"categories":[17,3],"tags":[],"class_list":["post-5998","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-17","category-noticias"],"_links":{"self":[{"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/posts\/5998","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/comments?post=5998"}],"version-history":[{"count":1,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/posts\/5998\/revisions"}],"predecessor-version":[{"id":6165,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/posts\/5998\/revisions\/6165"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/media\/5823"}],"wp:attachment":[{"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/media?parent=5998"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/categories?post=5998"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/tags?post=5998"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}