{"id":5732,"date":"2020-12-15T14:06:18","date_gmt":"2020-12-15T17:06:18","guid":{"rendered":"https:\/\/www.emco.mil.cl\/?p=5732"},"modified":"2021-09-28T10:27:11","modified_gmt":"2021-09-28T13:27:11","slug":"cambio-de-mando-del-comando-conjunto-austral-3","status":"publish","type":"post","link":"https:\/\/www.emco.mil.cl\/index.php\/2020\/12\/15\/cambio-de-mando-del-comando-conjunto-austral-3\/","title":{"rendered":"Cambio de mando del Comando Conjunto Austral"},"content":{"rendered":"\n<p>El lunes 14 de diciembre, en Punta Arenas, se llev\u00f3 a cabo el cambio de mando del Comando Conjunto Austral, alta repartici\u00f3n ministerial dependiente del Estado Mayor Conjunto, actividad donde General de Divisi\u00f3n Rodrigo Ventura Sancho, le entreg\u00f3 el mando al General de Brigada Sergio Est\u00e9vez Valencia, ceremonia que estuvo presidida por el Subjefe del Estado Mayor Conjunto, General de Brigada A\u00e9rea Jean Pierre Desgroux Ycaza.<\/p>\n\n\n\n<div class=\"wp-block-image is-style-default\"><figure class=\"aligncenter\"><a href=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2-129.jpg\"><img decoding=\"async\" src=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2-129.jpg\" alt=\"2\" class=\"wp-image-5735\"\/><\/a><\/figure><\/div>\n\n\n\n<p>El GDD Ventura fue el Comandante del Comando Conjunto Austral desde diciembre de 2019, donde tambi\u00e9n cumpli\u00f3 con la labor de Jefe de la Defensa Nacional de Magallanes y Ant\u00e1rtica Chilena por el Estado de Excepci\u00f3n Constitucional de Cat\u00e1strofe por la pandemia por el Covid-19. El General Ventura asumir\u00e1 como Comandante de Apoyo a la Fuerza del Ej\u00e9rcito de Chile.<\/p>\n\n\n\n<p>Por otro lado, el General Est\u00e9vez tambi\u00e9n asumir\u00e1 el cargo de Comandante en Jefe de la V Divisi\u00f3n de Ej\u00e9rcito, aparte de ser el Comandante del Comando Conjunto Austral, donde cumplir\u00e1 la misi\u00f3n de Jefe de la Defensa Nacional de la regi\u00f3n el tiempo que est\u00e9 vigente el Estado de Excepci\u00f3n Constitucional.<\/p>\n\n\n\n<div class=\"wp-block-image is-style-default\"><figure class=\"aligncenter\"><a href=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/1-133.jpg\"><img decoding=\"async\" src=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/1-133.jpg\" alt=\"1\" class=\"wp-image-5734\"\/><\/a><\/figure><\/div>\n","protected":false},"excerpt":{"rendered":"<p>El lunes 14 de diciembre, en Punta Arenas, se llev\u00f3 a cabo el cambio de mando del Comando Conjunto Austral, alta repartici\u00f3n ministerial dependiente del Estado Mayor Conjunto, actividad donde General de Divisi\u00f3n Rodrigo Ventura Sancho, le entreg\u00f3 el mando al General de Brigada Sergio Est\u00e9vez Valencia, ceremonia que estuvo presidida por el Subjefe del&#8230;<\/p>\n","protected":false},"author":5,"featured_media":5823,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"footnotes":""},"categories":[11,3],"tags":[],"class_list":["post-5732","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-11","category-noticias"],"_links":{"self":[{"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/posts\/5732","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/comments?post=5732"}],"version-history":[{"count":2,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/posts\/5732\/revisions"}],"predecessor-version":[{"id":5827,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/posts\/5732\/revisions\/5827"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/media\/5823"}],"wp:attachment":[{"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/media?parent=5732"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/categories?post=5732"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/tags?post=5732"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}