{"id":55,"date":"2013-07-01T21:46:39","date_gmt":"2013-07-01T21:46:39","guid":{"rendered":"http:\/\/www.emc.mil.cl\/nemc\/?p=55"},"modified":"2021-09-29T14:31:41","modified_gmt":"2021-09-29T17:31:41","slug":"jemco-asiste-a-cambio-de-mando-de-la-presidencia-de-la-jid","status":"publish","type":"post","link":"https:\/\/www.emco.mil.cl\/index.php\/2013\/07\/01\/jemco-asiste-a-cambio-de-mando-de-la-presidencia-de-la-jid\/","title":{"rendered":"JEMCO asiste a cambio de mando de la presidencia de la JID"},"content":{"rendered":"<p><img decoding=\"async\" class=\"aligncenter\" src=\"https:\/\/www.emco.mil.cl\/\/wp-content\/uploads\/01-julio-2013-JEMCO-asiste-a-cambio-de-mando-de-la-presidencia-de-la-JID.jpg\" \/><br \/>\nEl Jefe del Estado Mayor Conjunto, General de Divisi\u00f3n Hern\u00e1n Mardones R\u00edos, asisti\u00f3 este 28 de junio a la ceremonia de cambio de mando de la Presidencia de la Junta Interamericana de Defensa (JID), oportunidad en la que asumi\u00f3 el General de Divisi\u00f3n Werther Araya Menghini, perteneciente al Ej\u00e9rcito de Chile.<br \/>\nA los 71 a\u00f1os de la creaci\u00f3n de la JID de la OEA, por primera vez tendr\u00e1 un Presiente chileno en su Consejo de Delegados, lo que es motivo de orgullo para las Fuerzas Armadas de nuestro pa\u00eds.<br \/>\nDentro de las tem\u00e1ticas que deber\u00e1 abordar el General Araya se destaca la generaci\u00f3n de respuestas ante cat\u00e1strofes naturales, desminado humanitario y amenazas emergentes.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Jefe del Estado Mayor Conjunto, General de Divisi\u00f3n Hern\u00e1n Mardones R\u00edos, asisti\u00f3 este 28 de junio a la ceremonia de cambio de mando de la Presidencia de la Junta Interamericana de Defensa (JID), oportunidad en la que asumi\u00f3 el General de Divisi\u00f3n Werther Araya Menghini, perteneciente al Ej\u00e9rcito de Chile. A los 71 a\u00f1os&#8230;<\/p>\n","protected":false},"author":5,"featured_media":5823,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"footnotes":""},"categories":[28,3],"tags":[],"class_list":["post-55","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-28","category-noticias"],"_links":{"self":[{"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/posts\/55","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/comments?post=55"}],"version-history":[{"count":2,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/posts\/55\/revisions"}],"predecessor-version":[{"id":7183,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/posts\/55\/revisions\/7183"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/media\/5823"}],"wp:attachment":[{"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/media?parent=55"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/categories?post=55"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/tags?post=55"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}