{"id":5409,"date":"2020-04-03T14:43:36","date_gmt":"2020-04-03T17:43:36","guid":{"rendered":"https:\/\/www.emco.mil.cl\/?p=5409"},"modified":"2021-09-28T10:44:42","modified_gmt":"2021-09-28T13:44:42","slug":"la-labor-de-las-fuerzas-armadas-ante-la-emergencia-sanitaria-covid-19","status":"publish","type":"post","link":"https:\/\/www.emco.mil.cl\/index.php\/2020\/04\/03\/la-labor-de-las-fuerzas-armadas-ante-la-emergencia-sanitaria-covid-19\/","title":{"rendered":"La labor de las Fuerzas Armadas ante la emergencia sanitaria COVID \u2013 19"},"content":{"rendered":"<p><span style=\"font-size: 10pt; color: #000000;\">En el marco del Estado de Excepci\u00f3n, las Fuerzas Armadas han efectuado una serie de tareas en apoyo a la autoridad civil, con el objetivo de frenar el contagio frente actual emergencia sanitaria.<\/span><\/p>\n<p><span style=\"font-size: 10pt; color: #000000;\"><strong>Colaboraci\u00f3n con las autoridades sanitarias <\/strong><\/span><\/p>\n<p><span style=\"font-size: 10pt; color: #000000;\">Las FF.AA. han desplegado personal en aduanas y cordones sanitarios en distintas zonas del pa\u00eds para ayudar a evitar la expansi\u00f3n del brote epid\u00e9mico del Coronavirus Covid-19.<\/span><\/p>\n<p><span style=\"font-size: 10pt; color: #000000;\">Las aduanas sanitarias son recintos de control obligatorio para todos quienes desean ingresar a una de las regiones que se encuentran en cuarentena. Son m\u00f3dulos habilitados por las Seremis de Salud y cuentan con personal de atenci\u00f3n del organismo, con el resguardo y apoyo de las Fuerzas Armadas.<\/span><\/p>\n<p><span style=\"font-size: 10pt; color: #000000;\">Los cordones sanitarios, implican la prohibici\u00f3n de entrada o salida de la ciudad o regi\u00f3n que se encuentra bajo este r\u00e9gimen. Solo las personas con salvoconducto, podr\u00e1n ingresar y salir de estas zonas. Sin embargo, todos deber\u00e1n someterse a un control de temperatura que detecta casos sospechosos del virus.<\/span><\/p>\n<p><span style=\"font-size: 10pt; color: #000000;\">El control ejecutado por los uniformados se ha realizado tanto en las fronteras internacionales, como dentro del territorio nacional de manera de resguardar a la poblaci\u00f3n de nuevos contagios, adem\u00e1s de mantener la continuidad de la cadena de distribuci\u00f3n log\u00edstica.<\/span><\/p>\n<p><a href=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/678-2.jpg\"><img fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter size-full wp-image-5422\" src=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/678-2.jpg\" alt=\"678\" width=\"620\" height=\"413\"><\/a><\/p>\n<p><span style=\"font-size: 10pt; color: #000000;\">Las instituciones de la Defensa Nacional tambi\u00e9n han colaborado sanitizando instalaciones estrat\u00e9gica como son los aeropuertos Diego Aracena en Iquique y Balmaceda en Ays\u00e9n.<\/span><\/p>\n<p><span style=\"font-size: 10pt; color: #000000;\">El Ej\u00e9rcito de Chile ha desplegado Puestos de Atenci\u00f3n M\u00e9dica Especializada (PAME) para reforzar los servicios de urgencia de recintos asistenciales en el Hospital Regional Dr. Ernesto Torres Galdames, en Iquique e instal\u00f3 el PAME en el Hospital Herminda Mart\u00edn, en Chill\u00e1n, para ayudar y descongestionar la demanda de atenci\u00f3n de salud en la zona.<\/span><\/p>\n<p><span style=\"font-size: 10pt; color: #000000;\">Asimismo, se implementaron tres m\u00f3dulos de evaluaci\u00f3n ambulatoria en el estacionamiento de la urgencia del Hospital San Jos\u00e9, en Santiago, que apoyar\u00e1 a la evaluaci\u00f3n de pacientes con sospecha del Covid-19.<\/span><\/p>\n<p><a href=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/1-112.jpg\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-5417\" src=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/1-112.jpg\" alt=\"1\" width=\"620\" height=\"413\"><\/a><\/p>\n<p><span style=\"font-size: 10pt; color: #000000;\">La Armada participa con el Buque Multiprop\u00f3sito LSDH-91 \u201cSargento Aldea\u201d, que tiene todas las capacidades disponibles para apoyar en esta emergencia sanitaria. El buque de la Armada no cuenta con material para diagnosticar pacientes con coronavirus, sino que apoyar\u00e1 a pacientes \u201cno Covid-19\u201d, con el fin de descongestionar los servicios de salud y centros hospitalarios.<\/span><\/p>\n<p><a href=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/Sin-t\u00edtulo-1-6.jpg\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-5423\" src=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/Sin-t\u00edtulo-1-6.jpg\" alt=\"Sin t\u00edtulo-1\" width=\"620\" height=\"413\"><\/a><\/p>\n<p><span style=\"font-size: 10pt; color: #000000;\">La Fuerza A\u00e9rea ha realizado aeroevacuaciones m\u00e9dicas, destac\u00e1ndose la evacuaci\u00f3n de dos pacientes cr\u00edticos desde Rapa Nui, quienes fueron diagnosticados con neumon\u00eda, y requirieron de un complejo sistema de aislamiento y soporte vital avanzado, con un monitoreo constante entregado por el Equipo de aeroevacuaciones medicas de la Divisi\u00f3n de Sanidad Institucional.<\/span><\/p>\n<p><span style=\"font-size: 10pt; color: #000000;\">La semana pasada, a trav\u00e9s de un avi\u00f3n DHC-6 \u201cTwin Otter\u201d de dotaci\u00f3n de la III\u00aa Brigada A\u00e9rea, la FACh realiz\u00f3 una evacuaci\u00f3n desde Chait\u00e9n, a un hombre que dio Covid-19 positivo, en un operativo en d\u00f3nde tambi\u00e9n participaron especialistas del SAMU, brindando el soporte de vida al paciente para evacuarlo de manera segura.<\/span><\/p>\n<p><span style=\"font-size: 10pt; color: #000000;\">La FACh ha apoyado trasladando vacunas contra la influenza en varios puntos de Chile, as\u00ed como tambi\u00e9n utili<\/span><span style=\"font-size: 10pt; color: #000000;\">zar sus aviones para trasportar carga sanitaria, insumos hospitalarios y equipamiento de apoyo.<\/span><\/p>\n<p><a href=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/Sin-t\u00edtulo-3-2.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-5429\" src=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/Sin-t\u00edtulo-3-2.jpg\" alt=\"Sin t\u00edtulo-3\" width=\"620\" height=\"413\"><\/a><\/p>\n<p><span style=\"font-size: 10pt; color: #000000;\"><strong>Garantizar la cadena de suministros<\/strong><\/span><\/p>\n<p><span style=\"font-size: 10pt; color: #000000;\">El Ministro de Defensa Nacional, Alberto Espina Otero, inform\u00f3 que las Fuerzas Armadas, Carabineros y la Polic\u00eda de Investigaciones, habilitar\u00e1n v\u00edas exclusivas en las aduanas sanitarias para asegurar el transito r\u00e1pido y expedito de la cadena de abastecimiento y distribuci\u00f3n de alimentos a lo largo del pa\u00eds.<\/span><\/p>\n<p><span style=\"font-size: 10pt; color: #000000;\">El Ministro Espina indic\u00f3 que para la distribuci\u00f3n se necesitan medidas necesarias para la debida protecci\u00f3n y resguardo de productos de primera necesidad, destacando que <strong><em>\u201cpor esa raz\u00f3n es que nuestro compromiso es que existir\u00e1 un riguroso resguardo del abastecimiento y de la distribuci\u00f3n de alimentos\u201d.<\/em><\/strong> &nbsp;<\/span><\/p>\n<p><a href=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/f3.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-5424\" src=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/f3.jpg\" alt=\"f3\" width=\"620\" height=\"413\"><\/a><\/p>\n<p><span style=\"font-size: 10pt; color: #000000;\"><strong>Vigilancia de infraestructura cr\u00edtica<\/strong><\/span><\/p>\n<p><span style=\"font-size: 10pt; color: #000000;\">Una vez de la entrada en vigencia del Estado de Excepci\u00f3n Constitucional de Cat\u00e1strofe, el Presidente de la Rep\u00fablica, Sebasti\u00e1n Pi\u00f1era Echenique determin\u00f3 que las Fuerzas Armadas vigilaran las infraestructuras cr\u00edticas, como son los hospitales, centros de atenci\u00f3n de salud, aeropuertos, estaciones de servicio, puertos, entre otros, para el resguardo que todos los chilenos sigan teniendo servicios b\u00e1sicos en tiempos de pandemia.<\/span><\/p>\n<p><a href=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/123-11.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-5416\" src=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/123-11.jpg\" alt=\"123\" width=\"620\" height=\"413\"><\/a><\/p>\n<p><span style=\"font-size: 10pt; color: #000000;\">Es de esta manera como las FF.AA. han desplegado un n\u00famero importante de recursos humanos y materiales, apoyando a las autoridades civiles en cada rinc\u00f3n del pa\u00eds, resguardando a la poblaci\u00f3n a trav\u00e9s del mandato entregado por las instituciones de la Rep\u00fablica.&nbsp;<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>En el marco del Estado de Excepci\u00f3n, las Fuerzas Armadas han efectuado una serie de tareas en apoyo a la autoridad civil, con el objetivo de frenar el contagio frente actual emergencia sanitaria. Colaboraci\u00f3n con las autoridades sanitarias Las FF.AA. han desplegado personal en aduanas y cordones sanitarios en distintas zonas del pa\u00eds para ayudar&#8230;<\/p>\n","protected":false},"author":5,"featured_media":5823,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"footnotes":""},"categories":[11,3],"tags":[],"class_list":["post-5409","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-11","category-noticias"],"_links":{"self":[{"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/posts\/5409","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/comments?post=5409"}],"version-history":[{"count":2,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/posts\/5409\/revisions"}],"predecessor-version":[{"id":5855,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/posts\/5409\/revisions\/5855"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/media\/5823"}],"wp:attachment":[{"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/media?parent=5409"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/categories?post=5409"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/tags?post=5409"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}