{"id":5394,"date":"2020-04-02T12:20:25","date_gmt":"2020-04-02T15:20:25","guid":{"rendered":"https:\/\/www.emco.mil.cl\/?p=5394"},"modified":"2021-09-28T10:45:20","modified_gmt":"2021-09-28T13:45:20","slug":"comandante-de-la-fuerza-unficyp-revista-a-personal-chileno","status":"publish","type":"post","link":"https:\/\/www.emco.mil.cl\/index.php\/2020\/04\/02\/comandante-de-la-fuerza-unficyp-revista-a-personal-chileno\/","title":{"rendered":"Comandante de la Fuerza UNFICYP revista a personal chileno"},"content":{"rendered":"<p><span style=\"font-size: 10pt; color: #000000;\">Este martes 31 de marzo, la Comandante de la Fuerza de la Misi\u00f3n de Naciones Unidas en Chipre (UNFICYP), Mayor General Cheryl Pearce, de la Fuerza A\u00e9rea australiana, revist\u00f3 al personal de la Base de Patrulla 3 en la localidad de Kokkina (conocida con ese nombre por el lado griego) o Erenk\u00f6y (para el lado turco).<\/span><\/p>\n<p><span style=\"color: #000000;\"><a style=\"color: #000000;\" href=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/1-111.jpg\"><img fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter size-full wp-image-5395\" src=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/1-111.jpg\" alt=\"1\" width=\"620\" height=\"413\"><\/a><\/span><\/p>\n<p><span style=\"font-size: 10pt; color: #000000;\">Esta patrulla se encuentra bajo el mando del Teniente Segundo IM de la Armada de Chile, Crist\u00f3bal L\u00f3pez Troncoso, y cuenta con la participaci\u00f3n de 13 <em>peacekeepers<\/em> provenientes de Argentina, Chile y Paraguay, quienes mantienen la vigilancia constante de las fuerzas en oposici\u00f3n en la zona.<\/span><\/p>\n<p><span style=\"font-size: 10pt; color: #000000;\">Durante su visita, la General Pearce, inspeccion\u00f3 el trabajo y las funciones ejecutadas por el personal uniformado, felicitando el buen desempe\u00f1o de sus integrantes e inst\u00e1ndolos a que sigan con ese nivel de ejecuci\u00f3n.<\/span><\/p>\n<p><span style=\"color: #000000;\"><a style=\"color: #000000;\" href=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2-108.jpg\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-5397\" src=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2-108.jpg\" alt=\"2\" width=\"620\" height=\"413\"><\/a><\/span><\/p>\n<p><span style=\"font-size: 10pt; color: #000000;\">Nuestro pa\u00eds participa de esta misi\u00f3n desde el a\u00f1o 1999, con 12 uniformados, 6 representantes del Ej\u00e9rcito y 6 de la Armada, quienes junto a militares de otras naciones desarrollan labores de observaci\u00f3n y patrullaje para evitar incidentes entre las comunidades griegas y turcas.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Este martes 31 de marzo, la Comandante de la Fuerza de la Misi\u00f3n de Naciones Unidas en Chipre (UNFICYP), Mayor General Cheryl Pearce, de la Fuerza A\u00e9rea australiana, revist\u00f3 al personal de la Base de Patrulla 3 en la localidad de Kokkina (conocida con ese nombre por el lado griego) o Erenk\u00f6y (para el lado&#8230;<\/p>\n","protected":false},"author":5,"featured_media":5823,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"footnotes":""},"categories":[11,3],"tags":[],"class_list":["post-5394","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-11","category-noticias"],"_links":{"self":[{"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/posts\/5394","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/comments?post=5394"}],"version-history":[{"count":2,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/posts\/5394\/revisions"}],"predecessor-version":[{"id":5856,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/posts\/5394\/revisions\/5856"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/media\/5823"}],"wp:attachment":[{"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/media?parent=5394"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/categories?post=5394"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/tags?post=5394"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}