{"id":5083,"date":"2019-10-10T19:54:28","date_gmt":"2019-10-10T19:54:28","guid":{"rendered":"https:\/\/www.emco.mil.cl\/?p=5083"},"modified":"2021-09-28T11:29:09","modified_gmt":"2021-09-28T14:29:09","slug":"repliegue-subcomisario-de-la-pdi-de-mision-de-apoyo-a-la-justicia-de-las-naciones-unidas-en-haiti","status":"publish","type":"post","link":"https:\/\/www.emco.mil.cl\/index.php\/2019\/10\/10\/repliegue-subcomisario-de-la-pdi-de-mision-de-apoyo-a-la-justicia-de-las-naciones-unidas-en-haiti\/","title":{"rendered":"Repliegue Subcomisario de la PDI de Misi\u00f3n de Apoyo a la Justicia de las Naciones Unidas en Hait\u00ed"},"content":{"rendered":"<p style=\"text-align: justify;\"><span style=\"font-size: 10pt; color: #000000;\">En dependencias del Estado Mayor Conjunto, el Director de Operaciones y Conducci\u00f3n Conjunta (DOPCON), Contralmirante Pablo Niemann Figari, recibi\u00f3 a la Subcomisario B\u00e1rbara C\u00e1rdenas Oyarz\u00fan, quien estuvo 6 meses representando a nuestro pa\u00eds, en la Misi\u00f3n de Apoyo a la Justicia de las Naciones Unidas en Hait\u00ed (MINUJUSTH).<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 10pt; color: #000000;\"><strong><em>\u201cLo que estaba haciendo en la misi\u00f3n, era acompa\u00f1ar y asesorar a los mando medios y altos mandos de la Polic\u00eda Nacional de Hait\u00ed, orient\u00e1ndolos en la toma de decisi\u00f3n, aconsej\u00e1ndolos en los cursos seguir en determinadas investigaciones<\/em><\/strong>\u201d, dijo la Subcomisario C\u00e1rdenas.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 10pt; color: #000000;\">En cuanto a su experiencia coment\u00f3 que <strong><em>\u201cfue muy interesante poder trabajar con gente de otros pa\u00edses y principalmente de otras culturas, en mi unidad la mayor\u00eda eran de \u00c1frica y Canad\u00e1, entonces era muy distinto el d\u00eda a d\u00eda por las costumbres y las comidas, pero fue una muy buena experiencia\u201d.<\/em><\/strong><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 10pt; color: #000000;\">Con el repliegue de la Subcomisario C\u00e1rdenas, quien se desempe\u00f1\u00f3 como Polic\u00eda de Naciones Unidas (UNPOL), Chile culmina con su participaci\u00f3n en Misi\u00f3n de Apoyo a la Justicia de las Naciones Unidas en Hait\u00ed (MINUJUSTH), donde tuvo presencia uniformada desde el 2004 en pa\u00eds caribe\u00f1o.<\/span><\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/213243254.jpg\"><img fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter size-full wp-image-5084\" src=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/213243254.jpg\" alt=\"213243254\" width=\"620\" height=\"413\"><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>En dependencias del Estado Mayor Conjunto, el Director de Operaciones y Conducci\u00f3n Conjunta (DOPCON), Contralmirante Pablo Niemann Figari, recibi\u00f3 a la Subcomisario B\u00e1rbara C\u00e1rdenas Oyarz\u00fan, quien estuvo 6 meses representando a nuestro pa\u00eds, en la Misi\u00f3n de Apoyo a la Justicia de las Naciones Unidas en Hait\u00ed (MINUJUSTH). \u201cLo que estaba haciendo en la misi\u00f3n,&#8230;<\/p>\n","protected":false},"author":5,"featured_media":5823,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"footnotes":""},"categories":[15,3],"tags":[],"class_list":["post-5083","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-15","category-noticias"],"_links":{"self":[{"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/posts\/5083","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/comments?post=5083"}],"version-history":[{"count":1,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/posts\/5083\/revisions"}],"predecessor-version":[{"id":5906,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/posts\/5083\/revisions\/5906"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/media\/5823"}],"wp:attachment":[{"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/media?parent=5083"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/categories?post=5083"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/tags?post=5083"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}