{"id":4874,"date":"2019-08-14T20:03:06","date_gmt":"2019-08-14T20:03:06","guid":{"rendered":"https:\/\/www.emco.mil.cl\/?p=4874"},"modified":"2021-09-28T11:58:38","modified_gmt":"2021-09-28T14:58:38","slug":"intercambio-de-experiencias-de-operaciones-de-paz-entre-el-comando-conjunto-de-las-ff-aa-del-peru-y-el-estado-mayor-conjunto-de-chile","status":"publish","type":"post","link":"https:\/\/www.emco.mil.cl\/index.php\/2019\/08\/14\/intercambio-de-experiencias-de-operaciones-de-paz-entre-el-comando-conjunto-de-las-ff-aa-del-peru-y-el-estado-mayor-conjunto-de-chile\/","title":{"rendered":"Intercambio de experiencias de Operaciones de Paz entre el Comando Conjunto de las FF.AA. del Per\u00fa y  el Estado Mayor Conjunto de Chile"},"content":{"rendered":"<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Entre<\/span><span style=\"color: #000000; font-size: 10pt;\"> el 12 y 14 de agosto, se est\u00e1 llevando a cabo el Intercambio de experiencias de Operaciones de Paz entre el Comando Conjunto de las FF.AA. del Per\u00fa (CCFFAA) y el Estado Mayor Conjunto de Chile (EMCO). Instancia de di\u00e1logos y cooperaci\u00f3n mutua en el aprendizaje sobre las experiencias en la labor que vienen realizando los respectivos integrantes de las Fuerzas Armadas de Per\u00fa y Chile en distintas Misiones de las Naciones Unidas.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000; font-size: 10pt;\"><a style=\"color: #000000;\" href=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/12-4.jpg\"><img fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter size-full wp-image-4879\" src=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/12-4.jpg\" alt=\"12\" width=\"620\" height=\"413\"><\/a><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000; font-size: 10pt;\"><strong><em>\u201cPara nosotros el intercambio de informaci\u00f3n sobre experiencias en misiones de paz, en particular el trabajo y tiempo que lleva el contingente peruano en la Misi\u00f3n en la Rep\u00fablica Centroafricana (MINUSCA), nos entrega una distinta visi\u00f3n en los procesos log\u00edsticos y pr\u00e1cticos, lo que nos ayuda a ir perfeccionando m\u00e1s nuestra labor\u201d, <\/em><\/strong>coment\u00f3 el Jefe del Departamento II Conducci\u00f3n de Operaciones de Paz, Capit\u00e1n de Nav\u00edo (IM) Favio Santiba\u00f1ez Ortiz.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000; font-size: 10pt;\"><a style=\"color: #000000;\" href=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/3-58.jpg\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-4876\" src=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/3-58.jpg\" alt=\"3\" width=\"620\" height=\"413\"><\/a><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000; font-size: 10pt;\"><strong><em>\u201cEstas reuniones se enmarcan en los entendimientos que existen en base de una ronda de conversaciones que se realiz\u00f3 el a\u00f1o pasado, donde se estableci\u00f3 el intercambio de informaci\u00f3n entre los Estados Mayores Conjuntos, en particular en las experiencias en Operaciones de Paz, en donde actualmente Per\u00fa est\u00e1 participando en 7 misiones. Nosotros esperamos sacar el mayor provecho de la experiencia que ustedes tienen y poder implementarlas en nuestro provecho\u201d,<\/em><\/strong> dijo el Coronel de Ej\u00e9rcito del Per\u00fa, Antonio C\u00f3rdova Espinoza.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000; font-size: 10pt;\">Entre las actividades del intercambio, la delegaci\u00f3n peruana tambi\u00e9n visit\u00f3 el Centro Conjunto para Operaciones de Paz de Chile (CECOPAC), en donde el Director del centro de estudio, Comandante de Grupo Sergio Valencia Burgos, expuso sobre el importante trabajo que realizan, preparando y entrenando al personal de las Fuerzas Armadas, de Orden y Seguridad P\u00fablica, y civiles, que deban participar en operaciones de paz. Asimismo, junto a representantes del Estado Mayor Conjunto de Chile, visitaron el Regimiento Log\u00edstico N\u00b02 \u201cArsenales de Guerra\u201d, en donde su Comandante, el Coronel de Ej\u00e9rcito Felipe Salazar Caro, los recibi\u00f3, mostr\u00f3 las instalaciones y realiz\u00f3 una exposici\u00f3n como encargado y custodio del material de \u201cCruz del Sur\u201d.<\/span><\/p>\n<p><span style=\"font-size: 10pt;\"><a href=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2-92.jpg\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-4875\" src=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2-92.jpg\" alt=\"2\" width=\"620\" height=\"413\"><\/a><\/span><\/p>\n<p><a href=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/4-19.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-4877\" src=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/4-19.jpg\" alt=\"4\" width=\"620\" height=\"413\"><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Entre el 12 y 14 de agosto, se est\u00e1 llevando a cabo el Intercambio de experiencias de Operaciones de Paz entre el Comando Conjunto de las FF.AA. del Per\u00fa (CCFFAA) y el Estado Mayor Conjunto de Chile (EMCO). Instancia de di\u00e1logos y cooperaci\u00f3n mutua en el aprendizaje sobre las experiencias en la labor que vienen&#8230;<\/p>\n","protected":false},"author":5,"featured_media":5823,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"footnotes":""},"categories":[15,3],"tags":[],"class_list":["post-4874","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-15","category-noticias"],"_links":{"self":[{"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/posts\/4874","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/comments?post=4874"}],"version-history":[{"count":1,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/posts\/4874\/revisions"}],"predecessor-version":[{"id":5935,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/posts\/4874\/revisions\/5935"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/media\/5823"}],"wp:attachment":[{"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/media?parent=4874"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/categories?post=4874"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/tags?post=4874"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}