{"id":4850,"date":"2019-07-30T21:04:10","date_gmt":"2019-07-30T21:04:10","guid":{"rendered":"http:\/\/www.emco.mil.cl\/?p=4850"},"modified":"2021-09-28T12:00:08","modified_gmt":"2021-09-28T15:00:08","slug":"delegacion-de-chile-participa-en-la-gran-parada-militar-de-peru","status":"publish","type":"post","link":"https:\/\/www.emco.mil.cl\/index.php\/2019\/07\/30\/delegacion-de-chile-participa-en-la-gran-parada-militar-de-peru\/","title":{"rendered":"Delegaci\u00f3n de Chile participa en la Gran Parada Militar de Per\u00fa"},"content":{"rendered":"<p><span style=\"font-size: 10pt; color: #000000;\">Una delegaci\u00f3n de cadetes de las escuelas matrices de las Fuerzas Armadas de Chile, coordinado por el Departamento de Asuntos Internacionales, Ant\u00e1rticos y Especiales (DAI), del Estado Mayor Conjunto, representaron a nuestro pa\u00eds en el desfile militar por el 198\u00b0 aniversario de la Proclamaci\u00f3n de la Independencia Nacional de Per\u00fa, que se llev\u00f3 a cabo el 29 de julio en Lima.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 10pt; color: #000000;\">El contingente chileno, compuesto por una escuadra y abanderados de las respectivas escuelas matrices, abrieron la Gran Parada Militar como la segunda delegaci\u00f3n extranjera presente, desfilando frente al Presidente de Per\u00fa, Mart\u00edn Vizcarra, autoridades pol\u00edticas y un numeroso p\u00fablico. Los militares chilenos fueron invitados a participar de esta tradici\u00f3n castrense, por el Jefe del Comando Conjunto de las Fuerzas Armadas de Per\u00fa.<\/span><\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/1-93.jpg\"><img fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter size-full wp-image-4852\" src=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/1-93.jpg\" alt=\"1\" width=\"620\" height=\"413\"><\/a><\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2-90.jpg\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-4853\" src=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2-90.jpg\" alt=\"2\" width=\"620\" height=\"413\"><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Una delegaci\u00f3n de cadetes de las escuelas matrices de las Fuerzas Armadas de Chile, coordinado por el Departamento de Asuntos Internacionales, Ant\u00e1rticos y Especiales (DAI), del Estado Mayor Conjunto, representaron a nuestro pa\u00eds en el desfile militar por el 198\u00b0 aniversario de la Proclamaci\u00f3n de la Independencia Nacional de Per\u00fa, que se llev\u00f3 a cabo&#8230;<\/p>\n","protected":false},"author":5,"featured_media":5823,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"footnotes":""},"categories":[15,3],"tags":[],"class_list":["post-4850","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-15","category-noticias"],"_links":{"self":[{"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/posts\/4850","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/comments?post=4850"}],"version-history":[{"count":1,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/posts\/4850\/revisions"}],"predecessor-version":[{"id":5937,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/posts\/4850\/revisions\/5937"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/media\/5823"}],"wp:attachment":[{"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/media?parent=4850"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/categories?post=4850"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/tags?post=4850"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}