{"id":4720,"date":"2019-06-10T14:57:10","date_gmt":"2019-06-10T14:57:10","guid":{"rendered":"http:\/\/www.emco.mil.cl\/?p=4720"},"modified":"2021-09-28T12:12:06","modified_gmt":"2021-09-28T15:12:06","slug":"jemco-despide-a-oficiales-que-asistiran-al-curso-joint-transitions-joint-combined-warfighting-school","status":"publish","type":"post","link":"https:\/\/www.emco.mil.cl\/index.php\/2019\/06\/10\/jemco-despide-a-oficiales-que-asistiran-al-curso-joint-transitions-joint-combined-warfighting-school\/","title":{"rendered":"JEMCO despide a oficiales que asistir\u00e1n al curso \u201cJoint Transitions &#8211; Joint Combined Warfighting School\u201d"},"content":{"rendered":"<p><span style=\"font-size: 10pt; color: #000000;\">El viernes 7 de junio, el Jefe del Estado Mayor Conjunto, Vicealmirante Rodrigo \u00c1lvarez Aguirre, recibi\u00f3 a los oficiales de Estado Mayor que realizar\u00e1n el curso \u201c<em>Joint Transition \u2013 Joint and Combined Warfighting School<\/em>\u201d en Norfolk, Virginia, en EE.UU., por tres meses.<\/span><\/p>\n<p><span style=\"font-size: 10pt; color: #000000;\">El Teniente Coronel Jaime Castro Valdivieso, es profesor del Curso Conjunto de las Academias de Guerra y Profesor de la Academia de Guerra del Ej\u00e9rcito (ACAGUE), es uno de los oficiales que participar\u00e1 del curso conjunto, cuyo fin es la planificaci\u00f3n conjunta y el diario operacional, a trav\u00e9s de seminarios. <strong><em>\u201cEs un honor el haber sido designado y es tambi\u00e9n, una buena oportunidad de poder crecer profesionalmente y es muy importante, poder tener la visi\u00f3n de poder traspasar las cosas que pudiesen aplicarse al corto plazo en nuestros diferentes curr\u00edculos\u201d<\/em><\/strong>, coment\u00f3 el TCL Castro.<\/span><\/p>\n<p><span style=\"font-size: 10pt; color: #000000;\">Quien tambi\u00e9n ser\u00e1 parte de estos cursos, es el Capit\u00e1n de Fragata Alejandro Elgueta Gonz\u00e1lez, primer lugar en el Curso Conjunto de Estado Mayor de las Academias de Guerra 2018, <strong><em>\u201cmi intenci\u00f3n, aparte de aprender y conocer en este curso, es estrechar lazos con los integrantes de las Fuerzas Armadas de los otros pa\u00edses que participan, darnos a conocer como pa\u00eds tambi\u00e9n y posteriormente, traer a Chile toda la experiencia adquirida y hacerla llegar a nuestras Academias para as\u00ed reforzar nuestros conocimientos y preparaci\u00f3n profesional\u201d<\/em><\/strong>.&nbsp;<\/span><\/p>\n<p><a href=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/1-81.jpg\"><img fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter size-full wp-image-4721\" src=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/1-81.jpg\" alt=\"1\" width=\"620\" height=\"413\"><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El viernes 7 de junio, el Jefe del Estado Mayor Conjunto, Vicealmirante Rodrigo \u00c1lvarez Aguirre, recibi\u00f3 a los oficiales de Estado Mayor que realizar\u00e1n el curso \u201cJoint Transition \u2013 Joint and Combined Warfighting School\u201d en Norfolk, Virginia, en EE.UU., por tres meses. El Teniente Coronel Jaime Castro Valdivieso, es profesor del Curso Conjunto de las&#8230;<\/p>\n","protected":false},"author":5,"featured_media":5823,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"footnotes":""},"categories":[15,3],"tags":[],"class_list":["post-4720","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-15","category-noticias"],"_links":{"self":[{"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/posts\/4720","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/comments?post=4720"}],"version-history":[{"count":1,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/posts\/4720\/revisions"}],"predecessor-version":[{"id":5953,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/posts\/4720\/revisions\/5953"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/media\/5823"}],"wp:attachment":[{"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/media?parent=4720"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/categories?post=4720"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/tags?post=4720"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}