{"id":4616,"date":"2019-05-08T20:24:00","date_gmt":"2019-05-08T20:24:00","guid":{"rendered":"http:\/\/www.emco.mil.cl\/?p=4616"},"modified":"2021-09-28T12:21:56","modified_gmt":"2021-09-28T15:21:56","slug":"alumnos-de-la-academia-nacional-de-estudios-politicos-y-estrategico-visitan-el-comando-conjunto-norte","status":"publish","type":"post","link":"https:\/\/www.emco.mil.cl\/index.php\/2019\/05\/08\/alumnos-de-la-academia-nacional-de-estudios-politicos-y-estrategico-visitan-el-comando-conjunto-norte\/","title":{"rendered":"Alumnos de la Academia Nacional de Estudios Pol\u00edticos y Estrat\u00e9gico visitan el Comando Conjunto Norte"},"content":{"rendered":"<p style=\"text-align: justify;\"><span style=\"color: #000000; font-size: 10pt;\">El d\u00eda 6 mayo, en marco de la malla curricular del \u201cDiplomado de Conducci\u00f3n Pol\u00edtica, Estrat\u00e9gica y Defensa\u201d de la Academia Nacional de Estudios Pol\u00edticos y Estrat\u00e9gico (ANEPE), el Comandante del Comando Conjunto Norte (CCN), General de Divisi\u00f3n Juan Carlos Henr\u00edquez, recibi\u00f3 al Director de la ANEPE, Contraalmirante Leonel Mu\u00f1oz, junto a docentes y alumnos, viajaron hasta el CCN, actividad en la que tanto el Estado Mayor Conjunto (EMCO) como el Comando Conjunto Norte participan activamente, al tener un rol fundamental en la Defensa Nacional.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000; font-size: 10pt;\"><a style=\"color: #000000;\" href=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/1-71.jpg\"><img fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter size-full wp-image-4617\" src=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/1-71.jpg\" alt=\"1\" width=\"620\" height=\"413\" \/><\/a><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000; font-size: 10pt;\">En esta visita, los alumnos conocen los antecedentes de las misiones, responsabilidades y experiencias del CCN en cat\u00e1strofes y emergencias. Como as\u00ed tambi\u00e9n, las coordinaciones con las autoridades civiles regionales en el mismo \u00e1mbito de emergencia y cat\u00e1strofe, como con la Oficina Nacional de Emergencia del Ministerio del Interior (ONEMI).<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000; font-size: 10pt;\"><a style=\"color: #000000;\" href=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2-71.jpg\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-4618\" src=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2-71.jpg\" alt=\"2\" width=\"620\" height=\"413\" \/><\/a><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000; font-size: 10pt;\">De la actividad tambi\u00e9n particip\u00f3 el Intendente Regi\u00f3n de Tarapac\u00e1, Miguel \u00c1ngel Quezada, el Director de ONEMI Regi\u00f3n de Tarapac\u00e1, \u00c1lvaro Hormaz\u00e1bal, el Encargado Regional de Seguridad P\u00fablica, Andr\u00e9s Cappona, entre otros.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000; font-size: 10pt;\"><a style=\"color: #000000;\" href=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/3-43.jpg\"><img decoding=\"async\" class=\"size-full wp-image-4619 aligncenter\" src=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/3-43.jpg\" alt=\"3\" width=\"620\" height=\"413\" \/><\/a><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El d\u00eda 6 mayo, en marco de la malla curricular del \u201cDiplomado de Conducci\u00f3n Pol\u00edtica, Estrat\u00e9gica y Defensa\u201d de la Academia Nacional de Estudios Pol\u00edticos y Estrat\u00e9gico (ANEPE), el Comandante del Comando Conjunto Norte (CCN), General de Divisi\u00f3n Juan Carlos Henr\u00edquez, recibi\u00f3 al Director de la ANEPE, Contraalmirante Leonel Mu\u00f1oz, junto a docentes y alumnos,&#8230;<\/p>\n","protected":false},"author":5,"featured_media":5823,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"footnotes":""},"categories":[15,3],"tags":[],"class_list":["post-4616","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-15","category-noticias"],"_links":{"self":[{"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/posts\/4616","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/comments?post=4616"}],"version-history":[{"count":2,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/posts\/4616\/revisions"}],"predecessor-version":[{"id":5966,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/posts\/4616\/revisions\/5966"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/media\/5823"}],"wp:attachment":[{"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/media?parent=4616"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/categories?post=4616"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/tags?post=4616"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}