{"id":4041,"date":"2018-11-07T14:00:16","date_gmt":"2018-11-07T14:00:16","guid":{"rendered":"http:\/\/www.emco.mil.cl\/?p=4041"},"modified":"2021-09-28T14:37:56","modified_gmt":"2021-09-28T17:37:56","slug":"cambio-de-mando-en-casa-lot-chilena-en-bosnia-y-herzegovina","status":"publish","type":"post","link":"https:\/\/www.emco.mil.cl\/index.php\/2018\/11\/07\/cambio-de-mando-en-casa-lot-chilena-en-bosnia-y-herzegovina\/","title":{"rendered":"Cambio de mando en Casa LOT chilena en Bosnia y Herzegovina"},"content":{"rendered":"<p>El 29 de octubre, llegaron a Bosnia y Herzegovina los \u00faltimos integrantes del contingente CHILFOR 30, para relevar al personal de Ej\u00e9rcito que participa en la Operaci\u00f3n de Gesti\u00f3n de Crisis de la Uni\u00f3n Europea \u00abEUFOR- Althea\u00bb.<\/p>\n<p><a href=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2-32.jpg\"><img fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter size-full wp-image-4042\" src=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2-32.jpg\" alt=\"2\" width=\"620\" height=\"413\"><\/a><\/p>\n<p>Se llev\u00f3 a cabo el cambio de mando de la Casa LOT chilena (equipo de observaci\u00f3n y enlace, por sus siglas en ingl\u00e9s), en donde traspasaron las experiencias obtenidas durante los \u00faltimos meses, el conocimiento de las autoridades locales y de la zona de responsabilidad, como tambi\u00e9n el funcionamiento de la misi\u00f3n.<\/p>\n<p>Los equipos LOT cumplen una funci\u00f3n fundamental dentro la misi\u00f3n en Bosnia y Herzegovina, son los encargados de observar el desarrollo del proceso de paz implementado en esa zona. El personal CHILFOR 30, mide el estado actual de la sociedad y los avances en materia de integraci\u00f3n de las entidades que estuvieron en conflicto en la d\u00e9cada del 90.<\/p>\n<p>Con la firma de las actas de entrega, comenz\u00f3 el periodo de 8 meses que el contingente de la Fuerza de Chile (CHILFOR 30) deber\u00e1 cumplir en esta misi\u00f3n, contribuyendo al buen trabajo que el personal chileno desde el a\u00f1o 2003 en la en la Operaci\u00f3n EUFOR-Althea.<\/p>\n<p><a href=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/1-28.jpg\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-4043\" src=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/1-28.jpg\" alt=\"1\" width=\"620\" height=\"413\"><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El 29 de octubre, llegaron a Bosnia y Herzegovina los \u00faltimos integrantes del contingente CHILFOR 30, para relevar al personal de Ej\u00e9rcito que participa en la Operaci\u00f3n de Gesti\u00f3n de Crisis de la Uni\u00f3n Europea \u00abEUFOR- Althea\u00bb. Se llev\u00f3 a cabo el cambio de mando de la Casa LOT chilena (equipo de observaci\u00f3n y enlace,&#8230;<\/p>\n","protected":false},"author":6,"featured_media":5823,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"footnotes":""},"categories":[17,3],"tags":[],"class_list":["post-4041","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-17","category-noticias"],"_links":{"self":[{"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/posts\/4041","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/comments?post=4041"}],"version-history":[{"count":1,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/posts\/4041\/revisions"}],"predecessor-version":[{"id":6038,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/posts\/4041\/revisions\/6038"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/media\/5823"}],"wp:attachment":[{"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/media?parent=4041"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/categories?post=4041"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/tags?post=4041"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}