{"id":3920,"date":"2018-09-21T13:55:05","date_gmt":"2018-09-21T13:55:05","guid":{"rendered":"http:\/\/www.emco.mil.cl\/?p=3920"},"modified":"2021-09-28T16:04:37","modified_gmt":"2021-09-28T19:04:37","slug":"subjefe-del-estado-mayor-conjunto-participa-en-conferencia-de-jefes-de-defensa-del-asia-pacifico-2018","status":"publish","type":"post","link":"https:\/\/www.emco.mil.cl\/index.php\/2018\/09\/21\/subjefe-del-estado-mayor-conjunto-participa-en-conferencia-de-jefes-de-defensa-del-asia-pacifico-2018\/","title":{"rendered":"Subjefe del Estado Mayor Conjunto  participa en \u201cConferencia de Jefes de Defensa del Asia Pac\u00edfico\u201d 2018"},"content":{"rendered":"<p>Entre el 9 y 12 de septiembre, en Hawai, Estados Unidos, se llev\u00f3 a cabo la Conferencia de Jefes de Defensa del Asia Pac\u00edfico 2018 (CHOD), actividad en la que particip\u00f3 el Subjefe del Estado Mayor Conjunto, Vicealmirante Rodrigo \u00c1lvarez Aguirre, instancia organizada por el Comando del Pac\u00edfico de los Estados Unidos de Norteam\u00e9rica (USPACOM).<\/p>\n<p>Esta reuni\u00f3n regional tuvo como prop\u00f3sito generar un espacio de di\u00e1logo, intercambio de experiencias, implementaci\u00f3n de estrategias y definici\u00f3n de objetivos para hacer frente a amenazas comunes que atenten contra la seguridad y estabilidad de la regi\u00f3n. El tema central para este a\u00f1o fue \u201cAsegurando una regi\u00f3n Indo-Pac\u00edfico libre y abierta\u201d.<\/p>\n<p>En esta conferencia, participaron 26 Jefes de Defensa de pa\u00edses que conforman la \u201cCuenca del Pac\u00edfico\u201d, de los cuales s\u00f3lo tres son pa\u00edses latinoamericanos: Chile, Colombia y M\u00e9xico.<\/p>\n<p><a href=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/foto1-9.jpg\"><img fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter size-full wp-image-3921\" src=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/foto1-9.jpg\" alt=\"foto1\" width=\"620\" height=\"413\"><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Entre el 9 y 12 de septiembre, en Hawai, Estados Unidos, se llev\u00f3 a cabo la Conferencia de Jefes de Defensa del Asia Pac\u00edfico 2018 (CHOD), actividad en la que particip\u00f3 el Subjefe del Estado Mayor Conjunto, Vicealmirante Rodrigo \u00c1lvarez Aguirre, instancia organizada por el Comando del Pac\u00edfico de los Estados Unidos de Norteam\u00e9rica (USPACOM)&#8230;.<\/p>\n","protected":false},"author":6,"featured_media":5823,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"footnotes":""},"categories":[17,3],"tags":[],"class_list":["post-3920","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-17","category-noticias"],"_links":{"self":[{"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/posts\/3920","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/comments?post=3920"}],"version-history":[{"count":1,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/posts\/3920\/revisions"}],"predecessor-version":[{"id":6134,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/posts\/3920\/revisions\/6134"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/media\/5823"}],"wp:attachment":[{"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/media?parent=3920"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/categories?post=3920"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/tags?post=3920"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}