{"id":3853,"date":"2018-08-29T14:21:16","date_gmt":"2018-08-29T14:21:16","guid":{"rendered":"http:\/\/www.emco.mil.cl\/?p=3853"},"modified":"2021-09-28T16:25:23","modified_gmt":"2021-09-28T19:25:23","slug":"despedida-contingente-chileno-a-mision-de-paz-en-bosnia-y-herzegovina","status":"publish","type":"post","link":"https:\/\/www.emco.mil.cl\/index.php\/2018\/08\/29\/despedida-contingente-chileno-a-mision-de-paz-en-bosnia-y-herzegovina\/","title":{"rendered":"Despedida contingente chileno a Misi\u00f3n de Paz en Bosnia y Herzegovina"},"content":{"rendered":"<p>En dependencias del Estado Mayor Conjunto, el Jefe del Departamento II \u201cConducci\u00f3n de Operaciones de Paz\u201d, Capit\u00e1n de Nav\u00edo (IM) Favio Santiba\u00f1ez Ortiz, de la Direcci\u00f3n de Operaciones y Conducci\u00f3n Conjunta (DOPCON), despidi\u00f3 al personal de Ej\u00e9rcito que se despleg\u00f3 para integrarse a la Operaci\u00f3n Althea, en Bosnia y Herzegovina.<\/p>\n<p><a href=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/Cdte-Santiba\u00f1ez.jpg\"><img fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter size-full wp-image-3854\" src=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/Cdte-Santiba\u00f1ez.jpg\" alt=\"Cdte Santiba\u00f1ez\" width=\"620\" height=\"413\"><\/a><\/p>\n<p>Chile es uno de los pa\u00edses fuera de la Uni\u00f3n Europea y la Organizaci\u00f3n del Tratado del Atl\u00e1ntico Norte (OTAN), en participar activamente de la Misi\u00f3n de las Naciones Unidas en Bosnia y Herzegovina, con 16 efectivos del Ej\u00e9rcito, que son relevados cada 8 meses, desempe\u00f1\u00e1ndose en el Cuartel General en la ciudad de Sarajevo y equipos de observaci\u00f3n y enlace (Casa LOT) en la ciudad de Banja Luka.<\/p>\n<p><strong><em>\u201cNosotros tenemos muchas expectativa de mantener todo lo que se ha hecho estos \u00faltimos 15 a\u00f1os, el mantener el ambiente estable y seguro, adem\u00e1s de sentir el pulso de los problemas o conflictos que podr\u00edan generarse en Bosnia y Herzegovina\u201d,<\/em><\/strong> coment\u00f3 el Teniente Cristi\u00e1n Iturriaga Nielsen<\/p>\n<p><strong><em>\u201cEsta es una gran oportunidad de representar a Chile de la mejor manera. Nosotros vamos a preservar la paz y a ayudar en todo lo que sea necesario y todo lo que conlleva estar en un pa\u00eds que estuvo en guerra\u201d,<\/em><\/strong> dijo la Sargento Primero Cecilia Mart\u00ednez Gaete<\/p>\n<p>Bosnia y Herzegovina es un pa\u00eds situado en la Pen\u00ednsula de los Balcanes, cuya capital es la ciudad de Sarajevo, obtiene su independencia de la Antigua Yugoslavia en 1992, mediante un Refer\u00e9ndum realizado en marzo de ese a\u00f1o. Los serbios de la antigua Yugoslavia se oponen a esta independencia, motivados por una ideolog\u00eda nacionalista que propone la uni\u00f3n de todos los serbios en un solo Estado, junto a Macedonia y la actual Croacia, causando una guerra civil.<\/p>\n<p><a href=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/Contingente-2.jpg\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-3855\" src=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/Contingente-2.jpg\" alt=\"Contingente\" width=\"620\" height=\"413\"><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>En dependencias del Estado Mayor Conjunto, el Jefe del Departamento II \u201cConducci\u00f3n de Operaciones de Paz\u201d, Capit\u00e1n de Nav\u00edo (IM) Favio Santiba\u00f1ez Ortiz, de la Direcci\u00f3n de Operaciones y Conducci\u00f3n Conjunta (DOPCON), despidi\u00f3 al personal de Ej\u00e9rcito que se despleg\u00f3 para integrarse a la Operaci\u00f3n Althea, en Bosnia y Herzegovina. Chile es uno de los&#8230;<\/p>\n","protected":false},"author":4,"featured_media":5823,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"footnotes":""},"categories":[17,3],"tags":[],"class_list":["post-3853","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-17","category-noticias"],"_links":{"self":[{"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/posts\/3853","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/comments?post=3853"}],"version-history":[{"count":1,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/posts\/3853\/revisions"}],"predecessor-version":[{"id":6164,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/posts\/3853\/revisions\/6164"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/media\/5823"}],"wp:attachment":[{"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/media?parent=3853"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/categories?post=3853"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/tags?post=3853"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}