{"id":369,"date":"2013-11-18T15:04:29","date_gmt":"2013-11-18T15:04:29","guid":{"rendered":"http:\/\/10.10.20.7\/wp\/?p=369"},"modified":"2021-09-29T12:42:46","modified_gmt":"2021-09-29T15:42:46","slug":"jefe-de-las-fuerzas-de-paz-bosnia-herzegovina-en-chile-2","status":"publish","type":"post","link":"https:\/\/www.emco.mil.cl\/index.php\/2013\/11\/18\/jefe-de-las-fuerzas-de-paz-bosnia-herzegovina-en-chile-2\/","title":{"rendered":"Jefe de las Fuerzas de Paz Bosnia-Herzegovina en Chile"},"content":{"rendered":"<p>Una exposici\u00f3n respecto al quehacer del Estado Mayor Conjunto, la entrega de una ofrenda floral ante la estatua del Libertador Bernardo O\u00b4Higgins Riquelme, un recorrido por el Museo de la Escuela Militar y la imposici\u00f3n de la condecoraci\u00f3n \u201cEstado Mayor Conjunto\u201d, comprendi\u00f3 la primera actividad que realiza en nuestro pa\u00eds el Vice Comandante Supremo Aliado en Europa y Comandante Operacional de la fuerza de paz Bosnia-Herzegovina \u201cAlthea\u201d, General, Sir Richard Shirreff, invitado por el Jefe del Estado Mayor Conjunto, General de Divisi\u00f3n Hern\u00e1n Mardones R\u00edos.<\/p>\n<p>La misi\u00f3n de paz \u201cAlthea\u201d, que opera bajo el amparo de la Uni\u00f3n Europea con el nombre de EUFOR, est\u00e1 compuesta, entre otros, por efectivos del Ej\u00e9rcito de Chile quienes, a juicio del General Shirreff han constituido \u201cun ejemplo para todas las naciones, siendo un grupo compuesto por profesionales de primer nivel lo que han hecho una diferencia invalorable\u201d.<\/p>\n<p>Chile participa hace 10 a\u00f1os de forma consecutiva en EUFOR-ALTHEA, &nbsp;aniversario que se celebr\u00f3 hace unos d\u00edas en Sarajevo, con una ceremonia encabezada por el General Shirreff en la que se condecor\u00f3 a los miembros del contingente nacional con la \u201cEuropean Union Common Security and Defense Policy Service Medal\u201d, medalla que es \u201cun reconocimiento formal de la contribuci\u00f3n chilena al \u00e9xito de EUFOR\u201d.<\/p>\n<p>Shirreff tambi\u00e9n realizar\u00e1 visitas al Centro Conjunto para Operaciones de Paz de Chile (CECOPAC); adem\u00e1s del Comando de Educaci\u00f3n y Doctrina (CEDOC) y la Brigada de Operaciones Especiales del Ej\u00e9rcito de Chile (BOE).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Una exposici\u00f3n respecto al quehacer del Estado Mayor Conjunto, la entrega de una ofrenda floral ante la estatua del Libertador Bernardo O\u00b4Higgins Riquelme, un recorrido por el Museo de la Escuela Militar y la imposici\u00f3n de la condecoraci\u00f3n \u201cEstado Mayor Conjunto\u201d, comprendi\u00f3 la primera actividad que realiza en nuestro pa\u00eds el Vice Comandante Supremo Aliado&#8230;<\/p>\n","protected":false},"author":6,"featured_media":5823,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"footnotes":""},"categories":[28,3],"tags":[],"class_list":["post-369","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-28","category-noticias"],"_links":{"self":[{"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/posts\/369","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/comments?post=369"}],"version-history":[{"count":2,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/posts\/369\/revisions"}],"predecessor-version":[{"id":7160,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/posts\/369\/revisions\/7160"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/media\/5823"}],"wp:attachment":[{"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/media?parent=369"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/categories?post=369"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/tags?post=369"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}