{"id":3621,"date":"2018-06-12T18:13:08","date_gmt":"2018-06-12T18:13:08","guid":{"rendered":"http:\/\/www.emco.mil.cl\/?p=3621"},"modified":"2021-09-28T15:40:17","modified_gmt":"2021-09-28T18:40:17","slug":"ii-reunion-bilateral-de-estados-mayores-conjuntos-chile-espana","status":"publish","type":"post","link":"https:\/\/www.emco.mil.cl\/index.php\/2018\/06\/12\/ii-reunion-bilateral-de-estados-mayores-conjuntos-chile-espana\/","title":{"rendered":"II Reuni\u00f3n Bilateral de Estados Mayores Conjuntos Chile \u2013 Espa\u00f1a"},"content":{"rendered":"<p>Este 12 de junio, en dependencias del Estado Mayor Conjunto se dio inicio a la II reuni\u00f3n bilateral de Estados Mayores Conjuntos entre Chile y Espa\u00f1a 2018, actividad presidida por el Subjefe del Estado Mayor Conjunto, Vicealmirante Rodrigo \u00c1lvarez Aguirre, quien recibi\u00f3 a la delegaci\u00f3n espa\u00f1ola, encabezada por el Jefe de la divisi\u00f3n estrat\u00e9gica del Estado Mayor Conjunto, General de Divisi\u00f3n del Ej\u00e9rcito del Aire, Lucas Mu\u00f1oz Bronchales.<\/p>\n<p><a href=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/foto-2-3.jpg\"><img fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter size-full wp-image-3624\" src=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/foto-2-3.jpg\" alt=\"foto 2\" width=\"620\" height=\"413\"><\/a><\/p>\n<p><strong><em>\u201cPara Chile, el poder participar en esta instancia de di\u00e1logo, constituye una privilegiada oportunidad, la cual valoramos y agradecemos en toda su dimensi\u00f3n\u201d<\/em><\/strong>, dijo el SUBJEMCO, Vicealmirante \u00c1lvarez a los presentes en la reuni\u00f3n.<\/p>\n<p><a href=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/foto1-2.jpg\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-3623\" src=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/foto1-2.jpg\" alt=\"foto1\" width=\"620\" height=\"413\"><\/a><\/p>\n<p>En esta oportunidad, se tratar\u00e1n materias y temas de inter\u00e9s com\u00fan de la Defensa, tales como el intercambio de experiencias en operaciones de paz, capacidades de las unidades militares en crisis, emergencias y cat\u00e1strofes naturales y experiencias del Mando Conjunto en Ciberdefensa.<\/p>\n<p>Esta reuni\u00f3n se enmarca seg\u00fan lo dispuesto el a\u00f1o 2015, por los ministros de Defensa de Chile y Espa\u00f1a, para dar inicio a conversaciones de niveles estrat\u00e9gicos operacionales entre ambos pa\u00edses.<\/p>\n<p><a href=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/foto-3-3.jpg\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-3625\" src=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/foto-3-3.jpg\" alt=\"foto 3\" width=\"620\" height=\"413\"><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Este 12 de junio, en dependencias del Estado Mayor Conjunto se dio inicio a la II reuni\u00f3n bilateral de Estados Mayores Conjuntos entre Chile y Espa\u00f1a 2018, actividad presidida por el Subjefe del Estado Mayor Conjunto, Vicealmirante Rodrigo \u00c1lvarez Aguirre, quien recibi\u00f3 a la delegaci\u00f3n espa\u00f1ola, encabezada por el Jefe de la divisi\u00f3n estrat\u00e9gica del&#8230;<\/p>\n","protected":false},"author":6,"featured_media":5823,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"footnotes":""},"categories":[17,3],"tags":[],"class_list":["post-3621","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-17","category-noticias"],"_links":{"self":[{"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/posts\/3621","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/comments?post=3621"}],"version-history":[{"count":1,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/posts\/3621\/revisions"}],"predecessor-version":[{"id":6106,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/posts\/3621\/revisions\/6106"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/media\/5823"}],"wp:attachment":[{"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/media?parent=3621"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/categories?post=3621"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/tags?post=3621"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}