{"id":3584,"date":"2018-05-28T21:11:23","date_gmt":"2018-05-28T21:11:23","guid":{"rendered":"http:\/\/www.emco.mil.cl\/?p=3584"},"modified":"2021-09-28T15:38:07","modified_gmt":"2021-09-28T18:38:07","slug":"gran-concurrencia-al-ministerio-de-defensa-en-el-dia-del-patrimonio-cultural-de-chile","status":"publish","type":"post","link":"https:\/\/www.emco.mil.cl\/index.php\/2018\/05\/28\/gran-concurrencia-al-ministerio-de-defensa-en-el-dia-del-patrimonio-cultural-de-chile\/","title":{"rendered":"Gran concurrencia al Ministerio de Defensa en el D\u00eda del Patrimonio Cultural de Chile"},"content":{"rendered":"<p>Este domingo 27 de mayo, se abrieron las puertas del Edificio Ministerial a m\u00e1s de 10 mil personas, quienes pudieron conocer y disfrutar de las diferentes actividades que el Ministerio de Defensa y las Fuerzas Armadas ten\u00edan para todos quienes estuvieran interesados en conocer la historia de la Defensa Nacional.<\/p>\n<p><a href=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/44.jpg\"><img fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter size-full wp-image-3585\" src=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/44.jpg\" alt=\"44\" width=\"620\" height=\"413\" \/><\/a><\/p>\n<p>El Ministro de Defensa Nacional, Alberto Espina Otero, fue el anfitri\u00f3n y explic\u00f3 a cada una de las personas el funcionamiento del ministerio, en especial todo lo relativo al Gabinete y las Fuerzas Armadas. Adem\u00e1s, les mostr\u00f3 su oficina as\u00ed como tambi\u00e9n los hist\u00f3ricos salones O\u2019Higgins, Carrera y Zenteno del edificio.<\/p>\n<p><a href=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/55.jpg\"><img decoding=\"async\" class=\"size-full wp-image-3587 aligncenter\" src=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/55.jpg\" alt=\"55\" width=\"413\" height=\"620\" \/><\/a><\/p>\n<p>A la cita, lo acompa\u00f1aron el Jefe del Estado Mayor Conjunto, General de Aviaci\u00f3n Arturo Merino N\u00fa\u00f1ez, el Subsecretario de Defensa, Cristi\u00e1n de la Maza Riquelme y el Subsecretario para las Fuerzas Armadas, Juan Francisco Galli Basili.<\/p>\n<p><strong><em>\u201dAc\u00e1 estamos viviendo una verdadera fiesta ciudadana, donde las instituciones armadas muestran parte de sus capacidades que ponen a disposici\u00f3n de todos cuando alguna emergencia los afecta<\/em><\/strong>\u201d, destac\u00f3 el Ministro Espina, agregando que las FF.AA. son de todos, que no pertenecen a ning\u00fan sector pol\u00edtico y que siempre deben ser un factor de unidad.<\/p>\n<p><a href=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/11-3.jpg\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-3588\" src=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/11-3.jpg\" alt=\"11\" width=\"620\" height=\"413\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Este domingo 27 de mayo, se abrieron las puertas del Edificio Ministerial a m\u00e1s de 10 mil personas, quienes pudieron conocer y disfrutar de las diferentes actividades que el Ministerio de Defensa y las Fuerzas Armadas ten\u00edan para todos quienes estuvieran interesados en conocer la historia de la Defensa Nacional. El Ministro de Defensa Nacional,&#8230;<\/p>\n","protected":false},"author":6,"featured_media":5823,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"footnotes":""},"categories":[17,3],"tags":[],"class_list":["post-3584","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-17","category-noticias"],"_links":{"self":[{"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/posts\/3584","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/comments?post=3584"}],"version-history":[{"count":2,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/posts\/3584\/revisions"}],"predecessor-version":[{"id":6102,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/posts\/3584\/revisions\/6102"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/media\/5823"}],"wp:attachment":[{"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/media?parent=3584"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/categories?post=3584"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/tags?post=3584"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}