{"id":3273,"date":"2017-12-28T20:01:17","date_gmt":"2017-12-28T20:01:17","guid":{"rendered":"http:\/\/www.emco.mil.cl\/?p=3273"},"modified":"2021-09-28T16:37:23","modified_gmt":"2021-09-28T19:37:23","slug":"condecoracion-estado-mayor-conjunto-a-ayudantes-del-ministro-de-defensa-nacional","status":"publish","type":"post","link":"https:\/\/www.emco.mil.cl\/index.php\/2017\/12\/28\/condecoracion-estado-mayor-conjunto-a-ayudantes-del-ministro-de-defensa-nacional\/","title":{"rendered":"Condecoraci\u00f3n \u201cEstado Mayor Conjunto\u201d a ayudantes del Ministro de Defensa Nacional"},"content":{"rendered":"<p>En dependencias del EMCO, se llev\u00f3 a cabo la entrega de la medalla \u201cEstado Mayor Conjunto\u201d a los ayudantes militares del Ministro de Defensa Nacional en una ceremonia presidida por el titular de Defensa, Jos\u00e9 Antonio G\u00f3mez Urrutia, donde el Jefe del Estado Mayor Conjunto, General de Aviaci\u00f3n Arturo Merino N\u00fa\u00f1ez condecor\u00f3 a los oficiales colaboradores del Ministerio, con la presencia de la Subsecretaria para las Fuerzas Armadas, Paulina Vodanovic Rojas y autoridades del Estado Mayor Conjunto.<\/p>\n<p><strong><em>&nbsp;<\/em><\/strong>Los oficiales condecorados fueron:<\/p>\n<p>&#8211; Ayudant\u00eda Militar y Jefe de la Ayudant\u00eda: Coronel de Ej\u00e9rcito, Claudio Weber Orellana.<\/p>\n<p>&#8211; Ayudante Naval: Capit\u00e1n de Fragata, Felpe Otey Moses.<\/p>\n<p>&#8211; Ayudante A\u00e9reo: Comandante de Grupo (DA), Claudio Alc\u00e1zar Sichel.<\/p>\n<p>&#8211; Ayudante de Carabineros: Teniente Coronel, Cristi\u00e1n Montero Sep\u00falveda.<\/p>\n<p><a href=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/FOTO-2-7.jpg\"><img fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter size-large wp-image-3279\" src=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/FOTO-2-7.jpg\" alt=\"FOTO 2\" width=\"620\" height=\"413\"><\/a><\/p>\n<p><a href=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/FOTO-3-4.jpg\"><img decoding=\"async\" class=\"aligncenter size-large wp-image-3280\" src=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/FOTO-3-4.jpg\" alt=\"FOTO 3\" width=\"620\" height=\"413\"><\/a><\/p>\n<p><a href=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/FOTO-4-2.jpg\"><img decoding=\"async\" class=\"aligncenter size-large wp-image-3281\" src=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/FOTO-4-2.jpg\" alt=\"FOTO 4\" width=\"620\" height=\"413\"><\/a><\/p>\n<p><a href=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/FOTO-5-1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-3282\" src=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/FOTO-5-1.jpg\" alt=\"FOTO 5\" width=\"620\" height=\"413\"><\/a><\/p>\n<p><strong><em>\u201cPara m\u00ed, es motivo de una alta satisfacci\u00f3n y orgullo, poder reconocer el trabajo que los ayudantes del Se\u00f1or Ministro han materializado este a\u00f1o en beneficio y en pro de la eficiencia del Estado Mayor Conjunto. Han realizado un trabajo excepcional y profesionalmente merecen de sobra esta medalla. Nosotros somos los que nos hemos sido beneficiado con su trabajo, el cual se lo agradecemos a todos y por eso el motivo de esta distinci\u00f3n\u201d,<\/em><\/strong> dijo el General Merino a los ayudantes condecorados.<\/p>\n<p><a href=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/FOTO-1-8.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-3278\" src=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/FOTO-1-8.jpg\" alt=\"FOTO 1\" width=\"604\" height=\"402\"><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>En dependencias del EMCO, se llev\u00f3 a cabo la entrega de la medalla \u201cEstado Mayor Conjunto\u201d a los ayudantes militares del Ministro de Defensa Nacional en una ceremonia presidida por el titular de Defensa, Jos\u00e9 Antonio G\u00f3mez Urrutia, donde el Jefe del Estado Mayor Conjunto, General de Aviaci\u00f3n Arturo Merino N\u00fa\u00f1ez condecor\u00f3 a los oficiales&#8230;<\/p>\n","protected":false},"author":6,"featured_media":5823,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"footnotes":""},"categories":[22,3],"tags":[],"class_list":["post-3273","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-22","category-noticias"],"_links":{"self":[{"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/posts\/3273","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/comments?post=3273"}],"version-history":[{"count":1,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/posts\/3273\/revisions"}],"predecessor-version":[{"id":6171,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/posts\/3273\/revisions\/6171"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/media\/5823"}],"wp:attachment":[{"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/media?parent=3273"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/categories?post=3273"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/tags?post=3273"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}