{"id":2995,"date":"2017-09-26T12:05:52","date_gmt":"2017-09-26T12:05:52","guid":{"rendered":"http:\/\/www.emco.mil.cl\/?p=2995"},"modified":"2021-09-28T16:59:53","modified_gmt":"2021-09-28T19:59:53","slug":"ministro-de-defensa-inauguro-curso-conjunto-de-las-academias-de-guerra-institucionales","status":"publish","type":"post","link":"https:\/\/www.emco.mil.cl\/index.php\/2017\/09\/26\/ministro-de-defensa-inauguro-curso-conjunto-de-las-academias-de-guerra-institucionales\/","title":{"rendered":"Ministro de Defensa inaugur\u00f3 Curso Conjunto de las Academias de Guerra Institucionales"},"content":{"rendered":"<p>Vi\u00f1a del Mar, 26 de septiembre de 2017<\/p>\n<p>Con una ceremonia encabezada por el Ministro de Defensa Nacional Jos\u00e9 Antonio G\u00f3mez, el 26 de septiembre en el Audit\u00f3rium \u201cAlmirante Justiniano\u201d de la Academia de Guerra Naval, se inaugur\u00f3 el Curso Conjunto de Estado Mayor 2017, cuya planificaci\u00f3n y organizaci\u00f3n es de responsabilidad del Estado Mayor Conjunto. En este a\u00f1o 2017 su ejecuci\u00f3n est\u00e1 a cargo de la Academia de Guerra Naval, como Academia Sede.<\/p>\n<p><a href=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/web_interior.png\"><img fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter size-full wp-image-2997\" src=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/web_interior.png\" alt=\"web_interior\" width=\"620\" height=\"413\"><\/a><\/p>\n<p>La jornada cont\u00f3 con la presencia del Jefe Estado Mayor Conjunto General de Aviaci\u00f3n Arturo Merino N\u00fa\u00f1ez, el Jefe del Estado Mayor General del Ej\u00e9rcito, General de Divisi\u00f3n Ricardo Mart\u00ednez Menanteau, el Jefe del Estado Mayor General de la Fuerza A\u00e9rea, General de Aviaci\u00f3n Lorenzo Villal\u00f3n del Fierro, el Sub Jefe del Estado Mayor Conjunto Vicealmirante Rodrigo \u00c1lvarez Aguirre, el Director General del Personal de la Armada, Vicealmirante Arturo Undurraga D\u00edaz, los respectivos Directores de Educaci\u00f3n de las Instituciones, Directores de las Academias de Guerras y Jefes de Cursos de las tres ramas de nuestras Fuerzas Armadas.<\/p>\n<p>&nbsp;<\/p>\n<p>El Ministro G\u00f3mez expuso el tema, \u201cEl Valor de lo Conjunto\u201d, el que comenz\u00f3 con un resumen hist\u00f3rico de las batallas, campa\u00f1as y guerras que nuestro pa\u00eds -victoriosamente enfrent\u00f3- bajo una conducci\u00f3n conjunta, destacando la necesidad de evolucionar y avanzar en esa l\u00ednea en distintos \u00e1mbitos de acci\u00f3n, que van mucho m\u00e1s all\u00e1 de las situaciones de crisis, Operaciones de Paz y apoyo en cat\u00e1strofes naturales. Instancias en las que han quedado demostradas las capacidades polivalentes de las Fuerzas Armadas.<\/p>\n<p><a href=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/web_interior2.png\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-2998\" src=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/web_interior2.png\" alt=\"web_interior2\" width=\"620\" height=\"413\"><\/a><\/p>\n<p>&nbsp;<\/p>\n<p>El Jefe Estado Mayor Conjunto, dict\u00f3 una exposici\u00f3n llamada \u201cFortalecimiento de lo Conjunto\u201d, donde expuso un diagn\u00f3stico de la situaci\u00f3n actual del EMCO en relaci\u00f3n a las misiones y facultades que le otorga la ley 20.424, destacando algunas indicaciones a dicha ley, que fueron trabajadas en conjunto con las Instituciones y ser\u00e1n propuestas para el tr\u00e1mite legislativo durante el presente a\u00f1o.<\/p>\n<p><u>CURSO CONJUNTO:<\/u><\/p>\n<p>El Curso Conjunto 2017 congrega a 110 alumnos y 17 docentes provenientes de las Academias de Guerra del Ej\u00e9rcito, Naval y Fuerza A\u00e9rea y tendr\u00e1 una duraci\u00f3n de 11 semanas durante las cu\u00e1les los alumnos desarrollar\u00e1n m\u00faltiples actividades te\u00f3rico-pr\u00e1cticas en las diferentes Aulas, as\u00ed como tambi\u00e9n en Talleres y demostraciones de capacidades a lo largo del pa\u00eds, donde los alumnos podr\u00e1n conocer las capacidades del EMCO y los Comandos Conjuntos en las ciudades de Santiago, Iquique y Punta Arenas. Actividades que permiten potenciar un criterio y pensamiento en el \u00e1mbito conjunto, lo cual ser\u00e1 fundamental para su desempe\u00f1o futuro como asesores y comandantes de UU., que se desempe\u00f1an en el accionar conjunto de la Fuerza.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Vi\u00f1a del Mar, 26 de septiembre de 2017 Con una ceremonia encabezada por el Ministro de Defensa Nacional Jos\u00e9 Antonio G\u00f3mez, el 26 de septiembre en el Audit\u00f3rium \u201cAlmirante Justiniano\u201d de la Academia de Guerra Naval, se inaugur\u00f3 el Curso Conjunto de Estado Mayor 2017, cuya planificaci\u00f3n y organizaci\u00f3n es de responsabilidad del Estado Mayor&#8230;<\/p>\n","protected":false},"author":6,"featured_media":5823,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"footnotes":""},"categories":[22,3],"tags":[],"class_list":["post-2995","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-22","category-noticias"],"_links":{"self":[{"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/posts\/2995","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/comments?post=2995"}],"version-history":[{"count":2,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/posts\/2995\/revisions"}],"predecessor-version":[{"id":6279,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/posts\/2995\/revisions\/6279"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/media\/5823"}],"wp:attachment":[{"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/media?parent=2995"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/categories?post=2995"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/tags?post=2995"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}