{"id":2941,"date":"2017-07-26T11:34:09","date_gmt":"2017-07-26T11:34:09","guid":{"rendered":"http:\/\/www.emco.mil.cl\/?p=2941"},"modified":"2021-09-28T17:03:43","modified_gmt":"2021-09-28T20:03:43","slug":"comandante-general-de-las-fuerzas-militares-de-colombia-impone-medalla-militar-fe-en-la-causa-al-jefe-del-estado-mayor-conjunto","status":"publish","type":"post","link":"https:\/\/www.emco.mil.cl\/index.php\/2017\/07\/26\/comandante-general-de-las-fuerzas-militares-de-colombia-impone-medalla-militar-fe-en-la-causa-al-jefe-del-estado-mayor-conjunto\/","title":{"rendered":"Comandante General de las Fuerzas Militares de Colombia impone medalla militar \u201cFe en la causa\u201d al Jefe del Estado Mayor Conjunto"},"content":{"rendered":"<p>Santiago, 26 de julio de 2017<\/p>\n<p>En el marco de la II Reuni\u00f3n Bilateral entre el Estado Mayor Conjunto de las FF.AA. de Chile y el Comando General de las Fuerzas Militares de Colombia, el General Juan Pablo Rodr\u00edguez Barrag\u00e1n, Comandante General de las Fuerzas Militares de Colombia, impuso esta ma\u00f1ana en una significativa ceremonia desarrollada en dependencias del EMCO, la medalla militar \u201cFe en la causa\u201d, al Jefe del Estado Mayor Conjunto, General de Aviaci\u00f3n Arturo Merino N\u00fa\u00f1ez.<\/p>\n<p>Esta medalla se impone a Oficiales Colombianos y extranjeros por su aporte a la funci\u00f3n que desempe\u00f1an las Fuerzas Armadas de este pa\u00eds.<\/p>\n<p>El General Merino agradeci\u00f3 la medalla, se\u00f1alando en un breve discurso que: \u201cMe complace recibir esta valiosa condecoraci\u00f3n con el orgullo que simboliza un reconocimiento a todos quienes trabajamos en el Estado Mayor Conjunto\u201d. Asimismo, destac\u00f3 los hist\u00f3ricos v\u00ednculos y lazos que unen a las Fuerzas Armadas de ambos pa\u00edses, reafirmado su compromiso de seguir acompa\u00f1ando y apoyando el proceso de paz, llevado adelante por el pueblo de Colombia.<\/p>\n<p>La II Reuni\u00f3n Bilateral entre el Estado Mayor Conjunto de las FF.AA. de Chile y el Comando General de las Fuerzas Militares de Colombia, se est\u00e1 realizando en Santiago de Chile entre los d\u00edas 24 y 28 de julio. En ella, se han realizado saludos protocolares entre las delegaciones de Colombia y Chile, como tambi\u00e9n conferencias que han permitido intercambiar experiencias en temas tales como la participaci\u00f3n de las FF.AA. en el sistema de Protecci\u00f3n Civil ante Desastres Naturales y Emergencias por parte de Chile, y del Plan de Transformaci\u00f3n y Modernizaci\u00f3n de las Fuerzas Militares de Colombia, entre otros.<\/p>\n<p>Esta Reuni\u00f3n Bilateral constituye una excelente oportunidad para incrementar los lazos de cooperaci\u00f3n y de fomento de confianza, que permiten el desarrollo de una concepci\u00f3n com\u00fan en materias de seguridad y defensa.<a href=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/web_interior3.jpg\"><img fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter size-full wp-image-2950\" src=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/web_interior3.jpg\" alt=\"web_interior3\" width=\"620\" height=\"413\"><\/a><\/p>\n<p><a href=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/web_interior1.jpg\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-2942\" src=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/web_interior1.jpg\" alt=\"web_interior1\" width=\"620\" height=\"413\"><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Santiago, 26 de julio de 2017 En el marco de la II Reuni\u00f3n Bilateral entre el Estado Mayor Conjunto de las FF.AA. de Chile y el Comando General de las Fuerzas Militares de Colombia, el General Juan Pablo Rodr\u00edguez Barrag\u00e1n, Comandante General de las Fuerzas Militares de Colombia, impuso esta ma\u00f1ana en una significativa ceremonia&#8230;<\/p>\n","protected":false},"author":6,"featured_media":5823,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"footnotes":""},"categories":[22,3],"tags":[],"class_list":["post-2941","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-22","category-noticias"],"_links":{"self":[{"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/posts\/2941","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/comments?post=2941"}],"version-history":[{"count":2,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/posts\/2941\/revisions"}],"predecessor-version":[{"id":6284,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/posts\/2941\/revisions\/6284"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/media\/5823"}],"wp:attachment":[{"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/media?parent=2941"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/categories?post=2941"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/tags?post=2941"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}