{"id":2917,"date":"2017-07-07T19:30:49","date_gmt":"2017-07-07T19:30:49","guid":{"rendered":"http:\/\/www.emco.mil.cl\/?p=2917"},"modified":"2021-09-28T17:05:11","modified_gmt":"2021-09-28T20:05:11","slug":"jefe-de-estado-mayor-conjunto-participa-en-conferencia-de-jefes-de-defensa-en-la-organizacion-de-las-naciones-unidas","status":"publish","type":"post","link":"https:\/\/www.emco.mil.cl\/index.php\/2017\/07\/07\/jefe-de-estado-mayor-conjunto-participa-en-conferencia-de-jefes-de-defensa-en-la-organizacion-de-las-naciones-unidas\/","title":{"rendered":"Jefe de Estado Mayor Conjunto participa en conferencia de jefes de defensa en la Organizaci\u00f3n de las Naciones Unidas"},"content":{"rendered":"<p>En la sede de la Organizaci\u00f3n de Naciones Unidas en Nueva York, Estados Unidos, se desarroll\u00f3 entre el 5 y el 8 de julio, la 2da conferencia de Jefes de la Defensa organizado por el Departamento de Operaciones de Paz de la ONU con la participaci\u00f3n del Jefe del Estado Mayor Conjunto, General de Aviaci\u00f3n, Arturo Merino N\u00fa\u00f1ez.<\/p>\n<p>La reuni\u00f3n que se origin\u00f3 el a\u00f1o 2015, permiti\u00f3 a los Jefes de la Defensa de todos los pa\u00edses participantes de la ONU hacer un seguimiento e intercambiar experiencias &nbsp;que aportan contingentes y fuerzas militares para las operaciones de paz en el mundo y las materias propias tratadas durante la primera conferencia.<\/p>\n<p><a href=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/IMG_5561-e1499455777480.jpg\"><img fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter wp-image-2918 \" src=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/IMG_5561-e1499455777480-1024x716.jpg\" width=\"619\" height=\"433\"><\/a><\/p>\n<p>Durante la conferencia se realizaron actividades protocolares, conferencias y reuniones bilaterales en la que el General de Aviaci\u00f3n, Arturo Merino N\u00fa\u00f1ez. pudo tratar temas de inter\u00e9s nacional con diferentes actores internacionales.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En la sede de la Organizaci\u00f3n de Naciones Unidas en Nueva York, Estados Unidos, se desarroll\u00f3 entre el 5 y el 8 de julio, la 2da conferencia de Jefes de la Defensa organizado por el Departamento de Operaciones de Paz de la ONU con la participaci\u00f3n del Jefe del Estado Mayor Conjunto, General de Aviaci\u00f3n,&#8230;<\/p>\n","protected":false},"author":6,"featured_media":5823,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"footnotes":""},"categories":[22,3],"tags":[],"class_list":["post-2917","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-22","category-noticias"],"_links":{"self":[{"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/posts\/2917","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/comments?post=2917"}],"version-history":[{"count":2,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/posts\/2917\/revisions"}],"predecessor-version":[{"id":6287,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/posts\/2917\/revisions\/6287"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/media\/5823"}],"wp:attachment":[{"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/media?parent=2917"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/categories?post=2917"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/tags?post=2917"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}