{"id":2895,"date":"2017-06-22T20:56:35","date_gmt":"2017-06-22T20:56:35","guid":{"rendered":"http:\/\/www.emco.mil.cl\/?p=2895"},"modified":"2021-09-28T17:06:48","modified_gmt":"2021-09-28T20:06:48","slug":"debriefing-final-del-ejercicio-de-crisis-ciclon-2017","status":"publish","type":"post","link":"https:\/\/www.emco.mil.cl\/index.php\/2017\/06\/22\/debriefing-final-del-ejercicio-de-crisis-ciclon-2017\/","title":{"rendered":"Debriefing final del ejercicio de crisis cicl\u00f3n 2017"},"content":{"rendered":"<p>El d\u00eda martes 20 de junio en la Academia de Guerra A\u00e9rea de la FACh, se efectu\u00f3 el debriefing&nbsp; final del ejercicio Cicl\u00f3n 2017. &nbsp;En dicha actividad, participaron las m\u00e1ximas autoridades del EMCO, los Comandantes de los Comandos Conjuntos, los Comandantes de los diferentes \u00f3rganos de maniobra y asesores en las diferentes \u00e1reas de la actividad. Cont\u00f3 adem\u00e1s, con la participaci\u00f3n de delegados de Carabineros y de la Polic\u00eda de Investigaciones.<\/p>\n<p>En esta oportunidad se presentaron los principales logros alcanzados como tambi\u00e9n las lecciones aprendidas y los aspectos que se deben mejorar para pr\u00f3ximos ejercicios.<\/p>\n<p>Especial menci\u00f3n tuvo el hecho&nbsp;que todas las actividades se desarrollaron con total normalidad, sin ning\u00fan tipo de accidentes y respetando las normas de seguridad establecidas para el ejercicio.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El d\u00eda martes 20 de junio en la Academia de Guerra A\u00e9rea de la FACh, se efectu\u00f3 el debriefing&nbsp; final del ejercicio Cicl\u00f3n 2017. &nbsp;En dicha actividad, participaron las m\u00e1ximas autoridades del EMCO, los Comandantes de los Comandos Conjuntos, los Comandantes de los diferentes \u00f3rganos de maniobra y asesores en las diferentes \u00e1reas de la&#8230;<\/p>\n","protected":false},"author":6,"featured_media":5823,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"footnotes":""},"categories":[22,3],"tags":[],"class_list":["post-2895","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-22","category-noticias"],"_links":{"self":[{"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/posts\/2895","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/comments?post=2895"}],"version-history":[{"count":2,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/posts\/2895\/revisions"}],"predecessor-version":[{"id":6290,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/posts\/2895\/revisions\/6290"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/media\/5823"}],"wp:attachment":[{"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/media?parent=2895"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/categories?post=2895"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/tags?post=2895"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}