{"id":2887,"date":"2017-06-16T13:18:17","date_gmt":"2017-06-16T13:18:17","guid":{"rendered":"http:\/\/www.emco.mil.cl\/?p=2887"},"modified":"2021-09-28T17:07:30","modified_gmt":"2021-09-28T20:07:30","slug":"reconocimiento-a-profesionales-de-las-comunicaciones-por-labor-realizada-en-mision-de-paz-de-haiti","status":"publish","type":"post","link":"https:\/\/www.emco.mil.cl\/index.php\/2017\/06\/16\/reconocimiento-a-profesionales-de-las-comunicaciones-por-labor-realizada-en-mision-de-paz-de-haiti\/","title":{"rendered":"Reconocimiento a Profesionales de las Comunicaciones por labor realizada en Misi\u00f3n de Paz de Hait\u00ed"},"content":{"rendered":"<p>Con el retiro de nuestras tropas de la MINUSTAH, se pone fin a 13 a\u00f1os de trabajo. Hombres y mujeres pertenecientes a las Fuerzas Armadas y de Orden y Seguridad con profesionalismo, eficiencia y vocaci\u00f3n solidaria contribuyeron al bienestar del pueblo haitiano, restableciendo condiciones m\u00ednimas de seguridad y estabilidad lo que les permitir\u00e1 desarrollar un proceso pol\u00edtico que fortalezca sus instituciones y proteja los derechos de sus habitantes.<\/p>\n<p>En la actividad estuvieron presentes el Subsecretario de Defensa, Marcos Robledo, la Subsecretaria para las Fuerzas Armadas Paulina Vodanovic, el Jefe del Estado Mayor Conjunto, General de Aviaci\u00f3n Arturo Merino, el Vicealmirante Rodrigo \u00c1lvarez Aguirre y el Contraalmirante Jorge Rodr\u00edguez Urria.<\/p>\n<p>Es por todo ello que en un acto solemne encabezado por el Ministro de Defensa Nacional, Jos\u00e9 Antonio G\u00f3mez, efectuado en el Hall central del Ministerio de Defensa Nacional, se realiz\u00f3 una ceremonia de reconocimiento a los profesionales de las comunicaciones que han plasmado la realidad de Hait\u00ed, mostrando con respeto y profesionalismo la importante labor que realizaron nuestras tropas en aquella Isla del Caribe.<\/p>\n<p><a href=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/RC_5876-1024x692.jpg\"><img fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter  wp-image-2889\" src=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/RC_5876-1024x692-1024x692.jpg\" alt=\"RC_5876-1024x692\" width=\"620\" height=\"419\"><\/a><\/p>\n<p>El Ministro G\u00f3mez agradeci\u00f3 a los profesionales por el trabajo realizado: \u201cPara que nuestro pa\u00eds conozca, que nuestro pa\u00eds tenga consciencia que hay chilenos trabajando fuertemente por la paz, se requiere que los medios de comunicaci\u00f3n lo informen y que lo hagan responsablemente. Ustedes estuvieron all\u00e1, vieron como se trabaja y eso lo informaron de la mejor manera y por eso hoy hemos querido reconocer esta importante labor\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Con el retiro de nuestras tropas de la MINUSTAH, se pone fin a 13 a\u00f1os de trabajo. Hombres y mujeres pertenecientes a las Fuerzas Armadas y de Orden y Seguridad con profesionalismo, eficiencia y vocaci\u00f3n solidaria contribuyeron al bienestar del pueblo haitiano, restableciendo condiciones m\u00ednimas de seguridad y estabilidad lo que les permitir\u00e1 desarrollar un&#8230;<\/p>\n","protected":false},"author":6,"featured_media":5823,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"footnotes":""},"categories":[22,3],"tags":[],"class_list":["post-2887","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-22","category-noticias"],"_links":{"self":[{"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/posts\/2887","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/comments?post=2887"}],"version-history":[{"count":2,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/posts\/2887\/revisions"}],"predecessor-version":[{"id":6292,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/posts\/2887\/revisions\/6292"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/media\/5823"}],"wp:attachment":[{"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/media?parent=2887"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/categories?post=2887"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/tags?post=2887"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}