{"id":2685,"date":"2017-03-21T18:46:17","date_gmt":"2017-03-21T18:46:17","guid":{"rendered":"http:\/\/www.emco.mil.cl\/?p=2685"},"modified":"2021-09-28T17:20:36","modified_gmt":"2021-09-28T20:20:36","slug":"jemco-asiste-a-la-ceremonia-de-conmemoracion-del-203-aniversario-del-ministerio-de-defensa-nacional","status":"publish","type":"post","link":"https:\/\/www.emco.mil.cl\/index.php\/2017\/03\/21\/jemco-asiste-a-la-ceremonia-de-conmemoracion-del-203-aniversario-del-ministerio-de-defensa-nacional\/","title":{"rendered":"JEMCO asiste a la ceremonia de conmemoraci\u00f3n del 203\u00b0 Aniversario del Ministerio de Defensa Nacional"},"content":{"rendered":"<p>El Ministro Jos\u00e9 Antonio G\u00f3mez estuvo acompa\u00f1ado por los Comandantes en Jefe de las tres ramas de las Fuerzas Armadas y por el Jefe del Estado Mayor Conjunto<\/p>\n<p>En el Aula Magna de la Escuela Militar, el Ministro de Defensa Nacional, Jos\u00e9 Antonio G\u00f3mez, encabez\u00f3 la ceremonia de conmemoraci\u00f3n del 203\u00b0 Aniversario del Ministerio de Defensa Nacional, ocasi\u00f3n en la cual aprovecho de<strong> \u201creflexionar acerca de la doctrina y la hoja de ruta que gu\u00eda las principales directrices de la pol\u00edtica de Defensa del Estado\u201d<\/strong>, dando inici\u00f3 al A\u00f1o Acad\u00e9mico de las Escuelas Matrices institucionales, ante m\u00e1s de mil invitados especiales y delegaciones.<\/p>\n<p>La ceremonia cont\u00f3 con la presencia del Ministro del Deporte, Pablo Squella; del Subsecretario de Defensa, Marcos Robledo, la Subsecretaria para las FF.AA, Paulina Vodanovic, el Comandante en Jefe del Ej\u00e9rcito, General Humberto Oviedo; el Comandante en Jefe de la Armada, Almirante Enrique Larra\u00f1aga; el Comandante en Jefe de la Fuerza A\u00e9rea, General Jorge Robles y el Jefe del Estado Mayor Conjunto, General de Aviaci\u00f3n Arturo Merino.<\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\" wp-image-13648 aligncenter\" src=\"http:\/\/www.defensa.cl\/media\/comunicado_2017032003.jpg\" alt=\"comunicado_2017032003\" width=\"619\" height=\"359\"><\/p>\n<p>Como es costumbre, el Ministro de Defensa Nacional se dirigi\u00f3 a la audiencia compuesta por estudiantes, suboficiales y oficiales de las Fuerzas Armadas, e inici\u00f3 su alocusi\u00f3n se\u00f1alando que la Defensa va m\u00e1s all\u00e1 de su implicancia obvia, como lo es la acci\u00f3n de defender. <strong>\u201cEn la palabra Defensa hay connotaciones referidas a otro social, otro que en alg\u00fan momento \u2013o quiz\u00e1s siempre- puede tener las necesidades de \u201camparo, protecci\u00f3n y socorro\u201d<\/strong>, relevando a continuaci\u00f3n que <strong>\u201cestas necesidades no son imaginarias. Se han presentando con lamentable frecuencia en los \u00faltimos a\u00f1os, bajo la forma de terremotos, erupciones, aluviones, accidentes, incendios.\u201d<\/strong><\/p>\n<p>En ese sentido, el secretario de Estado afirm\u00f3 que esta noci\u00f3n de Defensa <strong>\u201cse ha ido desarrollando al mismo tiempo que las Fuerzas Armadas han exhibido sus capacidades y sobre todo, su eficacia\u201d<\/strong>, lo que no significa \u2013agreg\u00f3- que las instituciones se transformen en organizaciones de socorro o de control del orden p\u00fablico, sino que se explica en la medida que <strong>\u201clas amenazas contra la sociedad y la naci\u00f3n han venido mutando de un modo tal que cada d\u00eda es m\u00e1s dif\u00edcil aplicar las antiguas distinciones. (\u2026) Los efectos del cambio clim\u00e1tico, por ejemplo, se deben incorporar forzozamente a los an\u00e1lisis de la Defensa, porque afectan al territorio y a la poblaci\u00f3n y hasta pueden incidir en la maniobrabilidad de las propias herramientas de la Defensa\u201d<\/strong>.<\/p>\n<p>Para el Ministro de Defensa existen dimensiones cotidianas que las Fuerzas Armadas ofrecen a la sociedad como alertar de marejadas en el borde costero, vigilar los cambios geomorfol\u00f3gicos en el territorio, aumentar la conectividad y terminar con las fronteras interiores. <strong>\u201dEso lleva a conclusiones todav\u00eda m\u00e1s amplias. Las Fuerzas Armadas y la sociedad no constituyen elementos de diferente naturaleza, son una misma cosa. Las Fuerzas Armadas no se insertan en la sociedad, nacen de ellas\u201d<\/strong>, a\u00f1adiendo todos los hombres y todas las mujeres que integran las instituciones son sujetos sociales.&nbsp;<strong>\u201dCada uno tiene familia, amigos y colegas que no est\u00e1n en estas funciones especializadas, pero son parte sustancial de sus vidas\u201d<\/strong>.<\/p>\n<p>En su intervenci\u00f3n la autoridad de Defensa fue claro en se\u00f1alar que <strong>\u201cno hay ni puede haber una frontera conceptual entre las Fuerzas Armadas y la sociedad, ni siquiera reconociendo que eso pudo ocurrir en el pasado. Dig\u00e1moslo con claridad: si hubo un momento de separaci\u00f3n entre las Fuerzas Armadas y la sociedad, fue un error, si ustedes quieren, un error forzado por circunstancias fuera de control, pero de todas maneras un error\u201d<\/strong>.<\/p>\n<p><strong>\u201cChile ha definido una pol\u00edtica de Defensa seg\u00fan la cual la seguridad de la naci\u00f3n es una articulaci\u00f3n pol\u00edtico-estrat\u00e9gica, que se produce con el conjunto de las actividades que el Estado realiza para avanzar hacia el logro de sus objetivos y resguardar los intereses nacionales en relaci\u00f3n con el desarrollo y la paz social, as\u00ed como con los riesgos, amenazas, conflictos o interferencias\u201d<\/strong>. Esta descripci\u00f3n tiene un aspecto funcional, dijo, en cuanto establece la posici\u00f3n de la Defensa en el marco de la seguridad;<strong> \u201cy tiene tambi\u00e9n un aspecto sociopol\u00edtico, en cuanto precisa que esa posici\u00f3n est\u00e1 destinada a servir al desarrollo de la naci\u00f3n\u201d<\/strong>.<\/p>\n<p><a href=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/1.png\"><img decoding=\"async\" class=\"aligncenter  wp-image-2687\" src=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/1.png\" alt=\"1\" width=\"619\" height=\"410\"><\/a><\/p>\n<p>Al terminar su discurso, el ministro de Defensa reafirm\u00f3 <strong>\u201clo expresado en el Programa de Gobierno respecto a que la Defensa Nacional transita por una nueva etapa de su historia y que puede y debe realizar un aporte sustantivo al pa\u00eds\u201d<\/strong>. En este sentido, y en concordancia con las directrices presidenciales,<strong> \u201cuno de los desaf\u00edos que nos impusimos como sector fue el dise\u00f1o de una Agenda Amplia para una Defensa Moderna\u201d<\/strong>.<\/p>\n<p>Todo esto ha sido posible gracias al esfuerzo de civiles y de las Fuerzas Armadas. <strong>\u201cLas instituciones militares han dado cumplimiento a las grandes directrices que hemos trazado\u201d<\/strong>. No obstante, tambi\u00e9n debemos poner acento en las tareas y misiones crecientes que las Fuerzas Armadas est\u00e1n desarrollando y destacar y felicitar a nuestras instituciones por la excelente labor que realizan ante situaciones de desastre y emergencia. <strong>\u201cDebemos subrayar la necesidad de continuar perfeccionando capacidades y respuestas en este \u00e1mbito para, de esta manera, aportar desde el sector Defensa a la seguridad del pa\u00eds\u201d<\/strong>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Ministro Jos\u00e9 Antonio G\u00f3mez estuvo acompa\u00f1ado por los Comandantes en Jefe de las tres ramas de las Fuerzas Armadas y por el Jefe del Estado Mayor Conjunto En el Aula Magna de la Escuela Militar, el Ministro de Defensa Nacional, Jos\u00e9 Antonio G\u00f3mez, encabez\u00f3 la ceremonia de conmemoraci\u00f3n del 203\u00b0 Aniversario del Ministerio de&#8230;<\/p>\n","protected":false},"author":6,"featured_media":5823,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"footnotes":""},"categories":[22,3],"tags":[],"class_list":["post-2685","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-22","category-noticias"],"_links":{"self":[{"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/posts\/2685","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/comments?post=2685"}],"version-history":[{"count":2,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/posts\/2685\/revisions"}],"predecessor-version":[{"id":6317,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/posts\/2685\/revisions\/6317"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/media\/5823"}],"wp:attachment":[{"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/media?parent=2685"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/categories?post=2685"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/tags?post=2685"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}