{"id":26,"date":"2013-06-07T20:22:21","date_gmt":"2013-06-07T20:22:21","guid":{"rendered":"http:\/\/www.emc.mil.cl\/nemc\/?p=26"},"modified":"2021-09-29T14:43:03","modified_gmt":"2021-09-29T17:43:03","slug":"curso-de-operaciones-de-la-fuerza-de-paz-combinada-cruz-del-sur","status":"publish","type":"post","link":"https:\/\/www.emco.mil.cl\/index.php\/2013\/06\/07\/curso-de-operaciones-de-la-fuerza-de-paz-combinada-cruz-del-sur\/","title":{"rendered":"Curso de Operaciones de la Fuerza de Paz Combinada Cruz del Sur"},"content":{"rendered":"<p><img decoding=\"async\" class=\"aligncenter\" src=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/07-junio-2013-Curso-de-Operaciones-de-la-Fuerza-de-Paz-Combinada-Cruz-del-Sur-587x330.jpg\" \/><br \/>\nEn el marco de las actividades profesionales desarrolladas por el Estado Mayor Conjunto Combinado (EMCC), con sede en Argentina por este a\u00f1o,\u00a0 entre el 27 y el 31 de mayo se llev\u00f3 a efecto el curso de \u201cOperaciones de la Fuerza de Paz Combinada Cruz del Sur\u201d.<br \/>\nLa actividad acad\u00e9mica, en la que participaron Oficiales Jefes y Subalternos que\u00a0 se encuentran destinados en\u00a0 las unidades argentinas y que integran\u00a0 las respectivas componentes de esta fuerza de Paz combinada, se llev\u00f3 a efecto en dependencias del Centro Argentino de Entrenamiento Conjunto para Operaciones de Paz (CAECOPAZ), ubicado en Campo de Mayo, Buenos Aires, lugar donde se entregaron conocimientos generales y particulares respecto a la organizaci\u00f3n y conformaci\u00f3n de \u201cCruz del Sur\u201d en el marco de las Operaciones de Mantenimiento de la Paz de la Organizaci\u00f3n de Naciones Unidas, ONU.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En el marco de las actividades profesionales desarrolladas por el Estado Mayor Conjunto Combinado (EMCC), con sede en Argentina por este a\u00f1o,\u00a0 entre el 27 y el 31 de mayo se llev\u00f3 a efecto el curso de \u201cOperaciones de la Fuerza de Paz Combinada Cruz del Sur\u201d. La actividad acad\u00e9mica, en la que participaron Oficiales&#8230;<\/p>\n","protected":false},"author":5,"featured_media":5823,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"footnotes":""},"categories":[28,3],"tags":[],"class_list":["post-26","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-28","category-noticias"],"_links":{"self":[{"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/posts\/26","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/comments?post=26"}],"version-history":[{"count":2,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/posts\/26\/revisions"}],"predecessor-version":[{"id":7190,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/posts\/26\/revisions\/7190"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/media\/5823"}],"wp:attachment":[{"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/media?parent=26"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/categories?post=26"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/tags?post=26"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}