{"id":2531,"date":"2017-01-06T12:25:44","date_gmt":"2017-01-06T12:25:44","guid":{"rendered":"http:\/\/www.emco.mil.cl\/?p=2531"},"modified":"2021-09-28T17:27:13","modified_gmt":"2021-09-28T20:27:13","slug":"comunicado-de-prensa-mision-de-las-naciones-unidas-en-colombia","status":"publish","type":"post","link":"https:\/\/www.emco.mil.cl\/index.php\/2017\/01\/06\/comunicado-de-prensa-mision-de-las-naciones-unidas-en-colombia\/","title":{"rendered":"Comunicado de prensa: Misi\u00f3n de las Naciones Unidas en Colombia"},"content":{"rendered":"<p>Santiago, 06 de enero de 2017.-<\/p>\n<p>La Misi\u00f3n Permanente de Chile ante las Naciones Unidas (ONU) a trav\u00e9s de su Agregadur\u00eda de Defensa, ha informado oficialmente la Resoluci\u00f3n del Representante Especial de la ONU en Colombia, que dispone la repatriaci\u00f3n de cuatro oficiales observadores, dentro de los cuales se incluye a una Oficial de Carabineros de Chile, por no cumplir con la imparcialidad, integridad y tacto que los integrantes de la Misi\u00f3n Pol\u00edtica Especial en Colombia deben sostener. Al respecto, se comunica lo siguiente:<\/p>\n<p>El Jefe del Estado Mayor Conjunto y Autoridad Nacional Militar para Operaciones de Paz, previo informe al Se\u00f1or Ministro de Defensa Nacional y de acuerdo a las orientaciones impartidas, ha instruido que se efect\u00faen las siguientes actividades:<\/p>\n<ol>\n<li>Solicitar a trav\u00e9s de esa misi\u00f3n diplom\u00e1tica, que el Representante Especial del Secretario General en Colombia, remita la investigaci\u00f3n aplicada a la Oficial repatriada, para informar a su Instituci\u00f3n de los hechos acaecidos, efecto que esta \u00faltima adopte las medidas administrativas pertinentes.<\/li>\n<li>Disponer a la Direcci\u00f3n de Operaciones Conjuntas del Estado Mayor Conjunto reiterar las medidas respecto al C\u00f3digo de Conducta de las Naciones Unidas a ser observadas por parte de los integrantes nacionales de esta Misi\u00f3n Especial.<\/li>\n<\/ol>\n<p>Finalmente, fortalecemos nuestro compromiso con el apoyo a la Misi\u00f3n Pol\u00edtica Especial en Colombia, y al cumplimiento de los principios y normas relativas al comportamiento de los integrantes chilenos en misiones de paz, preceptos que son instruidos permanentemente al personal nacional, en el cumplimiento de sus servicios.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Santiago, 06 de enero de 2017.- La Misi\u00f3n Permanente de Chile ante las Naciones Unidas (ONU) a trav\u00e9s de su Agregadur\u00eda de Defensa, ha informado oficialmente la Resoluci\u00f3n del Representante Especial de la ONU en Colombia, que dispone la repatriaci\u00f3n de cuatro oficiales observadores, dentro de los cuales se incluye a una Oficial de Carabineros&#8230;<\/p>\n","protected":false},"author":6,"featured_media":5823,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"footnotes":""},"categories":[22,3],"tags":[],"class_list":["post-2531","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-22","category-noticias"],"_links":{"self":[{"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/posts\/2531","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/comments?post=2531"}],"version-history":[{"count":2,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/posts\/2531\/revisions"}],"predecessor-version":[{"id":6331,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/posts\/2531\/revisions\/6331"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/media\/5823"}],"wp:attachment":[{"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/media?parent=2531"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/categories?post=2531"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/tags?post=2531"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}