{"id":2333,"date":"2016-10-04T18:42:51","date_gmt":"2016-10-04T18:42:51","guid":{"rendered":"http:\/\/www.emco.mil.cl\/?p=2333"},"modified":"2021-09-29T08:57:46","modified_gmt":"2021-09-29T11:57:46","slug":"entrenamiento-de-las-fuerzas-armadas-chilenas-y-argentinas-bajo-la-coordinacion-del-estado-mayor-conjunto","status":"publish","type":"post","link":"https:\/\/www.emco.mil.cl\/index.php\/2016\/10\/04\/entrenamiento-de-las-fuerzas-armadas-chilenas-y-argentinas-bajo-la-coordinacion-del-estado-mayor-conjunto\/","title":{"rendered":"Entrenamiento de las Fuerzas Armadas chilenas y argentinas bajo la coordinaci\u00f3n del Estado Mayor Conjunto"},"content":{"rendered":"<div>El entrenamiento de las Fuerzas Armadas chilenas y argentinas bajo la coordinaci\u00f3n del Estado Mayor Conjunto (EMCO) del Ministerio de\u00a0Defensa Nacional, comenz\u00f3 hoy martes 4 de octubre, luego de una ceremonia realizada en el Centro Cultural Cotesma, presidida por la Intendenta de la ciudad de San Mart\u00edn de los Andes, Sra Brunilda Rebolledo, qui\u00e9n destac\u00f3 justamente el sentido solidario que posee este ejercicio, que permitir\u00e1 que las fuerzas armadas apoyen los requerimientos de la autoridad civil, a cargo de situaciones de desastres o cat\u00e1strofes naturales.<\/div>\n<div><\/div>\n<div>Por parte de Chile, hizo uso de la palabra el Brigadier Jorge Pe\u00f1a Nu\u00f1ez, Director de Educaci\u00f3n, Doctrina y Entrenamiento Conjunto del EMCO, qui\u00e9n agradeci\u00f3 las m\u00faltiples muestras de hospitalidad de los anfitriones a la vez de recalcar que el trabajo que se lleve a cabo la presente semana, servir\u00e1 para quedar en condiciones de apoyar a la civilidad de ambos pa\u00edses, ante la presencia de una situaci\u00f3n de emergencia.<\/div>\n<div>\u00a0<a href=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/DSC_0491.jpg\"><img fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter  wp-image-2337\" src=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/DSC_0491.jpg\" alt=\"DSC_0491\" width=\"573\" height=\"380\" \/><\/a><a href=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/DSC_0394.jpg\"><br \/>\n<\/a><\/div>\n<div>El Director argentino del ejercicio Coronel Jose Antonio\u00a0Saumell Robert en la oportunidad se refiri\u00f3 a los eventos que se recrear\u00e1n did\u00e1cticamente en esta instancia de trabajo coordinado.<\/div>\n<div><\/div>\n<div>Las Fuerzas del Ejercicio Solidaridad compuesta por integrantes del Ej\u00e9rcito, Armada y Fuerza A\u00e9rea de\u00a0Chile y Argentina integran un total de casi mil hombres(144 de ellos chilenos), apoyados por medios terrestres y a\u00e9reos de ambos pa\u00edses y efectuar\u00e1n diez distintas simulaciones que incluyen evacuaciones a\u00e9reas y terrestres, rescates desde estructuras siniestradas y b\u00fasqueda subacu\u00e1tica, entre otras.<\/div>\n<div><\/div>\n<div>Los ejercicios se extender\u00e1n ininterrumpida mente hasta el pr\u00f3ximo viernes 7 de octubre, d\u00eda en el que\u00a0comprobar\u00e1n en terreno los avances logrados por parte de las autoridades invitadas de ambos pa\u00edses.<\/div>\n","protected":false},"excerpt":{"rendered":"<p>El entrenamiento de las Fuerzas Armadas chilenas y argentinas bajo la coordinaci\u00f3n del Estado Mayor Conjunto (EMCO) del Ministerio de\u00a0Defensa Nacional, comenz\u00f3 hoy martes 4 de octubre, luego de una ceremonia realizada en el Centro Cultural Cotesma, presidida por la Intendenta de la ciudad de San Mart\u00edn de los Andes, Sra Brunilda Rebolledo, qui\u00e9n destac\u00f3&#8230;<\/p>\n","protected":false},"author":6,"featured_media":5823,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"footnotes":""},"categories":[23,3],"tags":[],"class_list":["post-2333","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-23","category-noticias"],"_links":{"self":[{"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/posts\/2333","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/comments?post=2333"}],"version-history":[{"count":3,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/posts\/2333\/revisions"}],"predecessor-version":[{"id":6496,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/posts\/2333\/revisions\/6496"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/media\/5823"}],"wp:attachment":[{"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/media?parent=2333"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/categories?post=2333"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/tags?post=2333"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}