{"id":2271,"date":"2016-09-06T20:14:41","date_gmt":"2016-09-06T20:14:41","guid":{"rendered":"http:\/\/www.emco.mil.cl\/?p=2271"},"modified":"2021-09-29T09:06:29","modified_gmt":"2021-09-29T12:06:29","slug":"saludos-protocolares-del-jefe-del-comando-operacional-de-las-fuerzas-armadas-argentinas","status":"publish","type":"post","link":"https:\/\/www.emco.mil.cl\/index.php\/2016\/09\/06\/saludos-protocolares-del-jefe-del-comando-operacional-de-las-fuerzas-armadas-argentinas\/","title":{"rendered":"Saludos protocolares del Jefe del Comando Operacional de las Fuerzas Armadas Argentinas"},"content":{"rendered":"<p>El General de Brigada Carlos P\u00e9rez Aquino,&nbsp;Jefe del Comando Operacional de las Fuerzas Armadas Argentinas se reuni\u00f3 hoy con el&nbsp; Jefe del Estado Mayor Conjunto Subrogante, Vicealmirante Rodrigo \u00c1lvarez Aguirre, en el marco de la realizaci\u00f3n de la Segunda Reuni\u00f3n T\u00e9cnica Bilateral de la Fuerza de Paz Combinada&nbsp; \u201cCruz del Sur\u201d.<\/p>\n<p><a href=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/DSC_0168ffff.jpg\"><img fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter size-full wp-image-2275\" src=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/DSC_0168ffff.jpg\" alt=\"DSC_0168ffff\" width=\"712\" height=\"1072\"><\/a><\/p>\n<p>&nbsp;<\/p>\n<p>El saludo se efectu\u00f3 en la oficina del JEMCO Subrogante, Vicealmirante, Rodrigo \u00c1lvarez A. qui\u00e9n estuvo acompa\u00f1ado del Director de Planificaci\u00f3n Conjunta y Director de Inteligencia de Defensa, General de Brigada Rodrigo D\u00edaz Amechazurra.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El General de Brigada Carlos P\u00e9rez Aquino,&nbsp;Jefe del Comando Operacional de las Fuerzas Armadas Argentinas se reuni\u00f3 hoy con el&nbsp; Jefe del Estado Mayor Conjunto Subrogante, Vicealmirante Rodrigo \u00c1lvarez Aguirre, en el marco de la realizaci\u00f3n de la Segunda Reuni\u00f3n T\u00e9cnica Bilateral de la Fuerza de Paz Combinada&nbsp; \u201cCruz del Sur\u201d. &nbsp; El saludo se&#8230;<\/p>\n","protected":false},"author":6,"featured_media":5823,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"footnotes":""},"categories":[23,3],"tags":[],"class_list":["post-2271","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-23","category-noticias"],"_links":{"self":[{"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/posts\/2271","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/comments?post=2271"}],"version-history":[{"count":2,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/posts\/2271\/revisions"}],"predecessor-version":[{"id":6505,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/posts\/2271\/revisions\/6505"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/media\/5823"}],"wp:attachment":[{"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/media?parent=2271"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/categories?post=2271"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/tags?post=2271"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}