{"id":2210,"date":"2016-08-03T21:10:24","date_gmt":"2016-08-03T21:10:24","guid":{"rendered":"http:\/\/www.emco.mil.cl\/?p=2210"},"modified":"2021-09-29T09:10:55","modified_gmt":"2021-09-29T12:10:55","slug":"relevo-del-agregado-de-defensa-de-chile-en-haiti","status":"publish","type":"post","link":"https:\/\/www.emco.mil.cl\/index.php\/2016\/08\/03\/relevo-del-agregado-de-defensa-de-chile-en-haiti\/","title":{"rendered":"Relevo del Agregado de Defensa de Chile en Hait\u00ed"},"content":{"rendered":"<p><a href=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/traub-1.jpg\"><img fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter wp-image-2213 size-full\" src=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/traub-1.jpg\" alt=\"traub\" width=\"1024\" height=\"768\"><\/a>En las dependencias de la &nbsp;Embajada de Chile en Hait\u00ed, &nbsp;se llev\u00f3 a cabo la ceremonia de cambio de mando del Agregado de Defensa chileno. &nbsp;<\/p>\n<p>&nbsp;El Coronel del Ej\u00e9rcito de Chile, Moritz Traub Bauer, se recibi\u00f3 como el nuevo Agregado de Defensa de Chile en Hait\u00ed, &nbsp;puesto que entreg\u00f3 el Capit\u00e1n de Nav\u00edo Alberto Vargas Heinrich, quienes firmaron las actas en presencia del Excelent\u00edsimo Se\u00f1or Embajador, Ra\u00fal Fern\u00e1ndez Daza.<\/p>\n<p>&nbsp;El Comandante Vargas, emocionado por dejar el pa\u00eds que lo acogi\u00f3 durante 6 meses,&nbsp; agradeci\u00f3 a los presentes en la Ceremonia por el apoyo entregado para poder cumplir su rol. &nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En las dependencias de la &nbsp;Embajada de Chile en Hait\u00ed, &nbsp;se llev\u00f3 a cabo la ceremonia de cambio de mando del Agregado de Defensa chileno. &nbsp; &nbsp;El Coronel del Ej\u00e9rcito de Chile, Moritz Traub Bauer, se recibi\u00f3 como el nuevo Agregado de Defensa de Chile en Hait\u00ed, &nbsp;puesto que entreg\u00f3 el Capit\u00e1n de Nav\u00edo Alberto&#8230;<\/p>\n","protected":false},"author":6,"featured_media":5823,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"footnotes":""},"categories":[23,3],"tags":[],"class_list":["post-2210","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-23","category-noticias"],"_links":{"self":[{"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/posts\/2210","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/comments?post=2210"}],"version-history":[{"count":2,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/posts\/2210\/revisions"}],"predecessor-version":[{"id":6510,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/posts\/2210\/revisions\/6510"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/media\/5823"}],"wp:attachment":[{"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/media?parent=2210"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/categories?post=2210"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/tags?post=2210"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}