{"id":2133,"date":"2016-05-23T16:11:16","date_gmt":"2016-05-23T16:11:16","guid":{"rendered":"http:\/\/www.emco.mil.cl\/?p=2133"},"modified":"2021-09-29T09:15:41","modified_gmt":"2021-09-29T12:15:41","slug":"batallon-chile-conmemoro-en-haiti-dia-de-las-glorias-navales","status":"publish","type":"post","link":"https:\/\/www.emco.mil.cl\/index.php\/2016\/05\/23\/batallon-chile-conmemoro-en-haiti-dia-de-las-glorias-navales\/","title":{"rendered":"Batall\u00f3n Chile conmemor\u00f3 en Hait\u00ed D\u00eda de las Glorias Navales"},"content":{"rendered":"<p>Con especial sentimiento de orgullo y emoci\u00f3n, el contingente de la Armada que integra el Batall\u00f3n Chile XXIV, conmemor\u00f3 el D\u00eda de las Glorias Navales y un nuevo aniversario del hero\u00edsmo demostrado en el Combate naval de Iquique y de Punta Gruesa.<\/p>\n<p>La ceremonia se realiz\u00f3 en el Cuartel Carrera, Cabo Haitiano, y fue presidida por el Agregado de Defensa de Chile en el pa\u00eds antillano, Capit\u00e1n de Nav\u00edo IM, Luis Vargas Heinrich, quien tras los honores de ordenanza, fue recibido por el Comandante de la unidad, Teniente Coronel, Jos\u00e9 Bustamante Sasmay.<\/p>\n<p>La conmemoraci\u00f3n de la mayor gesta naval de nuestra historia comenz\u00f3 con la lectura al saludo que hizo llegar el Comandante en Jefe de la Armada, Almirante Enrique Larra\u00f1aga Martin. En sus palabras inst\u00f3 al personal de la instituci\u00f3n, <b><i>\u201ca recordar con profundo recogimiento, a cada marino que sacrific\u00f3 su vida en aras de la patria, leg\u00e1ndonos a los chilenos, un imborrable e imperecedero sentido de amor a nuestra bandera\u201d<\/i><\/b>.<\/p>\n<p>Posteriormente, el Segundo Comandante del CHIBAT, Capit\u00e1n de Corbeta IM, Gast\u00f3n Lacrampe Mella, ley\u00f3 una alocuci\u00f3n patri\u00f3tica, en la que resalt\u00f3&nbsp; la gesta heroica de Prat y sus hombres. <b><i>\u00abHoy al cumplirse un nuevo aniversario de nuestra m\u00e1s heroica haza\u00f1a en la historia de Chile, es oportuno renovar tambi\u00e9n ante los h\u00e9roes de Iquique de 1879, nuestro gran compromiso de honor, aquel que un d\u00eda hicimos ante la bandera que preside esta ceremonia, la misma de aquella \u00e9poca, s\u00edmbolo sagrado, nunca derrotado y jam\u00e1s ultrajada. Batall\u00f3n Chile XXIV, desde este lejano territorio caribe\u00f1o, le podemos decir al Comandante Prat y la dotaci\u00f3n de la Esmeralda, que descansen en paz, en el sitial de honor de hoy tienen y que est\u00e9n seguros que no los defraudaremos y asumiremos con igual responsabilidad, los desaf\u00edos que la patria nos imponga\u00bb<\/i><\/b>, expres\u00f3.<\/p>\n<p>Acto seguido, el capell\u00e1n de la unidad conjunta y combinada, Mayor del Servicio Religioso, Carlos Melo Cruces, procedi\u00f3 a bendecir al personal presente y luego de ello, el Jefe de Contingente de Honduras, Mayor David Romero D\u00edaz, entreg\u00f3 galvanos al Teniente Primero IM, Claudio Aldayuz Mart\u00ednez y al Teniente Segundo IM, Hern\u00e1n Bravo D\u00edaz, en reconocimiento al liderazgo en la conducci\u00f3n de la Compa\u00f1\u00eda IM \u00abPrat\u00bb del Chibat, unidad en la que est\u00e1 inserto un pelot\u00f3n hondure\u00f1o.<\/p>\n<p>La ceremonia consider\u00f3 la entrega de la condecoraci\u00f3n \u00abAl M\u00e9rito Militar de las Fuerzas Armadas\u00bb, por 10, 20 y 30 a\u00f1os de servicios al siguiente personal:<\/p>\n<p>A) 10 a\u00f1os:<\/p>\n<p>Cabo 2\u00b0 IM&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; (ART) Nelson Rojas S\u00e1ez<\/p>\n<p>Cabo 2\u00b0 IM&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; (IC) &nbsp;Luis Coloma Valdevenito<\/p>\n<p>Cabo 2\u00b0&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;(INF) Mat\u00edas Guti\u00e9rrez Guti\u00e9rrez<\/p>\n<p>B) 20 a\u00f1os:<\/p>\n<p>Sargento 2\u00b0&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; (MC. ART.) Juan Salas Hern\u00e1ndez<\/p>\n<p>Sargento 2\u00b0 IM.&nbsp; &nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;    (COM)&nbsp;Oscar Garay Monta\u00f1o<\/p>\n<p>Sargento 2\u00b0&nbsp;&nbsp; &nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; (ENF. TAC. PAB) Pedro Suazo Loyola<\/p>\n<p>C) 30 a\u00f1os:<\/p>\n<p>Suboficial IM.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; (Art.) Pablo \u00c1vila Gonz\u00e1lez<\/p>\n<p>Antes de concluir el emotivo acto, los presentes interpretaron el Himno \u201cBrazas a ce\u00f1ir\u201d y la unidad de formaci\u00f3n desfil\u00f3 ante las autoridades presentes, sellando as\u00ed una jornada inolvidable para quienes celebraron en Hait\u00ed el D\u00eda de las Glorias de la Armada de Chile.<\/p>\n<p style=\"text-align: right;\">23 de mayo de 2016<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Con especial sentimiento de orgullo y emoci\u00f3n, el contingente de la Armada que integra el Batall\u00f3n Chile XXIV, conmemor\u00f3 el D\u00eda de las Glorias Navales y un nuevo aniversario del hero\u00edsmo demostrado en el Combate naval de Iquique y de Punta Gruesa. La ceremonia se realiz\u00f3 en el Cuartel Carrera, Cabo Haitiano, y fue presidida&#8230;<\/p>\n","protected":false},"author":6,"featured_media":5823,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"footnotes":""},"categories":[23,3],"tags":[],"class_list":["post-2133","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-23","category-noticias"],"_links":{"self":[{"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/posts\/2133","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/comments?post=2133"}],"version-history":[{"count":2,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/posts\/2133\/revisions"}],"predecessor-version":[{"id":6519,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/posts\/2133\/revisions\/6519"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/media\/5823"}],"wp:attachment":[{"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/media?parent=2133"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/categories?post=2133"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/tags?post=2133"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}