{"id":2123,"date":"2016-05-19T11:31:50","date_gmt":"2016-05-19T11:31:50","guid":{"rendered":"http:\/\/www.emco.mil.cl\/?p=2123"},"modified":"2021-09-29T09:16:47","modified_gmt":"2021-09-29T12:16:47","slug":"jefe-del-estado-mayor-conjunto-presenta-sus-saludos-protocolares-a-la-armada-de-chile","status":"publish","type":"post","link":"https:\/\/www.emco.mil.cl\/index.php\/2016\/05\/19\/jefe-del-estado-mayor-conjunto-presenta-sus-saludos-protocolares-a-la-armada-de-chile\/","title":{"rendered":"Jefe del Estado Mayor Conjunto presenta sus saludos protocolares a la Armada de Chile"},"content":{"rendered":"<p>El General de Aviaci\u00f3n Arturo Merino Nu\u00f1ez present\u00f3 en la tarde de hoy los saludos protocolares del Estado Mayor Conjunto, &nbsp;al Comandante en Jefe de la Armada Almirante Enrique Larra\u00f1aga Martin en dependencias de la Comandancia en Jefe de la Armada ubicadas en Santiago.<\/p>\n<p>El pr\u00f3ximo 21 de mayo se conmemora el aniversario el 137avo Aniversario de la gesta de Iquique y Punta Gruesa, celebr\u00e1ndose el d\u00eda de las Glorias Navales.&nbsp;<\/p>\n<p style=\"text-align: right;\">19 de &nbsp;mayo &nbsp;de &nbsp;2016<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El General de Aviaci\u00f3n Arturo Merino Nu\u00f1ez present\u00f3 en la tarde de hoy los saludos protocolares del Estado Mayor Conjunto, &nbsp;al Comandante en Jefe de la Armada Almirante Enrique Larra\u00f1aga Martin en dependencias de la Comandancia en Jefe de la Armada ubicadas en Santiago. El pr\u00f3ximo 21 de mayo se conmemora el aniversario el 137avo&#8230;<\/p>\n","protected":false},"author":6,"featured_media":5823,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"footnotes":""},"categories":[23,3],"tags":[],"class_list":["post-2123","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-23","category-noticias"],"_links":{"self":[{"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/posts\/2123","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/comments?post=2123"}],"version-history":[{"count":2,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/posts\/2123\/revisions"}],"predecessor-version":[{"id":6521,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/posts\/2123\/revisions\/6521"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/media\/5823"}],"wp:attachment":[{"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/media?parent=2123"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/categories?post=2123"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/tags?post=2123"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}