{"id":2021,"date":"2016-04-05T16:31:30","date_gmt":"2016-04-05T16:31:30","guid":{"rendered":"http:\/\/www.emco.mil.cl\/?p=2021"},"modified":"2021-09-29T09:27:50","modified_gmt":"2021-09-29T12:27:50","slug":"reunion-entre-el-estado-mayor-conjunto-y-las-ff-aa-de-chile-y-la-guardia-nacional-de-texas-se-desarrolla-en-nuestro-pais","status":"publish","type":"post","link":"https:\/\/www.emco.mil.cl\/index.php\/2016\/04\/05\/reunion-entre-el-estado-mayor-conjunto-y-las-ff-aa-de-chile-y-la-guardia-nacional-de-texas-se-desarrolla-en-nuestro-pais\/","title":{"rendered":"Reuni\u00f3n entre el Estado Mayor Conjunto y las FF.AA. de Chile y la Guardia Nacional de Texas se desarrolla en nuestro pa\u00eds"},"content":{"rendered":"<p>La relaci\u00f3n bilateral en el \u00e1mbito de la Defensa entre Chile y los Estados Unidos de Norteam\u00e9rica se ha fortalecido mediante el intercambio y cooperaci\u00f3n en la materia, lo que se ve reflejado en instancias como la \u201cVIII Reuni\u00f3n Anual de Planificaci\u00f3n del Programa de Estados Asociados entre el Estado Mayor Conjunto y las Fuerzas Armadas de Chile y la Guardia Nacional de Texas\u201d, que se desarrolla en la ciudad de Vi\u00f1a del Mar, Chile, entre el 4 y 7 de abril, constituy\u00e9ndose en una importante arista en materia de Defensa.<\/p>\n<p>Durante cuatro d\u00edas, los representantes del Estado Mayor Conjunto de Chile, encabezados por el Director de Mando y Control Estrat\u00e9gico, General de Brigada A\u00e9rea (TI) \u00c1lvaro Carrasco Rodr\u00edguez y el Director del Estado Mayor Conjunto de las Fuerzas Militares de Texas, Brigadier General Patrick Hamilton, tratar\u00e1n temas relativos a la participaci\u00f3n del Estado Mayor Conjunto nacional en Desastres Naturales y la experiencia en la competencia Best Warrior, que organiza la Guardia Nacional y que tiene relaci\u00f3n con la definici\u00f3n del \u201cmejor guerrero\u201d a trav\u00e9s de diferentes pruebas de obst\u00e1culos y otras, como una forma de efectuar un entrenamiento conjunto de capacidades.<\/p>\n<p>En tanto, los representantes de la naci\u00f3n norteamericana expondr\u00e1n respecto a&nbsp; su Fuerza de respuesta, su equipo de apoyo civil y capacidades; adem\u00e1s, sobre el programa de preparaci\u00f3n para los Suboficiales de la Guardia Nacional de Texas.<\/p>\n<p>La relaci\u00f3n entre las Fuerzas Armadas chilenas y norteamericanas constituye una fuente importante de conocimientos, experiencias, doctrinas, ciencia y tecnolog\u00eda, temas que, junto con estructurar un plan de cooperaci\u00f3n bilateral, permiten dar un paso m\u00e1s hacia el fortalecimiento los tradicionales lazos de amistad y cooperaci\u00f3n.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La relaci\u00f3n bilateral en el \u00e1mbito de la Defensa entre Chile y los Estados Unidos de Norteam\u00e9rica se ha fortalecido mediante el intercambio y cooperaci\u00f3n en la materia, lo que se ve reflejado en instancias como la \u201cVIII Reuni\u00f3n Anual de Planificaci\u00f3n del Programa de Estados Asociados entre el Estado Mayor Conjunto y las Fuerzas&#8230;<\/p>\n","protected":false},"author":6,"featured_media":5823,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"footnotes":""},"categories":[23,3],"tags":[],"class_list":["post-2021","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-23","category-noticias"],"_links":{"self":[{"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/posts\/2021","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/comments?post=2021"}],"version-history":[{"count":2,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/posts\/2021\/revisions"}],"predecessor-version":[{"id":6538,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/posts\/2021\/revisions\/6538"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/media\/5823"}],"wp:attachment":[{"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/media?parent=2021"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/categories?post=2021"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/tags?post=2021"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}