{"id":1957,"date":"2016-03-12T20:11:07","date_gmt":"2016-03-12T20:11:07","guid":{"rendered":"http:\/\/www.emco.mil.cl\/?p=1957"},"modified":"2021-09-29T09:32:21","modified_gmt":"2021-09-29T12:32:21","slug":"general-merino-se-reune-con-intendente-de-la-region-de-magallanes","status":"publish","type":"post","link":"https:\/\/www.emco.mil.cl\/index.php\/2016\/03\/12\/general-merino-se-reune-con-intendente-de-la-region-de-magallanes\/","title":{"rendered":"General Merino se re\u00fane con Intendente de la Regi\u00f3n de Magallanes"},"content":{"rendered":"<p>Una reuni\u00f3n de car\u00e1cter protocolar y profesional sostuvo el Jefe del Estado Mayor Conjunto, General de Aviaci\u00f3n Arturo Merino N\u00fa\u00f1ez con el Intendente de la Regi\u00f3n de Magallanes Jorge Flies A\u00f1\u00f3n, oportunidad en que ambas autoridades trataron diversos temas de inter\u00e9s com\u00fan, entre ellos los proyectos regionales y del \u00e1mbito de las Fuerzas Armadas para el desarrollo log\u00edstico y cient\u00edfico en el Continente Ant\u00e1rtico.&nbsp;<\/p>\n<p>Recientemente, ambos personeros hab\u00edan participado junto al Ministro de Defensa Nacional en la colocaci\u00f3n de la primera piedra de la Estaci\u00f3n Ant\u00e1rtica de Brasil, entre otras actividades.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Una reuni\u00f3n de car\u00e1cter protocolar y profesional sostuvo el Jefe del Estado Mayor Conjunto, General de Aviaci\u00f3n Arturo Merino N\u00fa\u00f1ez con el Intendente de la Regi\u00f3n de Magallanes Jorge Flies A\u00f1\u00f3n, oportunidad en que ambas autoridades trataron diversos temas de inter\u00e9s com\u00fan, entre ellos los proyectos regionales y del \u00e1mbito de las Fuerzas Armadas para&#8230;<\/p>\n","protected":false},"author":6,"featured_media":5823,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"footnotes":""},"categories":[23,3],"tags":[],"class_list":["post-1957","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-23","category-noticias"],"_links":{"self":[{"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/posts\/1957","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/comments?post=1957"}],"version-history":[{"count":2,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/posts\/1957\/revisions"}],"predecessor-version":[{"id":6547,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/posts\/1957\/revisions\/6547"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/media\/5823"}],"wp:attachment":[{"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/media?parent=1957"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/categories?post=1957"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/tags?post=1957"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}